{"id":271885,"date":"2025-10-05T12:42:56","date_gmt":"2025-10-05T10:42:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=271885"},"modified":"2025-10-05T12:47:41","modified_gmt":"2025-10-05T10:47:41","slug":"regionali-laffluenza-alle-12-in-calabria-e-al-77-a-cosenza-76","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/regionali-laffluenza-alle-12-in-calabria-e-al-77-a-cosenza-76\/","title":{"rendered":"Regionali, l&#8217;affluenza alle 12 in Calabria \u00e8 al 7,7%. A Cosenza 7,6%"},"content":{"rendered":"<p>COSENZA \u2013 Mattinata di <strong>votazioni in Calabria<\/strong> per rinnovare il <a href=\"https:\/\/www.consiglioregionale.calabria.it\/portale\" target=\"_blank\" rel=\"noopener\">consiglio regionale<\/a> dopo le dimissioni di Roberto Occhiuto. Alle <strong>ore 12.30 in Calabria<\/strong> hanno votato il<strong> 7,7%<\/strong> (il numero \u00e8 riferito a 2363 sezioni su 2406). Il dato \u00e8 pi\u00f9 o meno in linea rispetto alla stessa rilevazione alle precedenti elezioni regionali del 2021 quando intorno alle ore 12 aveva votato il 7,4.<\/p>\n<p>In provincia di Catanzaro gli elettori che hanno gi\u00e0 votato raggiungono quota 8,8% (8,59 % nel 2021). A seguire Crotone con 7,7%,<strong> poi Cosenza dove hanno votato il 7,6% degli aventi diritto. <\/strong>Reggio Calabria con 7,6%. Chiude Vibo Valentia con il 6%.<\/p>\n<p>I candidati alla presidenza <strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/regionali-roberto-occhiuto-ha-votato-a-cosenza-con-lui-i-suoi-due-figli-video\" target=\"_blank\" rel=\"noopener\">Roberto Occhiuto<\/a>,<\/strong> espressione del centrodestra e<a href=\"https:\/\/quicosenza.it\/news\/calabria\/regionali-francesco-toscano-ha-votato-a-gioia-tauro\" target=\"_blank\" rel=\"noopener\"> <strong>Francesco Toscano<\/strong> <\/a>per Democrazia Sovrana e Popolare\u00a0si sono recati alle urne questa mattina. <strong>L\u2019unico a non votare in Calabria \u00e8 Pasquale Tridico, <\/strong>rappresentante del campo progressista, <strong>perch\u00e9 residente a Roma.\u00a0<\/strong><\/p>\n<p>Nelle elezioni del 2021 l&#8217;affluenza alle urne era stata estremamente bassa. Solo il <b>44,38% <\/b>dei calabresi era andato a votare in lievissimo aumento rispetto alle precedenti consultazioni del <b>2020 <\/b>per le quali il dato si attestava al\u00a0<b>44,33%. P<\/b><strong>i\u00f9 di un calabrese su due non era andato a votare<\/strong>\u00a0per le elezioni regionali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Mattinata di votazioni in Calabria per rinnovare il consiglio regionale dopo le dimissioni di Roberto Occhiuto. Alle ore 12.30 in Calabria hanno votato il 7,7% (il numero \u00e8 riferito a 2363 sezioni su 2406). Il dato \u00e8 pi\u00f9 o meno in linea rispetto alla stessa rilevazione alle precedenti elezioni regionali del 2021 quando [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":155488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-271885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/271885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=271885"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/271885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/155488"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=271885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=271885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=271885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}