{"id":271940,"date":"2025-10-06T07:35:16","date_gmt":"2025-10-06T05:35:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=271940"},"modified":"2025-10-06T07:36:24","modified_gmt":"2025-10-06T05:36:24","slug":"cosenza-gran-finale-per-music-for-change-premio-speciale-a-paola-iezzi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-gran-finale-per-music-for-change-premio-speciale-a-paola-iezzi\/","title":{"rendered":"Cosenza: gran finale per &#8220;Music For Change&#8221;, premio speciale a Paola Iezzi"},"content":{"rendered":"<p>COSENZA &#8211; Si svolger\u00e0 venerd\u00ec <strong>10 ottobre<\/strong>\u00a0a partire dalle 9,30 al teatro Rendano di Cosenza, con ingresso libero, la finale della <strong>sedicesima edizione di Music for Change<\/strong>. Il premio musicale organizzato dall&#8217;<strong>Associazione Musica contro le mafie,<\/strong> tra i pi\u00f9 prestigiosi premi italiani ed europei, interamente focalizzato sulle tematiche civili e sociali, sta dunque per chiudere un&#8217;edizione, quella 2025, che nella prima fase andata in scena lo scorso mese di maggio, durante i numerosi appuntamenti, ha registrato larga partecipazione e successo.<\/p>\n<p>L&#8217;evento finale mette il sigillo su un percorso che, come sempre, ha visto e vedr\u00e0 protagonisti gli studenti ed i loro docenti, nel mix collaudato di spunti di riflessione e divertimento musicale. Music for Change affronta infatti ogni anno i grandi nodi del nostro tempo, trasformandoli in musica e narrazione condivisa.<\/p>\n<p>I <strong>7 temi cardine anche al centro dei brani dei 6 finalisti,<\/strong> mutuati dall&#8217;Agenda 2030 dell&#8217;ONU, sono: Resistenze e Democrazia, Ambiente ed Ecologia, Cittadinanza Digitale e Cyber-Risk, Parit\u00e0 di Genere e Diritti LGBTQ+, Lavoro e Dignit\u00e0, Migrazione e Popoli, Disuguaglianze e Marginalit\u00e0 Sociale.<\/p>\n<h3>La competizione canora<\/h3>\n<p>Quest&#8217;anno \u00e8 stata caratterizzata dalla formula esclusiva Stay or Go: dai quasi <strong>900 artisti<\/strong> candidati sono stati selezionati i primi<strong> 21 semifinalisti,<\/strong> che hanno partecipato alla fase Sound Village il 23 e 24 maggio 2025 per contendersi 7 posti per la finale, uno per ciascun tema. <strong>Soltanto sei di loro hanno portato a termine l&#8217;intero percorso<\/strong> e approdano cos\u00ec alla finale del <strong>10 ottobre a Cosenza<\/strong>. Con questo approccio, Music For Change si conferma come una delle manifestazioni pi\u00f9 attuali del panorama nazionale, capace di costruirsi e rigenerarsi in un perfetto equilibrio tra reale e virtuale, due dimensioni ormai inscindibili e destinate a guidare la quotidianit\u00e0 del prossimo futuro.<\/p>\n<p>Nella matin\u00e9e del 10 ottobre al teatro Rendano, presentata dalla poliedrica e visionaria <strong>Elasi<\/strong> (artista, producer e DJ), andr\u00e0 in scena il live con i <strong>6 finalisti<\/strong> che si esibiranno davanti al pubblico ed ai giudici con i rispettivi 6 brani realizzati lo scorso maggio in Calabria nelle fasi Sound Village e Pitching Friday Route. A decidere il vincitore saranno gli <strong>Artist Decider<\/strong>, tre artisti di sensibilit\u00e0 e storie diverse ma tutti accomunati dal rappresentare le nuove direzioni della canzone d&#8217;autore italiana, fra tradizione, sperimentazione e multidisciplinariet\u00e0: Avincola (cantautore romano), Giorgieness (cantautrice, gi\u00e0 host della fase Stay Or Go di quest&#8217;anno), Roberta Giallo (artista multidisciplinare e camaleontica, cantautrice, performer, scrittrice e attrice, \u00e8 stata sostenuta da Lucio Dalla e oggi \u00e8 una delle voci pi\u00f9 originali della scena italiana).<\/p>\n<h3>Premio Speciale Music for Change a Paola Iezzi<\/h3>\n<p>Verso la finale, cresce poi l&#8217;attesa per l&#8217;assegnazione di un Premio Speciale Music for Change a <strong>Paola Iezzi<\/strong>, voce della musica italiana che ha saputo unire pop e impegno civile: cantautrice, musicista e produttrice, \u00e8 un&#8217;icona del pop italiano che con il duo Paola &amp; Chiara ha firmato hit generazionali e conquistato palchi internazionali. Artista solista, DJ e oggi giudice di X-Factor, continua a reinventarsi tra dischi d&#8217;oro e di platino, collaborazioni di prestigio e un percorso che la conferma protagonista assoluta della scena musicale contemporanea. Impegnata da sempre per i diritti civili, \u00e8 stata madrina del Pride di Roma e protagonista nella Milano Pride Week, con parole forti e coerenti sulla <strong>difesa dei diritti LGBTQIA+<\/strong>.<\/p>\n<p>Paola Iezzi ricever\u00e0 il premio Speciale Music for Change con la <strong>motivazione<\/strong> di aver saputo coniugare la brillantezza di una carriera musicale pop con un impegno autentico a sostegno dei diritti civili e della libert\u00e0 individuale, non solo attraverso la sua voce pubblica, che l&#8217;ha vista protagonista in contesti simbolici di grande partecipazione collettiva, ma anche nella sua musica, dove con brani come &#8220;Viva el Amor!&#8221; e &#8220;Il linguaggio del corpo&#8221; ha scelto di dare spazio a temi di uguaglianza e inclusione. Paola Iezzi dimostra come l&#8217;arte possa trasformarsi in un linguaggio universale, capace di portare valori condivisi a un pubblico ampio e trasversale.<\/p>\n<h3>I finalisti<\/h3>\n<p><strong> LA NOCE<\/strong> con &#8220;Lucy&#8221; &#8211; sul tema Parit\u00e0 di Genere e Diritti Lgbtq+;<br \/>\n<strong>ROSSANA DE PACE<\/strong> con &#8220;Pelle d&#8217;oca&#8221; &#8211; sul tema Migrazione e Popoli;<br \/>\n<strong>DIMAGGIO<\/strong> con &#8220;Polemic\u0259&#8221; &#8211; sul tema Resistenze e Democrazia;<br \/>\n<strong>GIULIA LEONE<\/strong> con &#8220;Il Mondo prende fuoco&#8221; &#8211; sul tema Ambiente ed Ecologia;<br \/>\n<strong>ALICE CARONNA<\/strong> con &#8220;Non c&#8217;\u00e8 Tempo&#8221; &#8211; sul tema Lavoro e Dignit\u00e0;<br \/>\n<strong>NO DADA<\/strong> con &#8220;CTRL+C&#8221; &#8211; sul tema Cittadinanza Digitale e Cyber Risk.<\/p>\n<p>Come ha dichiarato Gennaro de Rosa, direttore artistico di Music For Change: \u00abMusic for Change non \u00e8 solo un premio musicale: \u00e8 una piattaforma culturale che mette in dialogo musica e impegno civile. In un tempo segnato da fragilit\u00e0 globali, alle grandi questioni umanitarie non servono slogan ad effetto o manifestazioni episodiche, ma percorsi costruiti nel tempo, capaci di generare impatto reale. Il nostro contributo \u00e8 offrire visibilit\u00e0 ad artisti e costruire percorsi dedicati alle nuove generazioni, portando temi complessi con formule accessibili, contemporanee e vicine ai loro linguaggi. Perch\u00e9 la musica, con la sua forza semplice e universale, sa parlare a tutti e aprire prospettive nuove sul presente e sul futuro\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Si svolger\u00e0 venerd\u00ec 10 ottobre\u00a0a partire dalle 9,30 al teatro Rendano di Cosenza, con ingresso libero, la finale della sedicesima edizione di Music for Change. Il premio musicale organizzato dall&#8217;Associazione Musica contro le mafie, tra i pi\u00f9 prestigiosi premi italiani ed europei, interamente focalizzato sulle tematiche civili e sociali, sta dunque per chiudere [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":271941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-271940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/271940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=271940"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/271940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/271941"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=271940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=271940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=271940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}