{"id":27228,"date":"2013-11-05T08:28:32","date_gmt":"2013-11-05T07:28:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27228"},"modified":"2023-01-17T13:24:43","modified_gmt":"2023-01-17T12:24:43","slug":"11266-gruppo-ammortizzatori-sociali-in-deroga-blocca-piazza-loreto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11266-gruppo-ammortizzatori-sociali-in-deroga-blocca-piazza-loreto\/","title":{"rendered":"Gruppo ammortizzatori sociali in deroga blocca piazza Loreto"},"content":{"rendered":"<p>COSENZA &#8211; Prosegue anche questa mattina a Cosenza il blocco della zona antistante l&#8217;Inps di Cosenza nei pressi di Piazza Loreto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Ieri la mobilitazione, organizzata ancora una volta dal Gruppo Ammortizzatori Sociali in Deroga, ha completamente paralizzato via misasi a Cosenza. I lavoratori che da giorni protestano nei pressi dell&#8217;Inps, non hanno ancora ricevuto risposte e certezze dalla Regione Calabria per il pagamento delle sette mensilit\u00e0 arretrate. Pertanto la protesta prosegue anche oggi, hanno fatto sapere i lavoratori e ad oltranza fino a che non arriveranno risposte in merito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Prosegue anche questa mattina a Cosenza il blocco della zona antistante l&#8217;Inps di Cosenza nei pressi di Piazza Loreto.<\/p>\n","protected":false},"author":19,"featured_media":27229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-27228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27228"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27229"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}