{"id":272733,"date":"2025-10-14T13:30:22","date_gmt":"2025-10-14T11:30:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=272733"},"modified":"2025-10-14T13:00:32","modified_gmt":"2025-10-14T11:00:32","slug":"rende-e-unical-un-ponte-di-cultura-con-la-7a-edizione-del-rende-teatro-festival-programma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-e-unical-un-ponte-di-cultura-con-la-7a-edizione-del-rende-teatro-festival-programma\/","title":{"rendered":"Rende e Unical, un ponte di cultura con la 7\u00aa edizione del &#8220;Rende Teatro Festival&#8221; &#8211; PROGRAMMA"},"content":{"rendered":"<p>RENDE &#8211; Si alza il sipario sulla <strong>7\u00aa edizione del Rende Teatro Festival.<\/strong> Non solo intrattenimento, ma spazio di riflessione, educazione civica e crescita collettiva. \u00c8 proprio questo lo spirito con cui Rende e l\u2019Universit\u00e0 della Calabria lanciano la settima edizione di un festival teatrale che unisce <strong>cultura, spettacolo e pensiero critico<\/strong>. Il festival \u00e8 stato presentato questa mattina nel foyer del Tau, alla presenza del rettore<strong> Nicola Leone,<\/strong> del prorettore <strong>Francesco Raniolo<\/strong>, del sindaco di Rende <strong>Sandro Principe<\/strong>, del vicesindaco e assessore allo spettacolo <strong>Fabio Liparoti<\/strong> e di <strong>Alfredo De Luca<\/strong>, direttore artistico della rassegna. Un festival che si arricchisce di volti noti, opere nuove e tematiche attuali. E sar\u00e0 il TAU, <strong>il Teatro Auditorium dell\u2019Unical<\/strong>, ad ospitare la maggior parte degli eventi in cartellone, siglando ancora di pi\u00f9 il legame tra l\u2019ateneo e il Comune di Rende. <strong>E per gli studenti dell&#8217;Unical, uno speciale sconto del 50%.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-272739 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rende-Teatro-Festival-03.jpg\" alt=\"\" width=\"700\" height=\"433\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rende-Teatro-Festival-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rende-Teatro-Festival-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rende-Teatro-Festival-03-768x475.jpg 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3>Il teatro come specchio della societ\u00e0<\/h3>\n<p>\u00abIl teatro ha una grande importanza nella cultura \u2013 ha dichiarato il sindaco di Rende, Sandro Principe \u2013 e si sposa con l\u2019educazione civica, con l\u2019illuminazione e l\u2019anticipazione delle tendenze\u00bb. Principe ha sottolineato il valore del pensiero critico nella programmazione culturale, proponendo per le prossime edizioni la presenza di intellettuali come Luciano Canfora: \u00abCome Aristofane, che 2.500 anni fa seppe anticipare i tempi, anche oggi il teatro pu\u00f2 dare voce al futuro\u00bb. Il sindaco ha anche ricordato il valore rivoluzionario dell\u2019Universit\u00e0 della Calabria: \u00abUn\u2019istituzione che difendo strenuamente e che \u00e8 nata con caratteristiche statutarie di cultura, innovazione e formazione\u00bb.<\/p>\n<h3>Unical e Rende<\/h3>\n<p>Il rettore Nicola Leone ha evidenziato la crescente apertura dell\u2019ateneo verso il territorio: \u00abIn questi anni abbiamo lavorato per portare l\u2019arte, il cinema, la musica e il teatro all\u2019interno della nostra comunit\u00e0. Il nostro rapporto con il Comune di Rende, in particolare con il sindaco Principe, \u00e8 privilegiato e proficuo\u00bb. Quest\u2019anno, per la prima volta, l\u2019intera rassegna si concentrer\u00e0 nell\u2019auditorium dell\u2019Unical: \u00abIl TAU diventa il teatro di riferimento, uno spazio scenico di altissimo livello che vogliamo far conoscere a tutti. <strong>Portare gli studenti a teatro \u00e8 una sfida culturale che stiamo vincendo<\/strong>\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-272742 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Sandro-Principe-Unical.jpg\" alt=\"\" width=\"757\" height=\"477\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Sandro-Principe-Unical.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Sandro-Principe-Unical-300x189.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Sandro-Principe-Unical-768x484.jpg 768w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><\/p>\n<h3>Il cartellone<\/h3>\n<p>Il direttore artistico <strong>Alfredo De Luca<\/strong> ha illustrato un programma variegato, capace di unire comicit\u00e0 e riflessione, spettacolo e cultura. Ad aprire il festival sar\u00e0 Carlotta Proietti, figlia del grande Gigi, con &#8220;Una commedia per futili motivi&#8221;, sulla quotidianit\u00e0 di coppia. Sar\u00e0 <strong>Carlotta Proietti, figlia del compianto Gigi Proietti,<\/strong>\u00a0ad aprire ufficialmente la stagione il<strong> 7 dicembre<\/strong> con \u201cPer futili motivi\u201d, una commedia distopica e surreale che immagina un futuro governato dall\u2019odio, contro cui un uomo e una donna oppongono resistenza con ironia e tenerezza. Un debutto che mescola leggerezza e riflessione.<\/p>\n<p>Il <strong>30 gennaio<\/strong> 2026 salir\u00e0 sul palco <strong>Peppe Barra<\/strong> con \u201cBuonasera a tutti\u201d, recital intimo e poetico che ripercorre sessant\u2019anni di carriera tra musica, memorie e suggestioni partenopee.<\/p>\n<p>A seguire, il <strong>5 febbraio<\/strong>, sar\u00e0 protagonista <strong>Martina Colombari<\/strong> con \u201cVenerd\u00ec 13\u201d, una commedia degli equivoci dai toni brillanti, in bilico tra lutti apparenti e vincite al Superenalotto, tra sorprese e colpi di scena.<\/p>\n<p>L\u2019<strong>8 febbraio toccher\u00e0 a Gianluigi Nuzzi,<\/strong> noto giornalista d\u2019inchiesta, portare in scena \u201cLa fabbrica degli innocenti\u201d, un lavoro che intreccia verit\u00e0, media e giustizia, proponendo un\u2019inchiesta teatrale a tutti gli effetti. Quattro giorni dopo, il <strong>12 febbraio<\/strong>, sar\u00e0 la volta del filosofo <strong>Umberto Galimberti<\/strong> con \u201cL\u2019etica del viandante\u201d, spettacolo denso e coinvolgente che affronta il senso dell\u2019esistenza nell\u2019epoca della tecnica.<\/p>\n<p>Il <strong>19 marzo spazio al doppiatore e comico Maurizio Merluzzo<\/strong> con \u201cE se facessi un tour?\u201d, show brillante che alterna satira e motivazione personale, pensato per conquistare il pubblico giovane. Il giorno successivo, il <strong>20 marzo, Massimo Ghini<\/strong> porter\u00e0 sul palco \u201cNoi, Giuda\u201d, un monologo intenso che racconta San Francesco come artista e rivoluzionario, tra spiritualit\u00e0 e ribellione.<\/p>\n<p>Il <strong>24 marzo,<\/strong> lo psichiatra e scrittore <strong>Paolo Crepet<\/strong> presenter\u00e0 \u201cIl reato di pensare\u201d, uno spettacolo-incontro sul valore del dissenso e delle emozioni in un\u2019epoca di pensiero anestetizzato. <strong>A chiudere marzo, due appuntamenti attesissimi:<\/strong> il <strong>30 marzo<\/strong> <strong>Maurizio Casagrande<\/strong> con \u201cLa prova del nove\u201d, una commedia musicale sulla confusione creativa e l\u2019arte del reinventarsi, e il <strong>31 marzo il divulgatore digitale Salvatore Aranzulla,<\/strong> con \u201cIl Metodo Aranzulla\u201d, uno spettacolo ironico, informativo e sorprendentemente teatrale sul sapere nell\u2019era digitale.<\/p>\n<p>L\u2019<strong>11 aprile toccher\u00e0 a Ettore Bassi con \u201cEl Futbol\u201d<\/strong>, spettacolo dedicato al calcio come metafora dell\u2019esistenza, che unisce sport, poesia e passione. Il <strong>22 aprile<\/strong> andr\u00e0 in scena \u201c<strong>Miseria e Nobilt\u00e0 \u2013 Il Musical<\/strong>\u201d, rivisitazione moderna del classico di Eduardo Scarpetta, diretto dal <strong>rendese Francesco Mastroianni<\/strong> e prodotto da <strong>Lindo Nudo<\/strong>. Infine, il <strong>6 maggio, chiusura in grande stile con Biagio Izzo<\/strong> e il suo nuovo show \u201cTutto Stressato\u201d, un\u2019esplosione di comicit\u00e0 partenopea che trasforma le nevrosi<strong> quotidiane in risate liberatorie.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sul palco del TAU grandi nomi come Galimberti, Peppe Barra, Martina Colombari e Gianluigi Nuzzi ma anche Salvatore Aranzulla e Maurizio Merluzzo. Il festival teatrale di Rende si rinnova con una programmazione che intreccia spettacolo, riflessione e impegno civico. Il sindaco Principe: \u00abIl teatro educa e anticipa i tempi\u00bb<\/p>\n","protected":false},"author":19,"featured_media":272738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-272733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/272733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=272733"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/272733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/272738"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=272733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=272733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=272733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}