{"id":272945,"date":"2025-10-16T13:35:12","date_gmt":"2025-10-16T11:35:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=272945"},"modified":"2025-10-16T13:37:07","modified_gmt":"2025-10-16T11:37:07","slug":"il-riscatto-e-la-rinascita-passa-anche-dallunical-la-storia-di-claudio-conte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/il-riscatto-e-la-rinascita-passa-anche-dallunical-la-storia-di-claudio-conte\/","title":{"rendered":"Il riscatto e la rinascita passa anche dall&#8217;Unical: la storia di Claudio Conte"},"content":{"rendered":"<p>RENDE &#8211;\u00a0\u00c8 dell\u2019<strong>Universit\u00e0 della Calabria<\/strong> si parla di riscatto con il <strong>primo dottore di ricerca detenuto in Italia. <\/strong>Lui \u00e8 <strong>Claudio Conte,<\/strong> laureato in Giurisprudenza a Catanzaro che ha conseguito il titolo di <strong>dottore di ricerca in \u201cPolitica, Cultura e Sviluppo\u201d<\/strong> grazie a una borsa riservata ai candidati privati della libert\u00e0 personale. L\u2019esame finale si \u00e8 svolto nei giorni scorsi presso l\u2019Universit\u00e0 di Parma, dove Conte \u00e8 stato formalmente ospitato per lo svolgimento della prova.<\/p>\n<p>La sua tesi, intitolata \u201cLe interazioni sociali in ambito penitenziario dal punto di vista degli stude-tenuti: resistenze, reazioni, trasformazioni\u201d (tutor Franca Garreffa, co-tutor Vincenza Pellegrino), esplora la <strong>funzione dello studio universitario in carcere<\/strong> come esperienza di <strong>rinascita personale e cambiamento sociale.<\/strong> La commissione \u2013 composta da Paolo Jedlowski, Andrea Borghini e Chiara Scivoletto \u2013 ha giudicato il lavoro \u201ceccellente con lode\u201d.<\/p>\n<p>Un percorso che si \u00e8 reso possibile grazie all&#8217;istituzione della <strong>CNUPP<\/strong> (Conferenza Nazionale dei Delegati dei Rettori per i Poli Universitari Penitenziari), organismo che coordina e promuove le attivit\u00e0 degli Atenei all\u2019interno degli istituti penitenziari.<\/p>\n<h3>La storia di Claudio Conte: il dottorato conseguito all&#8217;Unical<\/h3>\n<p>Collegati dalla sala Guarasci dell\u2019Universit\u00e0 della Calabria, il <strong>rettore eletto Gianluigi Greco<\/strong> e il coordinatore del dottorato <strong>Francesco Raniolo<\/strong> hanno espresso grande soddisfazione per un risultato che \u201ctrasforma il carcere in un luogo di conoscenza e riflessione critica\u201d. Per il presidente della Conferenza Nazionale dei Delegati dei Rettori ai Poli Penitenziari (CNUPP), Giancarlo Monina, l\u2019impresa di Conte rappresenta <strong>\u201cun passaggio storico\u201d:<\/strong> &#8220;Uno studente detenuto non \u00e8 pi\u00f9 soltanto un recluso, ma anche e soprattutto uno studente universitario&#8221;. Lo studio in carcere \u2013 ha sottolineato \u2013 apre ponti tra \u201cdentro\u201d e \u201cfuori\u201d, contribuendo a costruire una societ\u00e0 pi\u00f9 aperta, solidale e coerente con l\u2019articolo 27 della Costituzione.<\/p>\n<p>Nel corso della cerimonia, accanto al riconoscimento accademico, non sono mancati i momenti di riflessione sul senso della pena e sulle prospettive di giustizia riparativa, con gli interventi di <strong>Elisabetta Zamparutti e Sergio D\u2019Elia<\/strong> (Nessuno Tocchi Caino), <strong>Francesca Vianello<\/strong> (Universit\u00e0 di Padova), <strong>Agnese Moro, Paolo Setti Carraro<\/strong> e i messaggi di <strong>Manlio Milani e Lucia Montanino.<\/strong><\/p>\n<p>Nella sua ricerca, condotta anche in collaborazione con la redazione di <strong>Ristretti Orizzonti<\/strong> (coordinata da Ornella Favero e Carla Chiappini), Conte ha mostrato come la formazione possa diventare <strong>strumento di riconciliazione e responsabilit\u00e0<\/strong>, in linea con le esperienze di giustizia riparativa ricordate da Franco Bonisoli, ex militante della lotta armata.<\/p>\n<p>Nel corso della cerimonia, infine, un ringraziamento particolare \u00e8 stato rivolto al <strong>rettore Nicola Leone<\/strong> e al Senato Accademico dell\u2019Universit\u00e0 della Calabria per aver riservato un posto di dottorato a persone private della libert\u00e0 ma capaci di produrre ricerca di qualit\u00e0 sul carcere e dal carcere.<\/p>\n<p>Una scelta significativa che apre la strada a una <strong>visione nuova dell\u2019istituzione penitenziaria<\/strong>: non pi\u00f9 solo luogo di detenzione, ma spazio <strong>dinamico di conoscenza e trasformazione<\/strong>, in cui pena, educazione e riparazione si intrecciano come pratiche condivise tra detenuti, vittime, operatori e mondo accademico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laureato in Giurisprudenza a Catanzaro, il detenuto ha conseguito il titolo di dottore di ricerca in \u201cPolitica, Cultura e Sviluppo\u201d nell&#8217;ateneo di Rende: &#8220;Un passaggio storico&#8221; <\/p>\n","protected":false},"author":90,"featured_media":272950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-272945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/272945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=272945"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/272945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/272950"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=272945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=272945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=272945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}