{"id":27334,"date":"2013-11-08T11:20:09","date_gmt":"2013-11-08T10:20:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27334"},"modified":"2023-01-17T13:24:49","modified_gmt":"2023-01-17T12:24:49","slug":"11321-troppi-ritardi-medico-denunciato-per-interruzione-di-pubblico-servizio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11321-troppi-ritardi-medico-denunciato-per-interruzione-di-pubblico-servizio\/","title":{"rendered":"Troppi ritardi, medico denunciato per interruzione di pubblico servizio"},"content":{"rendered":"<p>MOTTA SANTA LUCIA (CZ) &#8211; Arrivava sempre in ritardo in ambulatorio, mandando in tilt tutti gli appuntamenti.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Cos\u00ec i carabinieri di Soveria Mannelli (Cz) hanno notificato un avviso di garanzia ad un medico di base del comune di Motta Santa Lucia, con l&#8217;accusa di interruzione di pubblico servizio. L&#8217;attivit\u00e0 dei militari \u00e8 partita a seguito delle numerose querele presentate da cittadini, che avrebbero accertato, in pi\u00f9 occasioni, la responsabilita&#8217; del medico che sistematicamente disattendeva gli orari di visita programmati nel suo ambulatorio, turbando in tal modo la regolarita&#8217; del servizio pubblico di medico di base. La situazione, secondo quanto riferito dagli inquirenti, era ormai diventata insostenibile per i pazienti del medico che erano costretti a lunghe ore di attesa nel suo ambulatorio nonostante il vigente orario di apertura della struttura, con grave disservizio causato all&#8217;intera comunit\u00e0 del piccolo centro per l&#8217;interruzione dell&#8217;assistenza sanitaria pubblica. Il medico e&#8217; stato cosi&#8217; denunciato alla Procura della Repubblica di Lamezia Terme che ha emesso un avviso di garanzia nei suoi confronti per il reato di interruzione di pubblico servizio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MOTTA SANTA LUCIA (CZ) &#8211; Arrivava sempre in ritardo in ambulatorio, mandando in tilt tutti gli appuntamenti.&nbsp;<\/p>\n","protected":false},"author":19,"featured_media":27335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-27334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27334"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27335"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}