{"id":273357,"date":"2025-10-21T11:52:30","date_gmt":"2025-10-21T09:52:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=273357"},"modified":"2025-10-21T11:52:30","modified_gmt":"2025-10-21T09:52:30","slug":"cosenza-controlli-della-polizia-3-arresti-e-7-denunce-sequestrati-quasi-due-chili-di-droga","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-controlli-della-polizia-3-arresti-e-7-denunce-sequestrati-quasi-due-chili-di-droga\/","title":{"rendered":"Cosenza, controlli della Polizia: 3 arresti e 7 denunce. Sequestrati quasi due chili di droga"},"content":{"rendered":"<p>COSENZA &#8211; Fine settimana impegnativo per la Polizia di Stato di Cosenza, con controlli del territorio che hanno coinvolto l\u2019intero capoluogo e varie aree della provincia.\u00a0I servizi straordinari, condotti in sinergia dalla Squadra Mobile, dalla Squadra Volante, dalla Divisione Anticrimine della Questura e dai Commissariati distaccati di <strong>Corigliano-Rossano, Paola e Castrovillari<\/strong>, hanno portato complessivamente <strong>all\u2019arresto<\/strong> di <strong>tre persone<\/strong>, due delle quali per reati legati agli stupefacenti e una per atti persecutori.<\/p>\n<p><strong>Sette le denunce <\/strong>scattate a vario titolo per reati di<strong> resistenza a pubblico ufficiale, lesioni personali, atti persecutori e violazioni della normativa sugli stupefacenti<\/strong>. I sequestri effettuati nel corso dei controlli hanno riguardato complessivamente <strong>64 grammi di cocaina, 1 chilo e 230 grammi di hashish e 504 grammi di marijuana.<\/strong><\/p>\n<h3>Violenza di genere<\/h3>\n<p>Sul fronte della prevenzione della violenza di genere, sono state eseguite <strong>tre ordinanze di applicazione della misura cautelare del divieto di avvicinamento per episodi di atti persecutori e lesioni personali<\/strong>. La Divisione Anticrimine ha inoltre emesso quattro ammonimenti, quattro avvisi orali e due fogli di via obbligatori.<\/p>\n<p>Un\u2019ulteriore ordinanza, emessa ai sensi dell\u2019art. 100 del Testo Unico delle Leggi di Pubblica Sicurezza (TULPS), ha <strong>disposto la chiusura per 15 giorni di un esercizio commerciale nel centro cittadino<\/strong>, risultato coinvolto in <strong>contesti critici per l\u2019ordine pubblico<\/strong>.<\/p>\n<p>L\u2019azione della Polizia ha incluso anche un\u2019intensa attivit\u00e0 di controllo su strada:<strong> 765 persone identificate, 334 veicoli ispezionati<\/strong> e numerose contestazioni elevate per violazioni al Codice della Strada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controlli capillari su tutto il territorio. Eseguiti anche provvedimenti cautelari per atti persecutori e chiuso un esercizio commerciale in centro citt\u00e0<\/p>\n","protected":false},"author":42,"featured_media":273360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,803],"tags":[],"class_list":["post-273357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-cronaca"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=273357"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/273360"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=273357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=273357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=273357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}