{"id":273622,"date":"2025-10-23T18:08:53","date_gmt":"2025-10-23T16:08:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=273622"},"modified":"2025-10-23T18:08:53","modified_gmt":"2025-10-23T16:08:53","slug":"gregoraci-il-padre-a-processo-per-maltrattamenti-alla-ex-la-difesa-versione-unilaterale-dei-fatti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/gregoraci-il-padre-a-processo-per-maltrattamenti-alla-ex-la-difesa-versione-unilaterale-dei-fatti\/","title":{"rendered":"Gregoraci, il padre a processo per maltrattamenti alla ex. La difesa: \u00abversione unilaterale dei fatti\u00bb"},"content":{"rendered":"<p>CATANZARO &#8211; &#8220;Senza volere affrontare questioni che potranno e dovranno essere sviluppate esclusivamente nelle sedi competenti si vuole evidenziare che \u00e9 stata proposta una versione unilaterale dei fatti paventando una alterazione di un rapporto pretesamente deterioratosi nel tempo&#8221;. Lo afferma<strong> l&#8217;avvocata Ramona Gualtieri<\/strong>, difensore di <strong>Mario Gregoraci, padre della show girl Elisabetta<\/strong>, per il quale la Procura della Repubblica di Catanzaro ha chiesto il rinvio a giudizio per atti persecutori, <strong><a href=\"https:\/\/quicosenza.it\/news\/bufera-sulla-famiglia-gregoraci-il-padre-della-showgirl-nei-guai-con-la-giustizia\/\" target=\"_blank\" rel=\"noopener\">maltrattamenti e lesioni personali<\/a> nei confronti della ex compagna Rosita Gentile. <\/strong>&#8220;Non deve infine sfuggire &#8211; prosegue &#8211; che sono pendenti, nella fase delle indagini preliminari, procedimenti penali che vedono Mario Gregoraci persona offesa da condotte consumate da Gentile&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00c8 stata proposta una versione unilaterale, Mario Gregoraci \u00e8 persona offesa da condotte consumate dalla ex Rosita gentile\u00bb &#8211; dichiara l&#8217;avvocato Ramona Gentile, difensore di Mario Gregoraci<\/p>\n","protected":false},"author":58,"featured_media":273485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-273622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=273622"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/273485"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=273622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=273622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=273622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}