{"id":273643,"date":"2025-10-23T20:44:15","date_gmt":"2025-10-23T18:44:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=273643"},"modified":"2025-10-23T20:44:15","modified_gmt":"2025-10-23T18:44:15","slug":"sparatoria-a-lamezia-53enne-si-consegna-ai-carabinieri-due-feriti-uno-grave","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sparatoria-a-lamezia-53enne-si-consegna-ai-carabinieri-due-feriti-uno-grave\/","title":{"rendered":"Sparatoria a Lamezia, 53enne si consegna ai carabinieri: due feriti, uno grave"},"content":{"rendered":"<p>LAMEZIA TERME (CZ) &#8211; Un<strong> uomo di 53 anni,<\/strong> si \u00e8 presentato nel pomeriggio ai carabinieri di Lamezia Terme in relazione alla sparatoria di stamattina nel corso della quale due persone di etnia rom sono rimaste ferite, una in modo grave. Insieme al proprio difensore, l&#8217;avvocato Renzo Andricciola, l&#8217;uomo si \u00e8 recato dai carabinieri per rendere <strong>dichiarazioni sulla sparatoria<\/strong> e si trova adesso nella caserma della Compagnia carabinieri di Lamezia Terme.<strong> L&#8217;uomo sarebbe stato sottoposto a fermo.<\/strong> Le indagini proseguono per accertare e riscontrare ulteriori aspetti della sparatoria scaturita al termine di una<strong> lite<\/strong>. Intanto, il ferito pi\u00f9 grave, raggiunto all&#8217;addome, \u00e8 stato sottoposto ad un intervento chirurgico nell&#8217;ospedale cittadino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le indagini proseguono per accertare e riscontrare ulteriori aspetti della sparatoria scaturita al termine di una lite, L&#8217;uomo ha reso dichiarazioni oggi in merito alla sparatoria<\/p>\n","protected":false},"author":58,"featured_media":273646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-273643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=273643"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/273646"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=273643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=273643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=273643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}