{"id":273780,"date":"2025-10-25T13:52:10","date_gmt":"2025-10-25T11:52:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=273780"},"modified":"2025-10-25T13:52:57","modified_gmt":"2025-10-25T11:52:57","slug":"lospedale-universitario-ad-arcavacata-va-bene-ma-lhub-deve-restare-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lospedale-universitario-ad-arcavacata-va-bene-ma-lhub-deve-restare-a-cosenza\/","title":{"rendered":"\u00abL\u2019ospedale universitario ad Arcavacata va bene ma l\u2019Hub deve restare a Cosenza\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;L\u2019ospedale universitario ad Arcavacata di Rende va bene ma l\u2019ospedale Hub deve restare a Cosenza, citt\u00e0 capoluogo della provincia pi\u00f9 grande della Calabria. Se il sito di Vaglio Lise individuato e deliberato dal Consiglio comunale dovesse ritenersi inadeguato a causa di un insuperabile rischio idrogeologico, l\u2019ospedale opportunamente consolidato, ristrutturato, ampliato e potenziato dovrebbe restare dov\u2019\u00e8 adesso&#8221;. A scriverlo <strong>Piero Minutolo Presidente associazione \u201cIo partecipiamo\u201d ed ex sindaco di Cosenza.<\/strong><\/p>\n<p>La citt\u00e0 di Cosenza che nell\u2019arco di trent\u2019anni ha perduto pi\u00f9 di quarantamila abitanti non pu\u00f2 rinunciare anche a questa funzione direzionale fondamentale dal punto di vista sanitario e strategica per le sue ricadute sociali ed economiche. <strong>Senza ospedale Cosenza diventerebbe una citt\u00e0 senz\u2019anima.<\/strong><\/p>\n<p>Il centro storico si avvierebbe fatalmente, malgrado gli interventi del Cis e di Agenda urbana, verso un ulteriore processo di degrado e abbandono mentre l\u2019intera citt\u00e0 dei Bruzi registrerebbe un ulteriore spopolamento ed un consistente impoverimento delle attivit\u00e0 professionali, commerciali e dei servizi. L<strong>a collocazione ad Arcavacata di Rende in una zona sprovvista di collegamenti che potrebbero realisticamente realizzarsi in un giorno futuro, incerto e lontano<\/strong>, renderebbe il presidio sanitario difficilmente raggiungibile soprattutto dal nucleo centrale della citt\u00e0, dal Centro storico e dalla Presila, da Sant\u2019Ippolito, Borgo Partenope, Donnici superiore e inferiore, dai Comuni a sud di Cosenza e dalla zona industriale di Piano Lago. Dinnanzi al rischio di esproprio del pi\u00f9 importante presidio sanitario pubblico della provincia di Cosenza sorprende ma non meraviglia il silenzio di quanti negli anni hanno sostenuto la necessit\u00e0 di scelte rivolte al riequilibrio territoriale dello sviluppo, alla realizzazione dello svincolo autostradale a sud e alla rigenerazione del centro storico. Le accuse di campanilismo a chi cerca di difendere ci\u00f2 che ha sono irricevibili.<\/p>\n<p>Andrebbero semmai rivolte a quanti vogliono appropriarsi di un presidio sanitario di grande prestigio come l\u2019ospedale dell\u2019Annunziata che opera a servizio della citt\u00e0 di Telesio e dell\u2019intera provincia di Cosenza da pi\u00f9 di ottant\u2019anni. Auspichiamo pertanto che le decisioni e le azioni conseguenti vengano assunte da Regione, Comune di Cosenza e Universit\u00e0 della Calabria in un <strong>clima di operosa concordia<\/strong> per evitare che anche il nuovo ospedale finisca nel grande \u201cmare magnum\u201d delle opere annunciate, progettate, finanziate e mai realizzate. La storia delle opere pubbliche in Calabria ci dice, purtroppo, che le parole molte volte hanno mangiato i fatti&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A scriverlo Piero Minutolo Presidente associazione &#8216;Io partecipiamo&#8217; ed ex sindaco di Cosenza: &#8220;Senza ospedale Cosenza diventerebbe una citt\u00e0 senz\u2019anima&#8221;<\/p>\n","protected":false},"author":58,"featured_media":266983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-273780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=273780"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/266983"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=273780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=273780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=273780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}