{"id":273857,"date":"2025-10-26T21:20:38","date_gmt":"2025-10-26T20:20:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=273857"},"modified":"2025-10-27T09:43:58","modified_gmt":"2025-10-27T08:43:58","slug":"dramma-a-cosenza-soccorritore-della-misericordia-di-amantea-si-e-spento-a-seguito-malore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/dramma-a-cosenza-soccorritore-della-misericordia-di-amantea-si-e-spento-a-seguito-malore\/","title":{"rendered":"Dramma a Cosenza, soccorritore della Misericordia di Amantea si \u00e8 spento a seguito di un malore"},"content":{"rendered":"<p>COSENZA &#8211; Tragedia nel pomeriggio di oggi a Cosenza, durante la Festa del Cioccolato che ha animato il centro cittadino. Secondo quanto ricostruito <strong>Fausto Ricetto, 65 anni, storico soccorritore della Misericordia di Amantea<\/strong>, ha accusato un grave malore mentre si trovava su Corso Mazzini, tra i visitatori della manifestazione.<\/p>\n<p>L\u2019uomo si sarebbe sentito male sotto gli occhi dei presenti che hanno immediatamente allertato i soccorsi. Trasferito d\u2019urgenza all\u2019ospedale Annunziata di Cosenza, \u00e8 arrivato gi\u00e0 in arresto cardiaco e nonostante i tentativi di rianimarlo, per lui non c\u2019\u00e8 stato nulla da fare. Alcuni amici e colleghi, appresa la notizia, hanno espresso dolore e sconcerto per quanto accaduto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> L\u2019uomo, 65 anni, avrebbe accusato un malore mentre era su Corso Mazzini. Inutili i tentativi di rianimarlo: \u00e8 morto all\u2019ospedale dell\u2019Annunziata<\/p>\n","protected":false},"author":42,"featured_media":273858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,803],"tags":[],"class_list":["post-273857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-cronaca"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=273857"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/273858"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=273857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=273857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=273857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}