{"id":273968,"date":"2025-10-27T19:30:16","date_gmt":"2025-10-27T18:30:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=273968"},"modified":"2025-10-27T18:43:04","modified_gmt":"2025-10-27T17:43:04","slug":"delitto-torcasio-il-suo-assassino-tace-nessun-dettaglio-sul-movente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/delitto-torcasio-il-suo-assassino-tace-nessun-dettaglio-sul-movente\/","title":{"rendered":"Delitto Torcasio, il suo assassino tace: nessun dettaglio sul movente"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; Si \u00e8 avvalso della facolt\u00e0 di non rispondere <strong>Pasquale Colelli,<\/strong> 30enne responsabile del <strong>delitto <a href=\"https:\/\/quicosenza.it\/news\/dal-bar-allagghiacciante-delitto-a-coltellate-sul-lungomare-cosi-e-morto-emilio-torcasio\/\" target=\"_blank\" rel=\"noopener\">di Emiliano Torcasio,<\/a> <\/strong>avvenuto a Lamezia Terme nella notte tra venerd\u00ec e sabato scorsi. Colelli, che conosceva la vittima 52enne da tempo, si era costituito ai carabinieri nella giornata di sabato assumendosi la responsabilit\u00e0 dell&#8217;omicidio.<\/p>\n<p>Nel corso dell&#8217;udienza di convalida dell&#8217;arresto, svoltasi davanti al gip di Lamezia in presenza anche del sostituto procuratore Vincenzo Quaranta, titolare del fascicolo d&#8217;inchiesta aperto sull&#8217;omicidio, Colelli, difeso dagli avvocati Domenico Villella e Antonio Perri, <strong>non ha inteso chiarire<\/strong>, in particolare, il <strong>movente<\/strong> per il quale ha ucciso a coltellate Emiliano Torcasio.<\/p>\n<p>I legali di Colelli, secondo quanto si \u00e9 appreso, si riservano di valutare in un secondo momento <strong>se avanzare richiesta di incidente probatorio<\/strong> anche per<strong> valutare lo stato psicologico del giovane.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pasquale Colelli si era costituito: davanti al Gip noh ha spiegato le motivazioni che lo hanno spinto ad uccidere il 52enne che conosceva da tempo <\/p>\n","protected":false},"author":90,"featured_media":273700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-273968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=273968"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/273968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/273700"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=273968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=273968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=273968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}