{"id":27402,"date":"2013-11-11T05:50:58","date_gmt":"2013-11-11T04:50:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27402"},"modified":"2023-01-17T13:24:52","modified_gmt":"2023-01-17T12:24:52","slug":"11359-arrestato-consigliere-comunale-per-droga-e-banconote-false","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11359-arrestato-consigliere-comunale-per-droga-e-banconote-false\/","title":{"rendered":"Arrestato consigliere comunale per droga e banconote false"},"content":{"rendered":"<p>TORANO CASTELLO (CS) &#8211; Altro che politiche giovanili e iniziative di interesse per le generazioni future; la &#8220;speciale&#8221; delega a lui assegnata non era proprio calzante.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Elmiro Vitale, 34 anni, consigliere comunale di Torano, e proprietario del bar &#8220;lo Sfizietto&#8221;, \u00e8 stato arrestato dai carabinieri per detenzione ai fini di spaccio di sostanze stupefacenti e possesso di valuta falsa. Vitale \u00e8 finito in manette perch\u00e8 perquisito dai militari, \u00e8 stato trovato in possesso di 70 grammi di hascisc e 10 di marijuana e addosso aveva anche circa 3300 euro, forse i proventi dell&#8217;attivit\u00e0 di spaccio. La droga era nascosta in un portaocchiali che l&#8217;uomo aveva infilato dietro la schiena, tentando di occultarlo. I carabinieri hanno poi perquisito l&#8217;abitazione e l&#8217;attivit\u00e0 commerciale gestita dal consigliere comunale di maggioranza, dove hanno trovato altri 129 grammi di hascisc, 2980 euro, banconote false per 460 euro, cambiali e assegni. L\u2019uomo \u00e8 stato associato presso la casa circondariale Cosenza. I reati contestati sono detenzione stupefacenti, spendita e introduzione nello Stato di monete falsificate, falsa attestazione o dichiarazione commessa dal privato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORANO CASTELLO (CS) &#8211; Altro che politiche giovanili e iniziative di interesse per le generazioni future; la &#8220;speciale&#8221; delega a lui assegnata non era proprio calzante.<\/p>\n","protected":false},"author":19,"featured_media":27403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-27402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27402"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27403"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}