{"id":274020,"date":"2025-10-28T12:01:58","date_gmt":"2025-10-28T11:01:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274020"},"modified":"2025-10-28T12:47:12","modified_gmt":"2025-10-28T11:47:12","slug":"scomparso-a-cosenza-ore-dansia-per-il-47enne-paolo-valentino-lappello-aiutateci-a-trovarlo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scomparso-a-cosenza-ore-dansia-per-il-47enne-paolo-valentino-lappello-aiutateci-a-trovarlo\/","title":{"rendered":"Scomparso a Cosenza, ore d\u2019ansia per il 47enne Paolo Valentino. L&#8217;appello \u201caiutateci a trovarlo\u201d"},"content":{"rendered":"<p>COSENZA &#8211; Ore di apprensione a Cosenza per la scomparsa di <strong>Paolo Valentino<\/strong>, <strong>47 anni<\/strong>, di cui non si hanno pi\u00f9 notizie dalla notte scorsa. I familiari, preoccupati per la sua assenza, hanno lanciato<strong> un appello pubblico sui social<\/strong> e sporto regolare denuncia di scomparsa alle forze dell\u2019ordine.<\/p>\n<p>Secondo quanto riferito dai parenti, Paolo Valentino \u00e8 <strong>scomparso nella notte tra luned\u00ec e marted\u00ec<\/strong>, e da allora si sono perse completamente le sue tracce. Al momento della scomparsa indossava <strong>una maglia nera, pantaloni neri e un giubbino nero<\/strong>. Porta <strong>occhiali da vista<\/strong> e potrebbe trovarsi ancora nell\u2019area urbana di <strong>Cosenza o zone limitrofe<\/strong>, dove amici e familiari stanno battendo il territorio da diverse ore, purtroppo senza esito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-274023 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Paolo-Valentino.jpg\" alt=\"Paolo Valentino\" width=\"298\" height=\"417\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Paolo-Valentino.jpg 920w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Paolo-Valentino-214x300.jpg 214w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Paolo-Valentino-731x1024.jpg 731w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Paolo-Valentino-768x1075.jpg 768w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/><\/p>\n<p>La famiglia chiede l\u2019aiuto di tutti: \u201cSiamo molto preoccupati. Lo stiamo cercando in vano in tutta Cosenza ma non riusciamo a trovarlo. Vi chiediamo di condividere l\u2019appello e di avvisarci subito in caso di avvistamenti. Chiunque abbia <strong>informazioni utili<\/strong> o pensi di averlo visto \u00e8 invitato a <strong>contattare immediatamente le autorit\u00e0 competenti<\/strong> o chiamare il numero <strong>377 4548435&#8243;<\/strong>.<\/p>\n<p>L\u2019appello \u00e8 gi\u00e0 stato <strong>rilanciato da numerosi cittadini attraverso i social<\/strong> nella speranza che Paolo possa essere ritrovato al pi\u00f9 presto e tornare a casa dai suoi cari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019appello di familiari e conoscenti. Chiunque lo avvisti contatti immediatamente le autorit\u00e0 o il numero 377 4548435<\/p>\n","protected":false},"author":55,"featured_media":274021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-274020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274020"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/274021"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}