{"id":27410,"date":"2013-11-11T07:19:48","date_gmt":"2013-11-11T06:19:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27410"},"modified":"2023-01-17T13:24:52","modified_gmt":"2023-01-17T12:24:52","slug":"11363-turchia-vende-il-figlio-di-4-mesi-per-365-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11363-turchia-vende-il-figlio-di-4-mesi-per-365-euro\/","title":{"rendered":"Turchia, vende il figlio di 4 mesi per 365 euro"},"content":{"rendered":"<p>ISTANBUL (TURCHIA) &#8211; Sono immagini shock quelle che arrivano dalla Turchia ma ancora pi\u00f9 scioccante \u00e8 il gesto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una giovane mamma \u00e8 stata colta in flagranza a vendere il proprio figlio di quattro mesi all\u2019aeroporto di Sabiha Gocken. La donna, del Turkmenistan \u00e8 stata fermata dalla polizia che nel frattempo aveva seguito gli strani movimenti del suo bagaglio tramite le telecamere di sorveglianza. Il video delle riprese, \u00e8 stato diffuso in rete e mostra chiaramente la donna che scende da un taxi con in mano una valigia insieme a un connazionale. Raggiunti da una coppia di tedeschi, ovvero i potenziali acquirenti, i due si mettono a discutere e poi si spostano nel bagno, il luogo nel quale sarebbe avvenuto lo scambio per una cifra di &#8220;soli&#8221; 365 euro. La polizia ha arrestato la donna e il suo complice e denunciato la coppia tedesca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ISTANBUL (TURCHIA) &#8211; Sono immagini shock quelle che arrivano dalla Turchia ma ancora pi\u00f9 scioccante \u00e8 il gesto.<\/p>\n","protected":false},"author":19,"featured_media":27411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,22],"tags":[],"class_list":["post-27410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27410"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27411"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}