{"id":274246,"date":"2025-10-30T12:47:46","date_gmt":"2025-10-30T11:47:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274246"},"modified":"2025-10-30T12:47:46","modified_gmt":"2025-10-30T11:47:46","slug":"incendi-dolosi-due-persone-denunciate-elevate-sanzioni-per-15mila-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/incendi-dolosi-due-persone-denunciate-elevate-sanzioni-per-15mila-euro\/","title":{"rendered":"Incendi dolosi, due persone denunciate: elevate sanzioni per 15mila euro"},"content":{"rendered":"<p>CATANZARO &#8211; L&#8217;impegno dei Carabinieri di Sellia Marina nel contrasto al fenomeno degli incendi ha riguardato l\u2019area della Presila e la fascia ionica catanzarese. Due persone denunciate in stato di libert\u00e0 come presunti autori di incendi dolosi di aree di macchia mediterranea e decine di sanzioni amministrative, per un <strong>valore complessivo di circa 15.000 euro<\/strong>, nell\u2019ambito del Piano Regionale per la prevenzione e la lotta attiva agli incendi boschivi.<\/p>\n<p>A <strong>Sellia Marina e Sersale<\/strong>, i militari hanno intensificato i servizi di pattugliamento e prevenzione dopo i numerosi episodi che hanno interessato boschi e terreni incolti. In <strong>due distinte occasioni<\/strong>, i carabinieri sono riusciti a individuare e <strong>fermare due uomini<\/strong> <strong>subito dopo aver appiccato il fuoco a sterpaglie<\/strong> e <strong>residui vegetali<\/strong> raccolti nei pressi delle loro abitazioni. I roghi, <strong>alimentati dal vento,<\/strong> si sono rapidamente propagati ai terreni confinanti, mettendo a rischio anche la viabilit\u00e0 locale e causando danni all\u2019ambiente.<\/p>\n<p>Oltre ai due denunciati, i controlli hanno portato all\u2019applicazione di <strong>numerose sanzioni amministrative<\/strong> per violazioni alla normativa regionale in materia di incendi boschivi, a seguito di oltre cento servizi perlustrativi effettuati nelle ultime settimane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;attivit\u00e0 di contrasto ai incendi dolosi in Presila e sulla fascia jonica. Intensificati i controlli con oltre 100 servizi perlustrativi e multe per violazioni alla legge regionale <\/p>\n","protected":false},"author":42,"featured_media":112662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-274246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274246"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112662"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}