{"id":274309,"date":"2025-10-31T09:02:16","date_gmt":"2025-10-31T08:02:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274309"},"modified":"2025-10-31T09:03:52","modified_gmt":"2025-10-31T08:03:52","slug":"ponte-sullo-stretto-matteo-salvini-voglio-farlo-e-non-mi-interessan-scontri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ponte-sullo-stretto-matteo-salvini-voglio-farlo-e-non-mi-interessan-scontri\/","title":{"rendered":"Ponte sullo Stretto, Matteo Salvini \u00abvoglio farlo e non mi interessano gli scontri\u00bb"},"content":{"rendered":"<p>ROMA &#8211; Il ponte &#8220;lo voglio fare e non mi interessano gli scontri&#8221;, dice il ministro delle Infrastrutture e dei Trasporti e vicepremier, Matteo Salvini, rispondendo, ospite a RaiRadiouno, rispondendo a chi gli chiede perch\u00e8 ha abbassato i toni, dopo le prime reazioni allo stop della <a href=\"https:\/\/quicosenza.it\/news\/la-corte-dei-conti-ferma-il-ponte-sullo-stretto-chiarimenti-su-costi-e-iter-ma-il-governo-potrebbe-andare-avanti\/\">Corte dei Conti<\/a>. Riguardo alla posizione di Luca Zaia, il ministro dei trasporti sottolinea &#8220;ha gi\u00e0 smentito. D&#8217;altronde La Stampa, Repubblica&#8230; fanno titoli contro la Lega e contro Salvini da anni. <strong>Ognuno fa il suo mestiere<\/strong>. La domanda \u00e8:<strong> il ponte serve o non serve<\/strong>? Chiedete ai <strong>siciliani<\/strong>, ai <strong>calabresi<\/strong>, agli italiani, agli ingegneri italiani che sono fra i migliori al mondo e che fanno ponti ovunque&#8221;.<\/p>\n<p>&#8220;Oggi ho letto sui giornali che fortunatamente la <strong>stragrande maggioranza delle persone normali, non dei politici<\/strong>&#8230; ho letto grandi architetti a favore del ponte come Fuksas, come Libeskind, le associazioni degli agricoltori, dei commercianti, degli imprenditori, dei camionisti, e l&#8217;amministratore di Enel, di Ferrovie dello Stato, Confindustria. Il<strong> ponte non serve a Salvini o a Zanchini<\/strong>&#8220;, risponde.<\/p>\n<p>&#8220;Il ponte, dopo decenni di promesse mancate, <strong>unisce 5 milioni di italiani che vivono in Sicilia all&#8217;Italia e all&#8217;Europa<\/strong>&#8220;. &#8220;Lo vuole l&#8217;Europa. <strong>Ce lo chiedono gli agricoltori, gli ingegneri, gli amministratori<\/strong>&#8230; Ce lo chiedono tutti, <a href=\"https:\/\/quicosenza.it\/news\/giu-le-mani-dallo-stretto-il-29-novembre-manifestazione-contro-il-ponte-in-piazza-anche-cgil-pd-m5s-e-avs\/\">non lo vogliono<\/a> i Cinque Stelle&#8221;.<\/p>\n<h3>Ponte, &#8220;se non lo facesse Salvini sarebbero tutti a festeggiare&#8221;<\/h3>\n<p>Per gli elettori del Nord non \u00e8 una priorit\u00e0 della Lega? &#8220;Il ponte serve agli italiani, serve ai leghisti, serve a quelli del Pd, serve a quelli dei Cinque Stelle&#8221;. <strong>&#8220;Se non lo facesse <a href=\"https:\/\/quicosenza.it\/news\/ponte-stop-della-corte-dei-conti-ciucci-lavori-slittano-a-febbraio-il-governo-va-avanti\/\">Salvini<\/a> come ministro, il ponte, sarebbero tutti a festeggiare, a dire che \u00e8 una grande opera<\/strong>, serve, finalmente, dopo un secolo. Purtroppo qualcuno di l\u00e0 lo ha ideologizzato, e quindi siccome lo fa Salvini&#8230; &#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ministro Salvini: &#8220;la domanda \u00e8: il ponte serve o non serve? Chiedete ai siciliani, ai calabresi, agli ingegneri italiani che sono fra i migliori al mondo e che fanno ponti ovunque&#8221;<\/p>\n","protected":false},"author":42,"featured_media":274311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-274309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274309"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/274311"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}