{"id":27434,"date":"2013-11-11T18:02:40","date_gmt":"2013-11-11T17:02:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27434"},"modified":"2023-01-17T13:24:54","modified_gmt":"2023-01-17T12:24:54","slug":"11375-le-pagelle-dei-rosso-blu-7","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11375-le-pagelle-dei-rosso-blu-7\/","title":{"rendered":"Poggibonsi &#8211; Cosenza: le pagelle dei rosso blu"},"content":{"rendered":"<p>COSENZA -Ecco le nostre valutazioni sulla prova vittoriosa degli atleti silani a Poggibonsi.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>Frattali<\/strong> : insuperabile come sempre, portiere di categorie superiori <strong>7.5<\/strong><br \/><strong>Palazzi<\/strong> : prova di spessore e grande sostanza, bravo anche da centrale<strong> 7<\/strong><br \/><strong>Mannini<\/strong> : come tutti i suoi compagni di squadra si sacrifica fornendo una prestazione impeccabile <strong>7<\/strong><br \/><strong>Meduri<\/strong> : attento a tenere a bada chiunque capiti dalle sue parti<strong> 7<\/strong><br \/><strong>Blondett<\/strong> : <strong>S. V.<\/strong><br \/><strong>Pepe<\/strong> : ritorna titolare dimostrando di essere un centrale di sicuro affidamento <strong>7<\/strong><br \/><strong>Bigoni<\/strong> : esterno basso a destra, esterno basso a sinistra o esterno di centrocampo il risultato \u00e8 sempre lo stesso, semplicemente perfetto <strong>7<\/strong><br \/><strong>Giordano<\/strong> : lotta come un leone su ogni pallone 7<br \/><strong>Mosciaro<\/strong> : in occasione del goal ci crede e viene premiato, tornato sui livelli dello scorso campionato <strong>7<\/strong><br \/><strong>Calderini<\/strong> : non era il suo campo, ma lotta come meglio non potrebbe <strong>7<\/strong><br \/><strong>Alessandro<\/strong> : pur essendo un giocatore tecnico, dimostra ancora una volta la sua importanza in fase di non possesso palla :<strong>7<\/strong><br \/><strong>Carrieri<\/strong> : entra subito in partita fornendo il suo contributo alla vittoria<strong> 6.5<\/strong><br \/><strong>Criaco<\/strong> : si vede quanto importante possa essere per la squadra : <strong>6.5<\/strong><br \/><strong>Napolano<\/strong> : entra e lotta con grande ardore <strong>6.5<\/strong><br \/><strong>Cappellacci<\/strong> : la squadra esegue alla perfezione ci\u00f2 che lui pretende, dimostrando che le vittorie sono anche frutto di lavoro e capacit\u00e0 : <strong>7<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA -Ecco le nostre valutazioni sulla prova vittoriosa degli atleti silani a Poggibonsi.<\/p>\n","protected":false},"author":22,"featured_media":27435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-27434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27434"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27435"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}