{"id":274379,"date":"2025-10-31T14:48:38","date_gmt":"2025-10-31T13:48:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274379"},"modified":"2025-10-31T14:48:38","modified_gmt":"2025-10-31T13:48:38","slug":"no-al-ponte-occhiuto-il-governo-procedera-malgrado-la-corte-dei-conti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/no-al-ponte-occhiuto-il-governo-procedera-malgrado-la-corte-dei-conti\/","title":{"rendered":"No al Ponte? Occhiuto: &#8220;Il Governo proceder\u00e0 malgrado la Corte dei Conti&#8221;"},"content":{"rendered":"<p>CATANZARO &#8211; &#8220;Sono convinto che il Governo, che ha dimostrato su questa materia grande determinazione, proceder\u00e0 comunque nella realizzazione del ponte sullo Stretto, pur nel rispetto doveroso della<strong> sentenza della <a href=\"https:\/\/quicosenza.it\/news\/la-corte-dei-conti-dice-no-al-ponte-sullo-stretto-niente-visto-per-la-delibera-cipess\/\" target=\"_blank\" rel=\"noopener\">Corte dei Conti<\/a>&#8220;<\/strong>. Cos\u00ec il <strong>presidente della Regione Calabria, Roberto Occhiuto<\/strong>, parlando con i giornalisti a Catanzaro. &#8220;La legge &#8211; ha aggiunto Occhiuto &#8211; consente al Governo di chiedere alla Corte dei Conti la trascrizione con riserva e avviare i lavori. Penso che il ponte sia un grande attrattore di altre infrastrutture e di sviluppo. Abbiamo avuto tre miliardi e 800 milioni per il completamento della statale 106, 900 milioni per l&#8217;autostrada A2 e 500 milioni per la Trasversale delle Serre. A breve avremo anche altre risorse che sono riuscito ad ottenere. Manca pochissimo per l&#8217;ammodernamento dell&#8217;autostrada A2 e partiremo presto con lo svincolo di Cosenza e uno dei lotti della <strong><a href=\"https:\/\/quicosenza.it\/news\/autostrada-a2-3-miliardi-di-euro-e-3-anni-di-lavoro-per-il-nuovo-tracciato-da-cosenza-ad-altilia\/\" target=\"_blank\" rel=\"noopener\">Cosenza-Altilia<\/a><\/strong>. Tutte queste risorse le abbiamo avute grazie al Ponte. <strong>Una volta tanto la Calabria e la Sicilia possono essere al centro dell&#8217;interesse di tutto il mondo perch\u00e9 il ponte sar\u00e0 la pi\u00f9 grande opera<\/strong> <strong>di ingegneria<\/strong> mai realizzata in Italia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Una volta tanto la Calabria e la Sicilia possono essere al centro dell&#8217;interesse di tutto il mondo perch\u00e9 il ponte sar\u00e0 la pi\u00f9 grande opera di ingegneria&#8221;, ha dichiarato il governatore della Calabria<\/p>\n","protected":false},"author":58,"featured_media":197553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-274379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274379"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/197553"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}