{"id":274723,"date":"2025-12-24T19:57:29","date_gmt":"2025-12-24T18:57:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274723"},"modified":"2025-12-24T17:10:40","modified_gmt":"2025-12-24T16:10:40","slug":"politici-italiani-chi-sono-i-piu-ricchi-la-classifica-dei-redditi-2025-riserva-colpi-di-scena","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/politici-italiani-chi-sono-i-piu-ricchi-la-classifica-dei-redditi-2025-riserva-colpi-di-scena\/","title":{"rendered":"Politici italiani, chi sono i pi\u00f9 ricchi? La classifica dei redditi 2025 riserva colpi di scena"},"content":{"rendered":"<p>ROMA &#8211; <strong><a href=\"https:\/\/quicosenza.it\/news\/corruzione-in-italia-indagati-per-mazzette\/\" target=\"_blank\" rel=\"noopener\">Politici<\/a> italiani<\/strong>: chi sono i pi\u00f9 ricchi? In classifica c&#8217;\u00e8 sempre lei, l&#8217;avvocata e presidente della commissione Giustizia del Senato<strong> Giulia Bongiorno, che supera i 3 milioni di euro.<\/strong> Seguita, a una prima ricerca tra chi gi\u00e0 ha aggiornato la sua documentazione patrimoniale, da<strong> Giulio Tremonti che supera di poco i 2 milioni di euro.<\/strong> E spulciando tra i redditi dei parlamentari, che vengono pubblicati sui siti di Camera e Senato via via che i singoli forniscono i dati, emerge un reddito pi\u00f9 che dimezzato per la presidente del Consiglio, <strong>Giorgia Meloni,<\/strong> che nelle variazioni annota l&#8217;acquisto &#8220;definitivo&#8221; di un&#8217;abitazione &#8220;come prima casa&#8221;. Il reddito della premier passa cos\u00ec <strong>dai quasi 460mila euro dichiarati nel 2024 ai 180.031 dichiarati nel 2025<\/strong> (su cui sconta poco pi\u00f9 di 6mila euro di detrazioni per ristrutturazioni, mutuo e contributi al partito). Anche altri parlamentari hanno comprato casa lo scorso anno, ad esempio il capogruppo di Fdi alla Camera <strong>Galeazzo Bignami<\/strong> ha acquistato un&#8217;abitazione a Bologna (dichiara poco meno di 100mila euro) o il segretario dell&#8217;Udc e questore del Senato <strong>Antonio De Poli<\/strong> segnala una nuova casa a Padova (dichiarazione 2025 circa 146mila euro).<\/p>\n<p>Tra i capi partito che siedono in Parlamento <strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/Matteo_Renzi\" target=\"_blank\" rel=\"noopener\">Matteo Renzi<\/a> e Giuseppe Conte<\/strong> non hanno ancora dato per la pubblicazione le loro dichiarazioni, cos\u00ec come il vicepremier e leader della Lega Matteo Salvini. L&#8217;altro vicepremier e segretario di Forza Italia, Antonio Tajani, ha gi\u00e0 depositato la sua (circa 187mila euro), cos\u00ec come il leader di Noi Moderati Maurizio Lupi (che si attesta attorno ai 250mila euro). C&#8217;\u00e8 gi\u00e0 la dichiarazione del leader di Azione Carlo Calenda (circa 122mila euro) e di quello dei Verdi Angelo Bonelli (circa 100mila euro). Sotto queste cifre sia la segretaria del Pd Elly Schlein (98.471 euro) e quello di Sinistra italiana Nicola Fratoianni (poco meno di 99mila euro).<\/p>\n<p>Tra i <strong>ministri<\/strong> che hanno anche uno scranno alla Camera o al Senato, risultano gi\u00e0 <strong>Carlo Nordio<\/strong> (che dichiara quasi 260mila euro), <strong>Adolfo Urso<\/strong> (circa 126mila euro). Luca Ciriani dichiara circa 100mila mentre il titolare dell&#8217;Economia Giancarlo Giorgetti non arriva alla cifra tonda ma si ferma a circa 99mila euro. Tra i <strong>non parlamentari Alessandra Locatelli<\/strong> dichiara circa 100mila euro, <strong>Matteo Piantedosi<\/strong> circa 96mila, Orazio Schillaci circa 102mila euro. Pur impegnato in campagna elettorale per le Regionali in Campania, <strong>Edmondo Cirielli<\/strong> ha gi\u00e0 inviato la sua dichiarazione (circa 160mila euro) mentre non risulta ancora pubblicata quella di un altro parlamentare in corsa come governatore, questa volta del Veneto, cio\u00e8 il leghista Alberto Stefani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra chi compra casa e chi dichiara milioni, la fotografia dei redditi 2025. Bongiorno la pi\u00f9 ricca, Meloni in calo, Schlein sotto i 100mila euro<\/p>\n","protected":false},"author":58,"featured_media":274725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-274723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274723"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/274725"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}