{"id":274953,"date":"2025-11-15T20:00:28","date_gmt":"2025-11-15T19:00:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274953"},"modified":"2025-11-15T18:29:32","modified_gmt":"2025-11-15T17:29:32","slug":"campare-cento-anni-italia-longeva-con-oltre-23mila-centenari-8-su-10-sono-donne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/campare-cento-anni-italia-longeva-con-oltre-23mila-centenari-8-su-10-sono-donne\/","title":{"rendered":"&#8220;Campare cento anni&#8221;: Italia longeva con oltre 23mila centenari, 8 su 10 sono donne"},"content":{"rendered":"<p>ROMA &#8211; In Italia si &#8220;campa cento anni&#8221;; si potrebbe definire cos\u00ec il nostro Paese, in cui le culle restano spesso vuote mentre invece gli anziani vivono sempre pi\u00f9 a lungo. Sono oltre <strong>23mila i centenari<\/strong> in Italia, con una netta prevalenza femminile: <strong>otto su dieci sono donne<\/strong>, secondo l\u2019ultimo <strong><a href=\"https:\/\/www.istat.it\/wp-content\/uploads\/2025\/11\/STAT-TODAY_CENTENARI-2025.pdf\" rel=\"noopener\">rapporto <\/a><a href=\"https:\/\/www.istat.it\/wp-content\/uploads\/2025\/11\/STAT-TODAY_CENTENARI-2025.pdf\" rel=\"noopener\">Istat<\/a> aggiornato al 1\u00b0 gennaio 2025.<\/strong> Tra i <strong>nomi pi\u00f9 diffusi tra gli over 100<\/strong> figurano ancora <strong>Maria<\/strong> e <strong>Giuseppe<\/strong>, un tempo molto comuni ma oggi in disuso. <strong>Quasi l\u201983% dei centenari \u00e8 di sesso femminile<\/strong>. Rispetto al 2009, quando erano 10.158, il numero di centenari \u00e8 pi\u00f9 che raddoppiato (+130%). <strong>La crescita non \u00e8 stata lineare<\/strong>: tra il 2015 e il 2019 si \u00e8 registrata una flessione dovuta all\u2019ingresso tra gli ultracentenari delle generazioni nate durante la Prima Guerra Mondiale, meno numerose.<\/p>\n<h3>Semi supercentenari<\/h3>\n<p>I cosiddetti semi-supercentenari, ovvero le persone <strong>dai 105 anni in<\/strong> <strong>su<\/strong>, sono<strong> 724,<\/strong> in aumento rispetto ai <strong>654 del 2024<\/strong>. La maggioranza \u00e8 donna: 657 su 724 (90,7%). I supercentenari, con 110 anni o pi\u00f9, sono 19, solo uno dei quali maschio. Tra il 2009 e il 2025, 8.980 persone hanno superato i 105 anni: 7.956 donne (88%) e 1.024 uomini (12%).\u00a0Tra<strong> gli over 105, la maggior parte \u00e8 vedova o vedovo<\/strong>: 86% delle donne e 80% degli uomini. Le nubili rappresentano il 12% delle donne, il doppio dei celibi (6%); le donne coniugate sono solo l\u20191%, mentre gli uomini coniugati quasi il 14%, a conferma della maggiore longevit\u00e0 femminile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-274958 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/regoni-centenari-istat.jpg\" alt=\"regioni centenari istat\" width=\"882\" height=\"371\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/regoni-centenari-istat.jpg 1040w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/regoni-centenari-istat-300x126.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/regoni-centenari-istat-1024x431.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/regoni-centenari-istat-768x323.jpg 768w\" sizes=\"auto, (max-width: 882px) 100vw, 882px\" \/><\/p>\n<h3>Il decano d&#8217;Italia \u00e8 in Basilicata<\/h3>\n<p>Fino a <strong>ottobre 2025<\/strong>, il decano d\u2019Italia \u00e8 un uomo residente in <strong>Basilicata<\/strong>, con oltre 111 anni; la <strong>decana<\/strong> d\u2019Italia, residente in <strong>Campania<\/strong>, tra pochi giorni festegger\u00e0 i 115 anni. A livello mondiale, tra i viventi, il record per le donne \u00e8 di 116 anni e per gli uomini di 112 anni.\u00a0La distribuzione territoriale dei centenari mostra differenze significative. In valore assoluto, la Lombardia guida la classifica (quasi 4 mila), seguita da Lazio ed Emilia-Romagna (oltre 2 mila ciascuna). In termini relativi, il Molise ha circa 61 centenari ogni 100 mila residenti, mentre la Liguria, storicamente regione a pi\u00f9 forte invecchiamento, ne conta 59,4 ogni 100 mila. Tra le province, spiccano Isernia (78,7), Nuoro (65,5) e Siena e Gorizia (63,5). Tra le province liguri, Imperia ne conta 61,2, Genova 61,1 e La Spezia 61,0.<\/p>\n<p>Per quanto riguarda i semi-supercentenari, la Valle d\u2019Aosta ne ha la maggiore concentrazione (2,4 ogni 100 mila residenti), seguita dalla Liguria (2,3), Marche (2,0) e Basilicata (1,9). Tra le <strong>province<\/strong>, Nuoro guida con 4,6 ogni 100 mila abitanti.\u00a0Circa l\u201989% dei centenari vive in famiglia, mentre solo 2.598 risiedono in strutture istituzionalizzate. Tra i supercentenari, la quota di chi vive in famiglia sale al 91%, evidenziando come l\u2019assistenza familiare contribuisca a una maggiore qualit\u00e0 della vita. L\u2019Istat evidenzia inoltre che, superati i 105 anni, il rischio di morte non aumenta in maniera esponenziale. <strong>A 105 anni la probabilit\u00e0 di decesso \u00e8 del 48%<\/strong> e rimane sostanzialmente costante fino ai 112 anni, suggerendo un \u201cplateau\u201d della mortalit\u00e0 per i semi-supercentenari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo l\u2019Istat, gli over 100 sono aumentati di oltre 2mila rispetto al 2024, con 724 ultras 105enni e 19 supercentenari. La maggior parte vive ancora in famiglia, soprattutto nel Sud<\/p>\n","protected":false},"author":42,"featured_media":242762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-274953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274953"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/242762"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}