{"id":274978,"date":"2025-11-07T09:31:56","date_gmt":"2025-11-07T08:31:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274978"},"modified":"2025-11-07T07:39:08","modified_gmt":"2025-11-07T06:39:08","slug":"cassano-ionio-leonardo-e-daniel-dieci-anni-damore-coronati-dal-si-il-sindaco-celebra-lunione-civile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cassano-ionio-leonardo-e-daniel-dieci-anni-damore-coronati-dal-si-il-sindaco-celebra-lunione-civile\/","title":{"rendered":"Cassano Ionio: Leonardo e Daniel, dieci anni d\u2019amore coronati dal \u201cs\u00ec\u201d. Il sindaco celebra l&#8217;unione civile"},"content":{"rendered":"<p>CASSANO IONIO (CS) &#8211; Leonardo e Daniel, una coppia conosciuta da tutti, amata e stimata nella citt\u00e0 delle Terme. Hanno coronato il loro sogno d&#8217;amore con l&#8217;unione civile. A celebrare l&#8217;atto, come previsto dalla legge, \u00e8 stato il primo cittadino, <strong>Gianpaolo Iacobini<\/strong>, alla presenza di un <strong>folto gruppo di amici e conoscenti<\/strong> in un sentimento unanime: esprimere orgoglio e vicinanza a due cittadini che, con coraggio e autenticit\u00e0, hanno scelto di <strong>dare dignit\u00e0 giuridica e pubblica al loro legame<\/strong>.<\/p>\n<p>Leonardo, parrucchiere, e Daniel, barista, sono insieme da oltre dieci anni. Una relazione costruita sulla <strong>condivisione dei piccoli e grandi momenti della vita quotidiana<\/strong>, superando <strong>ostacoli e pregiudizi<\/strong>, trasformando ci\u00f2 che per molti \u00e8 ritenuto ancora &#8220;diverso&#8221; in una storia d&#8217;amore normale e splendente. &#8220;La luce che traspare dai loro occhi rende l&#8217;idea della loro felicit\u00e0&#8221;, commentano gli amici di una vita che insieme a loro hanno vissuto anche il giorno della loro unione, tra emozione e applausi sinceri.<\/p>\n<p>Per loro non \u00e8 stato sempre facile: &#8220;<strong>ci sono stati giorni grigi e giorni di sole<\/strong> &#8211; racconta Leonardo &#8211; <strong>ma il nostro amore ci ha insegnato la forza della verit\u00e0<\/strong>&#8220;. Da qui, il suo consiglio a chi, ancora, nasconde la propria identit\u00e0: &#8220;Abbiate il coraggio di osare l&#8217;aurora, di essere felici. Per paura di deludere i propri genitori o le persone care e vicine, molti non mostrano il loro vero essere. Ma <strong>perch\u00e9 condannarsi a un&#8217;infelicit\u00e0 sicura?&#8221;.<\/strong><\/p>\n<p>&#8220;Il sole torna sempre&#8221; aggiunge Daniel, ricordando che il <strong>tempo dell&#8217;amore non conosce etichette<\/strong>. La loro unione civile non \u00e8 solo un atto legale: \u00e8 un faro per tanti giovani che vivono con timore la loro verit\u00e0. In un Paese dove le battaglie per i diritti civili sono ancora aperte, Leonardo e Daniel ricordano a tutti che amare \u00e8 un diritto, e che il coraggio di vivere la propria felicit\u00e0 \u00e8 la pi\u00f9 grande forma di libert\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cerimonia, officiata dal sindaco Gianpaolo Iacobini, ha coronato dieci anni d\u2019amore e di coraggio. \u201cAbbiate il coraggio di essere felici\u201d il loro messaggio alla comunit\u00e0<\/p>\n","protected":false},"author":42,"featured_media":274979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-274978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274978"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/274979"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}