{"id":274982,"date":"2025-11-07T11:00:29","date_gmt":"2025-11-07T10:00:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=274982"},"modified":"2025-11-07T11:16:31","modified_gmt":"2025-11-07T10:16:31","slug":"sicurezza-stradale-calabria-lallarme-del-silp-cgil-servono-piu-uomini-mezzi-e-tutele-per-la-polstrada","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sicurezza-stradale-calabria-lallarme-del-silp-cgil-servono-piu-uomini-mezzi-e-tutele-per-la-polstrada\/","title":{"rendered":"Sicurezza stradale in Calabria, l&#8217;allarme del SILP CGIL: \u00abservono pi\u00f9 uomini, mezzi e tutele per la Polstrada\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; La sicurezza stradale in Calabria \u00e8 a rischio. A lanciare l\u2019allarme \u00e8 il Sindacato Italiano Lavoratori di Polizia \u2013 SILP CGIL Calabria, che denuncia una <strong>situazione ormai insostenibile<\/strong> per la <strong>Polizia Stradale della regione<\/strong>, chiamata ogni giorno a pattugliare arterie autostradali e strade extraurbane spesso con risorse insufficienti. \u201cLa Polstrada svolge un <strong>servizio vitale per i cittadini<\/strong>, ma oggi \u00e8 sempre pi\u00f9 in affanno. Senza un intervento urgente, sar\u00e0 impossibile garantire la vigilanza necessaria sulle arterie calabresi\u201d<br \/>\ndichiara <strong>Ottavio Spinella<\/strong>, Segretario Regionale del SILP CGIL.<\/p>\n<p>Il sindacato chiede il <strong>potenziamento delle pattuglie<\/strong>, un <strong>aumento<\/strong> degli <strong>organici<\/strong> per migliorare la qualit\u00e0 del servizio e tutelare gli operatori, e <strong>l\u2019assegnazione<\/strong> di <strong>nuove autovetture<\/strong>, poich\u00e9 il <strong>parco mezzi attuale \u00e8 giudicato \u201cvetusto<\/strong>\u201d. Indispensabile anche la fornitura di capi di vestiario adeguati per chi lavora ogni giorno su strada e un intervento per eliminare le sperequazioni economiche sull\u2019indennit\u00e0 autostradale, considerate non pi\u00f9 sostenibili.<\/p>\n<p>Il quadro tracciato dal SILP CGIL \u00e8 preoccupante e riguarda tutte le 5 province calabresi:<\/p>\n<p>&#8211; <strong>Cosenza<\/strong>: i distaccamenti sono costretti a unire le pattuglie per coprire i tratti principali.<br \/>\n&#8211; <strong>Crotone<\/strong>: la sezione che opera lungo la SS106 lavora in condizioni difficili senza che la zona sia riconosciuta come sede disagiata.<br \/>\n&#8211; <strong>Reggio Calabria<\/strong>: cinque reparti contano poco pi\u00f9 di un centinaio di agenti chiamati a presidiare un territorio vasto e complesso.<br \/>\n&#8211; <strong>Catanzaro e Vibo Valentia<\/strong>: soffrono anch\u2019esse un sotto dimensionamento ormai strutturale.<\/p>\n<p>La situazione dei mezzi \u00e8 simbolo della criticit\u00e0: \u201cLa riduzione di mezzi e personale ha portato alla contrazione delle pattuglie, con gravi conseguenze sulla sicurezza degli automobilisti e degli stessi operatori. Molte auto di servizio &#8211; evidenzia Spinella &#8211; segnano in media <strong>300.000 chilometri sul contachilometri<\/strong>. Alcune raggiungono <strong>anche i 500.000.<\/strong> Queste vengono utilizzate ancora per diverse centinaia di chilometri a turno e vengono impiegate senza sosta per garantire la presenza su strada\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindacato denuncia organici insufficienti, automezzi logori e difficolt\u00e0 operative in tutte le province calabresi. \u201cCos\u00ec non si pu\u00f2 garantire la sicurezza dei cittadini n\u00e9 quella degli operatori\u201d. Chiesto l\u2019intervento urgente del Ministero dell\u2019Interno<\/p>\n","protected":false},"author":42,"featured_media":257397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-274982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=274982"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/274982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/257397"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=274982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=274982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=274982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}