{"id":275059,"date":"2025-11-07T17:47:31","date_gmt":"2025-11-07T16:47:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=275059"},"modified":"2025-11-07T18:11:25","modified_gmt":"2025-11-07T17:11:25","slug":"lotta-al-degrado-e-sicurezza-urbana-nuovo-blitz-allautostazione-di-cosenza-con-controlli-interforze","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lotta-al-degrado-e-sicurezza-urbana-nuovo-blitz-allautostazione-di-cosenza-con-controlli-interforze\/","title":{"rendered":"Lotta al degrado e sicurezza urbana. Nuovo blitz all\u2019Autostazione di Cosenza con controlli interforze"},"content":{"rendered":"<p>COSENZA \u2013 Continuano senza sosta i controlli delle forze dell\u2019ordine in citt\u00e0, con interventi per combattere <strong>degrado urbano e microcriminalit\u00e0<\/strong> che da tempo interessano <strong>l\u2019Autostazione di Cosenza<\/strong>, nodo nevralgico per i collegamenti provinciali, regionali e interregionali e le zone circostanti. Come pi\u00f9 volte scritto ed evidenziato, l\u2019<a href=\"https:\/\/quicosenza.it\/news\/tensione-allautostazione-di-cosenza-litigio-finisce-in-una-violenta-aggressione-un-ferito-e-un-fermo\/\" target=\"_blank\" rel=\"noopener\">area<\/a> \u00e8 finita al centro di segnalazioni e denunce da parte di cittadini, commercianti e viaggiatori, stanchi di assistere quotidianamente a <strong>episodi di risse, bivacchi, spaccio e presenza di persone in evidente stato di alterazione fisica e psichica<\/strong>.\u00a0Per molti, a<strong>nche attendere un autobus in pieno giorno \u00e8 diventato un rischio<\/strong> con i pendolari costretti a convivere con situazioni di degrado che hanno trasformato l\u2019autostazione in una zona percepita come pericolosa, soprattutto nelle ore serali.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-275059 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/quicosenza.it\/news\/lotta-al-degrado-e-sicurezza-urbana-nuovo-blitz-allautostazione-di-cosenza-con-controlli-interforze\/autostazione-controlli2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"197\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli2-300x197.jpg\" class=\"attachment-medium size-medium\" alt=\"Autostazione Controlli petizione\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli2-300x197.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli2-768x504.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli2.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/quicosenza.it\/news\/lotta-al-degrado-e-sicurezza-urbana-nuovo-blitz-allautostazione-di-cosenza-con-controlli-interforze\/autostazione-controlli3\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"191\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli3-300x191.jpg\" class=\"attachment-medium size-medium\" alt=\"autostazione Cosenza aggressioni\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli3-300x191.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli3-768x490.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Autostazione-Controlli3.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<h3>Autostazione di Cosenza raffica di controlli<\/h3>\n<p>Tra l&#8217;orda di pranzo ed primo pomeriggio di oggi, la <strong>Questura di Cosenza<\/strong> ha coordinato un nuovo <strong>blitz interforze<\/strong>. In azione equipaggi della <strong>Squadra Volanti<\/strong> e del <strong>Reparto Prevenzione Crimine<\/strong> della Polizia di Stato, militari del <strong>Comando Provinciale dei Carabinieri<\/strong> e unit\u00e0 operative della <strong>Guardia di Finanza<\/strong>.\u00a0L\u2019intervento ha interessato l\u2019intera area con il piazzale delle Autolinee, <strong>le corsie dei bus e le vie limitrofe<\/strong> del centro cittadino, con presidi di controllo effettuati con mezzi dal personale, con verifiche<strong> anche su auto e mezzi in transito<\/strong>, identificazioni e un\u2019attenta attivit\u00e0 di monitoraggio per individuare eventuali <strong>stranieri irregolari<\/strong> sul territorio nazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controlli di polizia, carabinieri e guardia di finanza. Obiettivo \u00e8 restituire decoro e sicurezza a un\u2019area che da tempo rappresenta una criticit\u00e0 per la citt\u00e0 di Cosenza<\/p>\n","protected":false},"author":55,"featured_media":275060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-275059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=275059"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/275060"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=275059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=275059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=275059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}