{"id":275167,"date":"2025-11-09T17:38:01","date_gmt":"2025-11-09T16:38:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=275167"},"modified":"2025-11-10T07:13:52","modified_gmt":"2025-11-10T06:13:52","slug":"cosenza-spari-per-strada-e-un-violento-pestaggio-caruso-atti-vili-e-ignobili-la-citta-non-li-merita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-spari-per-strada-e-un-violento-pestaggio-caruso-atti-vili-e-ignobili-la-citta-non-li-merita\/","title":{"rendered":"Cosenza: spari per strada e un violento pestaggio, Caruso \u00abatti vili e ignobili, la citt\u00e0 non li merita\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Il sindaco di Cosenza Franz Caruso condanna con decisione i <strong>gravi episodi di violenza<\/strong> e delinquenza avvenuti nelle ultime ore in citt\u00e0, tra cui gli spari nei pressi dell\u2019<a href=\"https:\/\/quicosenza.it\/news\/cosenza-paura-allautostazione-spari-a-bordo-di-uno-scooter-caccia-a-due-uomini\/\">autostazione<\/a> e una rissa notturna culminata con il <a href=\"https:\/\/quicosenza.it\/news\/cosenza-violento-pestaggio-nella-notte-nei-pressi-di-un-bar-giovane-trasferito-in-codice-rosso-in-ospedale\/\">violento pestaggio<\/a> di un giovane, trasportato in codice rosso al Pronto Soccorso cittadino.\u00a0\u201cCondanno con la massima fermezza i gravi episodi di violenza e delinquenza che si sono verificati nelle ultime ore nella nostra citt\u00e0\u201d, ha dichiarato il primo cittadino esprimendo piena fiducia nel lavoro delle forze dell\u2019ordine che dovranno accertare le responsabilit\u00e0 dei fatti.<\/p>\n<p>\u201cNon spetta a me entrare nel merito delle dinamiche e delle responsabilit\u00e0 di quanto accaduto \u2013 ha proseguito Caruso \u2013 saranno le forze dell\u2019ordine, come sempre, a svolgere le indagini necessarie per accertare i fatti e individuare i responsabili. Tuttavia, non posso che ribadire la mia ferma <strong>condanna per questi atti vili e ignobili<\/strong>, <strong>espressione di un\u2019aggressivit\u00e0 e di una prepotenza che non appartengono al sentire comune della nostra comunit\u00e0\u201d.<\/strong><\/p>\n<h3>&#8220;A Cosenza prevalga la pace sociale&#8221;<\/h3>\n<p>Il sindaco ha ricordato come <strong>Cosenza<\/strong>, pur <strong>non essendo immune dai fenomeni di microcriminalit\u00e0<\/strong> che colpiscono i centri urbani, abbia sempre saputo distinguersi per il clima di civile convivenza.\u00a0\u201cCosenza ha saputo distinguersi negli anni per un clima di civile convivenza, che dobbiamo continuare a preservare con orgoglio. \u00c8 fondamentale che nella nostra citt\u00e0 prevalgano sempre la pace sociale, il rispetto reciproco e la sicurezza di tutti i cittadini, bandendo ogni forma di violenza, sopraffazione e incivilt\u00e0\u201d. Caruso ha poi espresso l\u2019auspicio che i<strong> fatti della notte, ovvero la violenta aggressione nei pressi del Top Flight, restino un episodio isolato<\/strong>, annunciando la volont\u00e0 di coinvolgere la Prefettura per rafforzare ulteriormente la sicurezza sul territorio.<\/p>\n<p>\u201cMi auguro sinceramente che quanto accaduto nella notte resti un episodio isolato e non abbia a ripetersi. A tal fine, chieder\u00f2 un incontro al signor Prefetto di Cosenza per valutare insieme l\u2019opportunit\u00e0 di intensificare i controlli, pur riconoscendo l\u2019impegno costante e l\u2019efficacia del lavoro svolto quotidianamente dalle nostre forze dell\u2019ordine sull\u2019intero territorio cittadino e, con particolare riferimento, nella zona <strong>dell\u2019autostazione<\/strong>\u201d. Caruso ha ricordato che <strong>proprio in quell\u2019area \u00e8 stata rafforzata la sorveglianza con posti di blocco interforze<\/strong>, per contrastare la criminalit\u00e0 e garantire maggiore sicurezza ai cittadini. \u201c\u00c8 solo attraverso la collaborazione tra istituzioni, cittadini e forze dell\u2019ordine che potremo continuare a garantire alla nostra citt\u00e0 il clima di serenit\u00e0, sicurezza e fiducia che merita\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo gli spari nei pressi dell\u2019autostazione e la rissa notturna che ha causato un ferito grave, il sindaco interviene con fermezza: \u201cCosenza \u00e8 una citt\u00e0 civile. Chieder\u00f2 al Prefetto di intensificare i controlli\u201d<\/p>\n","protected":false},"author":42,"featured_media":275169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-275167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=275167"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/275169"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=275167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=275167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=275167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}