{"id":27540,"date":"2013-11-15T06:30:56","date_gmt":"2013-11-15T05:30:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27540"},"modified":"2023-01-17T13:25:00","modified_gmt":"2023-01-17T12:25:00","slug":"11428-arrestato-il-boss-ed-ex-collaboratore-di-giustizia-antonino-lo-giudice","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11428-arrestato-il-boss-ed-ex-collaboratore-di-giustizia-antonino-lo-giudice\/","title":{"rendered":"Arrestato l&#8217;ex boss e collaboratore di giustizia Antonino Lo Giudice"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Era fuggito il 3 giugno scorso dagli arresti domiciliari.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Al momeno dell&#8217;arresto Lo giudice era insieme alla moglie e si nascondeva in un appartamento della periferia di Reggio Calabria. Quando i poliziotti hanno fatto irruzione nella casa, sfondando la porta, Lo Giudice non ha accennato alla minima reazione e si \u00e8 lasciato ammanettare senza opporre resistenza.&nbsp;L&#8217;ex boss e collaboratore di giustizia si era accusato di alcuni attentati oltre a quello al procuratore Salvatore Di Landro ed era stato condannato a 6 anni e 4 mesi per la stagione delle bombe e per le intimidazioni ai magistrati di Reggio Calabria nel 2010, tra cui anche il procuratore Giuseppe Pignatone. Il pentito della &#8216;ndrangheta Antonino Lo Giudice era scomparso dalla localit\u00e0 protetta dove si trovava agli arresti domiciliari e prima del suo allontanamento aveva fatto recapitare a due avvocati reggini un memoriale, nel quale ritrattava tutte le sue dichiarazioni sostenendo che la sua collaborazione con la giustizia era dovuta a pressioni da parte di alcuni magistrati di Reggio.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Nino <strong>Lo Giudice<\/strong>, nelle dichiarazioni, che poi ha ritrattato, fatte ai magistrati della Dda di Reggio Calabria all&#8217;epoca in cui l&#8217;ufficio era diretto da Giuseppe Pignatone, attuale Procuratore della Repubblica di Roma, <strong>si era autoaccusato<\/strong> di <strong>tre attentati<\/strong> compiuti nel 2010. Il primo fu quello compiuto contro la Procura generale di Reggio Calabria, davanti al portone della quale fu fatto esplodere un ordigno. Il secondo, pochi giorni dopo, fu l&#8217;attentato incendiario contro il portone dell&#8217;edificio in cui abita il Procuratore generale di Reggio Calabria, Salvatore Di Landro. La terza intimidazione, infine, fu quella diretta contro lo stesso procuratore Pignatone: davanti agli uffici della Dda fu lasciato un bazooka, la cui presenza fu segnalata con una telefonata anonima fatta da un telefono pubblico alla Polizia. Lo Giudice, dopo il suo pentimento, spieg\u00f2 che quegli attentati rappresentavano una strategia della &#8216;ndrangheta per generare tensione contro la magistratura di Reggio Calabria.<\/p>\n<p>&nbsp;<\/p>\n<p>Il <strong>commento<\/strong> del <strong>procuratore<\/strong> della Repubblica di Reggio Calabria,<strong> Federico Cafiero de Raho<\/strong>: &#8220;E&#8217; l&#8217;ennesima operazione, forse la pi\u00f9 significativa, che viene fatta nella citt\u00e0 di Reggio Calabria e che dimostra che lo Stato \u00e8 presente e non \u00e8 inquinato, come \u00e8 stato detto quando Lo Giudice si \u00e8 allontanato. Ancora una volta la professionalit\u00e0 della Polizia di Stato e dei magistrati della Dda hanno consentito di cancellare le illazioni che in questi mesi sono state ripetutamente diffuse. Lo Giudice verr\u00e0 interrogato e verr\u00e0 chiarito ogni aspetto del suo comportamento&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Era fuggito il 3 giugno scorso dagli arresti domiciliari.<\/p>\n","protected":false},"author":19,"featured_media":27541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-27540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27540"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27541"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}