{"id":27554,"date":"2013-11-15T10:13:58","date_gmt":"2013-11-15T09:13:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27554"},"modified":"2023-01-17T13:25:00","modified_gmt":"2023-01-17T12:25:00","slug":"11435-violazione-di-norme-ambientali-sette-denunce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11435-violazione-di-norme-ambientali-sette-denunce\/","title":{"rendered":"Violazione di norme ambientali, sette denunce"},"content":{"rendered":"<p>CATANZARO &#8211; Intensa attivit\u00e0 dei carabinieri del Nucleo operativo ecologico di Catanzaro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I militari hanno eseguito numerosi controlli durante i quali sono stati effettuati sequestri e sono state denunciate sette persone per violazione delle norme sull&#8217;ambiente. A Catanzaro \u00e8 stata sequestrata un&#8217;area di 4mila metri quadrati in uso alla societ\u00e0 &#8220;Aimeri Ambiente&#8221; per lo stoccaggio di rifiuti pericolosi e non, proveniente dalla raccolta urbana all&#8217;interno di cassoni posti nell&#8217;area adibita esclusivamente a parcheggio. Sono stati poi sequestrati un capannone, un rimorchio per motrice e mille quintali di pneumatici di propriet\u00e0 di una ditta che non aveva l&#8217;autorizzazione per la gestione, trattamento e stoccaggio di rifiuti speciali non pericolosi. E&#8217; stato sequestrato anche un impianto di lavorazione di materiale inerte perch\u00e8 privo dell&#8217;autorizzazione allo scarico di reflui industriali. Il valore complessivo dei beni sequestrati \u00e8 di circa 3 milioni di euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Intensa attivit\u00e0 dei carabinieri del Nucleo operativo ecologico di Catanzaro.<\/p>\n","protected":false},"author":19,"featured_media":27555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-27554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27554"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27555"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}