{"id":27562,"date":"2013-11-15T14:55:30","date_gmt":"2013-11-15T13:55:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27562"},"modified":"2023-01-17T13:25:00","modified_gmt":"2023-01-17T12:25:00","slug":"11439-maltempo-frana-impedisce-conferimento-rifiuti-alla-discarica-di-pianopoli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11439-maltempo-frana-impedisce-conferimento-rifiuti-alla-discarica-di-pianopoli\/","title":{"rendered":"Maltempo, frana impedisce conferimento rifiuti alla discarica di Pianopoli"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; Nuovi disagi a Lamezia per la raccolta dei rifiuti a causa di una frana che si \u00e8 verificata nella discarica di Pianopoli.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Da questa mattina infatti, l&#8217;impianto di selezione della Daneco nell&#8217;area industriale lametina non accetta il conferimento in quanto la discarica, gestita dalla stessa societ\u00e0 privata, non \u00e8 in grado di ricevere i rifiuti trattati a causa di una frana che ne impedisce il regolare esercizio. Una chiusura che non ha consentito ai mezzi della Lamezia Multiservizi, carichi di rifiuti, di conferire nell&#8217;impianto. Per questo, riferisce la stessa societa&#8217; che gestisce la raccolta dei rifiuti in citta&#8217;, &#8220;attualmente sono impossibilitati a riprendere la normale turnazione in citt\u00e0; l&#8217;indeterminatezza della situazione, che purtroppo permane ancora in queste ore, non ci consente di poter prevedere quando ci sar\u00e0 consentito di tornare ad assicurare con regolarit\u00e0 quotidiana il servizio visto che i nostri mezzi colmi di rifiuti sono fermi in attesa di poter scaricare e riprendere il lavoro in citt\u00e0. Sulla base delle informazioni in nostro possesso la situazione non dovrebbe tornare a normalizzarsi prima di lunedi&#8217; prossimo 18 novembre&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME &#8211; Nuovi disagi a Lamezia per la raccolta dei rifiuti a causa di una frana che si \u00e8 verificata nella discarica di Pianopoli.<\/p>\n","protected":false},"author":19,"featured_media":27563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-27562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27562"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27563"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}