{"id":27566,"date":"2013-11-16T07:40:25","date_gmt":"2013-11-16T06:40:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27566"},"modified":"2023-01-17T13:25:00","modified_gmt":"2023-01-17T12:25:00","slug":"11441-corigliano-la-piccola-giulia-montera-tra-le-braccia-di-papa-francesco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11441-corigliano-la-piccola-giulia-montera-tra-le-braccia-di-papa-francesco\/","title":{"rendered":"Corigliano: La piccola Giulia Montera tra le braccia di Papa Francesco"},"content":{"rendered":"<p>CORIGLIANO CALABRO (Cs) &#8211; Uno straordinario incontro tra il Pontefice e la piccola Giulia Montera, una bambina di Corigliano Calabro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Papa Francesco, nell\u2019Udienza Generale di mercoled\u00ec scorso, 13 novembre, presso la Sala Nervi del Vaticano, non si ferma alle benedizioni personali a tutti i bambini, ma va oltre. Otto minuti di dialogo, nel corso del quale il Papa ha tenuto tra le braccia la piccola Giulia. E poi alla conclusione Papa Francesco ha voluto i numeri di telefono ed ha chiesto di essere informato in modo dettagliato su Giulia. E poi la consegna del logo dell\u2019associazione \u201cUna lotta per la Vita\u201d e della brochure del film \u201cGiulia e le ali rubate, Giulia Montera una vita spezzata\u201d. Gabriele Montera, presidente della suddetta associazione, ha chiesto al Papa di intercedere per Giulia e per quei bambini come lei e di pregare anche affinch\u00e9 Giulia ottenga giustizia.<\/p>\n<p>&nbsp;<\/p>\n<p>Il padre della bambina infatti, ha avviato un procedimento penale per \u201cmalasanit\u00e0\u201d ed un mese fa ha ottenuto la prima vittoria, ossia il rigetto della proposta di archiviazione. Gabriele Montera, ha anche invitato a Papa Francesco per l\u2019apertura, prevista nel 2015, del Centro neurologico a carattere riabilitativo e scientifico denominato appunto \u201cCentro Giulia\u201d, che rappresenta la speranza di far lavorare le grandi menti che hanno lasciato l\u2019Italia per operare in importanti realt\u00e0 americane, canadesi ed italiane in Italia, e nello specifico in Calabria o in Sicilia (su queste due location si sceglier\u00e0 il luogo dove far nascere il Centro). Ora Giulia \u00e8 ancora a Roma, dopo il giorno di festa si \u00e8 ritornati alla realt\u00e0 e si sono aperte, com\u2019\u00e8 ormai consuetudine, le porte dell\u2019ospedale pediatrico \u201cBambin Ges\u00f9\u201d, ma questa volta presso il distaccamento di Palidoro. Tra i tanti problemi che affliggono la piccola Giulia, si rende infatti necessario intervenire al pi\u00f9 presto sulla colonna vertebrale ormai curva a causa della postura. Giulia, a seguito di un danno cerebrale, non si muove, \u00e8 immobile sempre da uno stesso lato. Adesso c\u2019\u00e8 un quarto intervento che aspetta Giulia, non facile viste le sue condizioni generali di salute, ed \u00e8 per questo che una equipe specifica di ortopedici, specialisti neurovertebrali, neurologi, broncopneumologi e cardiologi in queste ore sta valutando attentamente il caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO CALABRO (Cs) &#8211; Uno straordinario incontro tra il Pontefice e la piccola Giulia Montera, una bambina di Corigliano Calabro.<\/p>\n","protected":false},"author":19,"featured_media":27567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-27566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27566"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27567"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}