{"id":275723,"date":"2025-11-15T19:00:31","date_gmt":"2025-11-15T18:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=275723"},"modified":"2025-11-17T13:59:11","modified_gmt":"2025-11-17T12:59:11","slug":"centro-storico-senzacqua-sorical-dispersione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/centro-storico-senzacqua-sorical-dispersione\/","title":{"rendered":"Centro storico senz\u2019acqua. Sorical: \u201cdispersione in tubature vecchie 110 anni e allacci abusivi, il Comune sa da luglio\u201d"},"content":{"rendered":"<p data-start=\"158\" data-end=\"598\">COSENZA &#8211; Ieri pomeriggio la <strong>spontanea,<\/strong> ma decisa, <a href=\"https:\/\/quicosenza.it\/news\/da-5-giorni-senza-acqua-esplode-la-protesta-dei-cittadini-strade-bloccate-nel-centro-storico-di-cosenza\/\" target=\"_blank\" rel=\"noopener\">protesta<\/a><strong> dei cittadini<\/strong> nel centro storico di Cosenza, dove alcuni <strong>residenti del quartiere Massa e Spirito Santo<\/strong>, esasperati per la cronica mancanza di acqua, diventata vera e propria emergenza negli ultimi sette giorni, <strong>sono scesi in strada<\/strong>. Alcuni <strong>hanno bloccato alla meno peggio le strade d\u2019accesso al centro storico,<\/strong> paralizzando il traffico, per protestare contro l\u2019emergenza idrica ritenuta insopportabile.<\/p>\n<p>Sul posto sono intervenuti gli agenti della Polizia Municipale e pattuglie della Polizia di Stato, per monitorare la situazione e garantire la sicurezza. Ma la tensione resta alta<strong>: la crisi idrica colpisce l\u2019intero centro storico, in particolare nel rione Massa, Gergeri, Colle Triglio e Paparelle<\/strong>. Non va meglio nella parte sinistra del Crati, dove Portapiana e Spirito Santo vivono da tempo la stessa emergenza quotidiana. <strong>E cos\u00ec altre zone della citt\u00e0 di Cosenza <\/strong>dove dai rubinetti l\u2019acqua scorre meno di due ore al giorno.<\/p>\n<h3 data-start=\"1044\" data-end=\"1164\"><strong data-start=\"1048\" data-end=\"1164\">Sorical: \u201csegnalazioni al Comune di Cosenza da luglio\u201d<\/strong><\/h3>\n<p data-start=\"1166\" data-end=\"1614\">Ma tornando a quanto accaduto ieri nel centro storico, contattata dalla nostra redazione, <strong>Sorical ricostruisce una situazione ben pi\u00f9 complessa<\/strong> in quella area della citt\u00e0, acuita sicuramente dalla grave siccit\u00e0. La societ\u00e0 ricorda che la problematica della<strong> mancanza d\u2019acqua nella zona a Sud della citt\u00e0<\/strong>, in particolare quella servita dallo schema del Bufalo, \u00e8 stata gi\u00e0 da tempo <strong>segnalata al Comune di Cosenza<\/strong>. Alla base delle criticit\u00e0 &#8211; spiega il Gestore unico del servizio idrico &#8211; non ci sarebbe solo <strong>il drastico calo delle portate degli acquedotti regionali<\/strong>, ma anche criticit\u00e0 <strong>afferenti al sistema comunale di distribuzione <\/strong>(le condotte) oltre a possibili <strong>furti di acqua per allacci abusivi<\/strong>.<\/p>\n<p data-start=\"1616\" data-end=\"1943\">La prima interlocuzione con Palazzo dei Bruzi risale a luglio, quando, dopo le numerose segnalazioni che arrivavano gi\u00e0 da giugno, si svolse <strong>una riunione presso l\u2019ufficio tecnico comunale a Palazzo dei Bruzi<\/strong>. In quell\u2019occasione i tecnici Sorical avevano messo in evidenza<strong> i consumi anomali nei punti di consegna del \u201cpartitore San Lorenzo\u201d e di \u201cCozzo Badessa\u201d<\/strong>.<\/p>\n<h3 data-start=\"1616\" data-end=\"1943\">&#8220;Dispersioni dell&#8217;acqua in tubature vecchie di oltre un secolo&#8221;<\/h3>\n<p data-start=\"1945\" data-end=\"2403\">Secondo la societ\u00e0, l<strong>\u2019<\/strong>erogazione da parte degli acquedotti regionali risultava<strong> stabile e in linea <\/strong>sia con la <strong>media semestrale del 2025<\/strong>, sia <strong>con i valori registrati nello stesso periodo dell\u2019anno precedente<\/strong>. A cambiare, invece, sarebbero stati <strong>i consumi rilevati nelle reti comunali<\/strong>: proprio nel centro storico di Cosenza sono presenti <strong>tubature vecchie di oltre un secolo<\/strong> (alcune risalenti anche al 1905) e<strong> interessate da perdite <\/strong>oltre che da una serie di possibili <strong>allacci abusivi<\/strong> che sottrarrebbero acqua preziosa alla gi\u00e0 critica distribuzione ordinaria.<\/p>\n<p data-start=\"2405\" data-end=\"2796\">Il Comune, da parte sua, <strong>aveva contestato discrepanze significative<\/strong> tra i dati forniti da Sorical e le quantit\u00e0 registrate nelle proprie misurazioni. Ma Sorical aveva ribadito che <strong>tali differenze riguardavano tratte comunali \u201ca valle\u201d,<\/strong> spesso lunghe chilometri e &#8220;<strong>s<\/strong><em><strong>oggette a prelievi non autorizzati e a un uso improprio dell\u2019acqua&#8221;<\/strong><\/em>. Tratte che &#8211; evidenza il gestore &#8211; sono di <strong><em>&#8220;esclusiva responsabilit\u00e0 dell\u2019ente comunale&#8221;<\/em><\/strong>.<\/p>\n<h3 data-start=\"2405\" data-end=\"2796\">Dal Bufalo a Mussano:<\/h3>\n<p data-start=\"2405\" data-end=\"2796\">Ma le stesse problematiche sarebbero state evidenziate al Comune da <a href=\"http:\/\/www.sorical.it\" target=\"_blank\" rel=\"noopener\">Sorical<\/a> anche al<strong> serbatoio \u201cMussano\u201d,<\/strong> sito nella parte opposta della citt\u00e0 (alle spalle di via degli Stadi) , dove per Sorical erano presenti anche il quel caso <strong>discrepanze importanti<\/strong>, <strong>nell\u2019ordine del 15%-20%<\/strong> e ascrivibili all\u2019impiego di tale tratta &#8220;quale linea distributrice piuttosto che di semplice avvicinamento alle vasche&#8221;. Alle continue richieste di aumento dell&#8217;erogazione idrica da parte di Palazzo dei Bruzi, Sorical aveva replicato chiedendo al Comune di agire e<strong> intervenendo sulle tratte di condotta<\/strong> e non su &#8220;<em>richieste di aumenti che risulterebbero a danno di altri Comuni collegati al medesimo schema<\/em>&#8220;.<\/p>\n<h3 data-start=\"2798\" data-end=\"2860\"><strong data-start=\"2802\" data-end=\"2860\">Acqua e crisi idrica anche a Rende<\/strong><\/h3>\n<p data-start=\"2862\" data-end=\"3229\">Alla crisi di Cosenza si aggiunge <strong>quella di <\/strong><a href=\"https:\/\/quicosenza.it\/news\/rende-emergenza-idrica-senza-fine-quartieri-a-secco-da-giorni-la-rabbia-dei-cittadini-adesso-basta\/\" target=\"_blank\" rel=\"noopener\">Rende<\/a>, dove <strong>in diversi quartieri l\u2019erogazione \u00e8 ridotta al minimo da quasi una settimana<\/strong>. In alcuni quartieri da quasi una settimana l&#8217;erogazione \u00e8 al minimo, mentre d<strong>isagi enormi si registrano anche a Saporito<\/strong> e <strong>persino a Roges.<\/strong> Ad esempio Sorical \u00e8 dovuta intervenire con<strong> chiusure a Commenda per permettere di distribuire meglio l&#8217;acqua anche nella zona a Nord di Rende<\/strong>, cos\u00ec come <strong>nella zona del Centro Commerciale Metropolis<\/strong>.<\/p>\n<h3 data-start=\"2862\" data-end=\"3229\">Un cane che si morde la coda<\/h3>\n<p data-start=\"2862\" data-end=\"3229\">Proprio nell&#8217;area commerciale tutta <strong>una serie di attivit\u00e0 commerciali, con cisterne, hanno finito per captate quella poca acqua erogata<\/strong>, lasciando a secco molti palazzi. Ancora, \u00e8 del tutto evidente, che con il calo drastico di erogazione da tutti gli acquedotti, le chiusure dei serbatoio programmate da Sorical per una migliore redistribuzione in tutta l&#8217;area non funziona. E non aiuta <strong>la presenza di una serie non di poco conto di cassoni, autoclavi e cisterne, pi\u00f9 o meno grandi.<\/strong><\/p>\n<p data-start=\"2862\" data-end=\"3229\">L&#8217;erogazione idrica, di per s\u00e9 pi\u00f9 bassa rispetto al passato proprio per la crisi idrica, fa si che <strong>quando l&#8217;acqua viene erogata finisce quasi subito<\/strong> proprio perch\u00e8 va a<strong> riempire un numero enorme di cisterne e cassoni<\/strong>. E cos\u00ec, chi ne \u00e8 sprovvisto e <strong>le abitazioni ai piani pi\u00f9 alti dei palazzi<\/strong> restano a secco quasi tutto il giorno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorical punta il dito su allacci abusivi e perdite delle vecchie reti comunali, alcune datate ai primi del 900. Intanto l\u2019emergenza acqua colpisce anche Rende con interi quartieri ormai a secco<\/p>\n","protected":false},"author":23,"featured_media":275727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-275723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=275723"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/275727"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=275723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=275723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=275723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}