{"id":275931,"date":"2025-11-23T13:30:54","date_gmt":"2025-11-23T12:30:54","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=275931"},"modified":"2025-11-23T12:42:20","modified_gmt":"2025-11-23T11:42:20","slug":"cosenza-cardiovascolare-defibrillatore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-cardiovascolare-defibrillatore\/","title":{"rendered":"Cosenza, convegno su prevenzione cardiovascolare e donazione organi: in dono un defibrillatore"},"content":{"rendered":"<p>COSENZA &#8211; Cosenza si prepara a vivere un importante momento di prevenzione e sensibilizzazione. Marted\u00ec prossimo, 25 novembre, alle ore 17.30, presso il <strong>Centro Polifunzionale del Comitato Spontaneo Piazza Spirito Santo<\/strong>, si terr\u00e0 un <strong>convegno<\/strong> dedicato alla prevenzione delle malattie cardiovascolari e alla donazione degli organi. L\u2019evento rappresenta un\u2019occasione per discutere di salute pubblica, prevenzione e solidariet\u00e0, con la partecipazione di esperti e istituzioni locali. Durante l\u2019incontro, la <strong>Fondazione <a href=\"https:\/\/www.fondazionecarical.it\/\" rel=\"noopener\">Carical<\/a> doner\u00e0 al Comitato un<\/strong> <strong>defibrillatore<\/strong>, strumento fondamentale per garantire la sicurezza della comunit\u00e0. Il Dr. Piero Belmonte di PNDiagnostici illustrer\u00e0 le funzioni e l\u2019utilizzo del dispositivo, sottolineando la sua importanza per la tutela della vita.<\/p>\n<h3>Prevenzione e donazione<\/h3>\n<p>Saranno presenti il Direttore Generale della Fondazione Carical, Dott. Carlo Cannataro, e il Sindaco di Cosenza, Avv. Franz Caruso, che porteranno i loro saluti istituzionali. La Dott.ssa Marianna Dodaro, responsabile comunicazione del Comitato, presieder\u00e0 l\u2019iniziativa, con interventi di rilievo tra cui il Dott. Gianni Romeo (Presidente Coop. Sociale La Terra), il Dott. Francesco Greco (Direttore UOC Cardiologia Interventistica A.O. Cosenza), la Dott.ssa Rachele Celebre (Presidente CSV Cosenza), il Dott. Roberto Caporale (Fondazione per il tuo cuore &#8211; HCF ONLUS) e Giuseppe Muto (Presidente Provinciale e Consigliere Nazionale AIDO).<\/p>\n<p>Il convegno prevede anche <strong>testimonianze di persone trapiantate e cittadini<\/strong> in lista d\u2019attesa, oltre a un collegamento in diretta con la Dott.ssa Chiara Nalli, dirigente medico del Centro di Riferimento Trapianti dell\u2019Ospedale di Udine. Un evento che unisce informazione, prevenzione e comunit\u00e0, confermando come <strong>la salute del cuore e la donazione degli organi<\/strong> siano un impegno condiviso: un vero cuore che batte insieme per la vita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un incontro dedicato alla salute, alla prevenzione e alla solidariet\u00e0 con esperti, istituzioni e testimonianze di trapiantati. L&#8217;iniziativa al Centro Polifunzionale di Piazza Spirito Santo<\/p>\n","protected":false},"author":42,"featured_media":275934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-275931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=275931"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/275931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/275934"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=275931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=275931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=275931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}