{"id":27594,"date":"2013-11-16T10:15:10","date_gmt":"2013-11-16T09:15:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27594"},"modified":"2023-01-17T13:25:02","modified_gmt":"2023-01-17T12:25:02","slug":"11455-maltempo-a-corigliano-abitanti-di-un-palazzo-soccorsi-con-una-barca","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11455-maltempo-a-corigliano-abitanti-di-un-palazzo-soccorsi-con-una-barca\/","title":{"rendered":"Maltempo, a Corigliano abitanti di un palazzo soccorsi con una barca"},"content":{"rendered":"<p>CORIGLIANO CALABRO (CS) &#8211; Le piogge forti che si sono abbattuta anche nella notte hanno provocato nuovi disagi, dopo quelli dei giorni scorsi, nella zona della Sibaritide.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Tanti i terreni allagati e numerosi gli interventi di Protezione civile e vigili del fuoco, anche se non si registrano problemi per le persone. Schiavonea, frazione marina di Corigliano Calabro, \u00e8 stata invasa dall&#8217;acqua e dal fango. Una palazzina \u00e8 rimasta isolata e alcuni bambini che vi abitano con le loro famiglie sono stati soccorsi da un giovane, che ha utilizzato la sua barca a remi per poter arrivare nell&#8217;edificio. Problemi anche a Rossano, in contrada Momena, dove l&#8217;acqua e il fango hanno bloccato alcune famiglie ai piani terreni delle loro abitazioni. Danni a mobili e suppellettili. Nella notte, inoltre, in diverse zone della citt\u00e0 \u00e8 mancata la corrente elettrica. Ieri il sindaco di Rossano, Giuseppe Antoniotti, aveva chiesto la dichiarazione dello stato di calamit\u00e0 naturale per i danni del maltempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO CALABRO (CS) &#8211; Le piogge forti che si sono abbattuta anche nella notte hanno provocato nuovi disagi, dopo quelli dei giorni scorsi, nella zona della Sibaritide.<\/p>\n","protected":false},"author":19,"featured_media":27595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-27594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27594"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27595"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}