{"id":276410,"date":"2025-11-23T07:30:48","date_gmt":"2025-11-23T06:30:48","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=276410"},"modified":"2025-11-23T07:35:33","modified_gmt":"2025-11-23T06:35:33","slug":"volo-salva-vita-bimbo-un-anno-calabria-roma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/volo-salva-vita-bimbo-un-anno-calabria-roma\/","title":{"rendered":"Volo salva vita per bimbo di 1 anno dalla Calabria a Roma"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; Nella serata di ieri un<strong> bambino di 1 anno<\/strong>, in condizioni di salute molto gravi, \u00e8 stato trasferito d&#8217;urgenza <strong>da Lamezia Terme a Roma Ciampino<\/strong> grazie ad un <strong>volo salva vita<\/strong>. Il piccolo ha viaggiato a bordo\u00a0di un <strong>velivolo Gulfstream G-650A del 31\u00b0 Stormo di Ciampino.<\/strong><\/p>\n<p>Il volo sanitario \u00e8 stato attivato dalla Sala Situazioni di Vertice dello Stato Maggiore dell&#8217;Aeronautica Militare dopo la richiesta arrivata dalla Prefettura di Catanzaro. Dopo l&#8217;arrivo dell&#8217;aeromobile all&#8217;aeroporto di Ciampino, il piccolo paziente \u00e8 stato affidato al personale sanitario che lo ha condotto all&#8217;<a href=\"https:\/\/www.ospedalebambinogesu.it\/\" target=\"_blank\" rel=\"noopener\"><strong>ospedale Bambino Ges\u00f9<\/strong><\/a> per il ricovero.\u00a0A bordo del velivolo erano presenti l&#8217;\u00e9quipe medica e la madre del bambino.<\/p>\n<h3>Volo salva vita, il ruolo dell&#8217;Aeronautica Militare<\/h3>\n<p>Come ha spiegato l\u2019Aeronautica Militare in una nota,\u00a0 il volo salva vita erogato ieri, cos\u00ec come accade per questo genere di attivit\u00e0, &#8220;\u00e8 stato <strong>autorizzato dalla Presidenza del Consiglio dei Ministri<\/strong> che gestisce e coordina le attivit\u00e0 della flotta dei velivoli di Stato. I Reparti di volo dell\u2019Aeronautica Militare sono a disposizione della collettivit\u00e0 24 ore al giorno, 365 giorni l\u2019anno, con mezzi ed equipaggi in grado di operare, anche in condizioni meteorologiche complesse. Assicurano il <strong>trasporto urgente<\/strong> non solo di<a href=\"https:\/\/quicosenza.it\/news\/uncz-attacco-dasma-e-poi-la-terapia-intensiva-volo-salva-vita-per-un-bimbo-dalla-calabria-a-genova\/\" target=\"_blank\" rel=\"noopener\"> persone in imminente pericolo di vita<\/a>, ma anche di <strong>organi, \u00e9quipe mediche o ambulanze&#8221;.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-185847 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita.jpg\" alt=\"volo salva vita\" width=\"537\" height=\"332\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/volo-salva-vita-356x220.jpg 356w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/p>\n<p>&#8220;Sono centinaia ogni anno le ore di volo &#8211; conclude la nota &#8211; effettuate per questo genere di interventi dagli aerei del 31\u00b0 Stormo di Ciampino, del 14\u00b0 Stormo di Pratica di Mare, della 46\u00aa Brigata Aerea di Pisa e dagli elicotteri del 15\u00b0 Stormo di Cervia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il volo sanitario \u00e8 stato attivato dalla Sala Situazioni di Vertice dello Stato Maggiore dell&#8217;Aeronautica Militare dopo la richiesta arrivata dalla Prefettura di Catanzaro <\/p>\n","protected":false},"author":90,"featured_media":192767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-276410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/276410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=276410"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/276410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/192767"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=276410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=276410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=276410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}