{"id":276777,"date":"2025-11-26T15:11:42","date_gmt":"2025-11-26T14:11:42","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=276777"},"modified":"2025-11-26T15:46:23","modified_gmt":"2025-11-26T14:46:23","slug":"pirossigeno-cosenza-futsal-preso-kevin-arrieta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/pirossigeno-cosenza-futsal-preso-kevin-arrieta\/","title":{"rendered":"La Pirossigeno Cosenza Futsal piazza il colpo Kevin Arrieta. Il classe 97, vicecampione del mondo, in rossoblu"},"content":{"rendered":"<p>COSENZA &#8211; La Pirossigeno Cosenza Futsal annuncia un acquisto di altissimo livello: il laterale argentino <strong>Kevin Nahuel Arrieta<\/strong> vestir\u00e0 la m<strong>aglia rossobl\u00f9 numero 24<\/strong>, portando con s\u00e9 un <strong>curriculum di primissimo piano<\/strong> e una carriera costellata di successi internazionali. Un innesto importantissimo per rafforzare una squadra che venerd\u00ec scorso \u00e8 tornata al<a href=\"https:\/\/quicosenza.it\/news\/futsal-serie-a-pirossigeno-cosenza-vittoria\/\" target=\"_blank\" rel=\"noopener\"> successo<\/a> con una epica remuntada<\/p>\n<h3><strong>Kevin Arrieta a Cosenza con un palmar\u00e8s da urlo<\/strong><\/h3>\n<p>Nato a Buenos Aires il 16 febbraio 1997, <strong>Arrieta ha iniziato la sua carriera nelle giovanili di 17 de Agosto e del Racing Club<\/strong>, vincendo gi\u00e0 da giovane il campionato sudamericano Under 20 con la maglia dell\u2019Argentina. Successivamente si \u00e8 trasferito nel Boca Juniors, conquistando immediatamente il titolo nazionale.<\/p>\n<p>Nel 2018\/2019 Kevin sbarca in Italia con la <strong>Feldi Eboli<\/strong>, stagione in cui si distingue per la sua prolificit\u00e0 in zona gol. Dopo un breve ritorno in patria al Barracas Central, la carriera di Arrieta raggiunge l\u2019apice in Kazakistan: con il <strong>Kairat Almaty<\/strong> vince il campionato nazionale e sfiora il titolo continentale, segnando anche nella finale di Champions League persa contro il Palma. Il <strong>talento albiceleste<\/strong> ha inoltre brillato ai mondiali, conquistando la <strong>medaglia d\u2019argento<\/strong> con l\u2019Argentina grazie a 7 reti in 7 partite, tra cui 2 decisive nella semifinale vinta 3-2 contro la Francia.<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/keviin_arrieta\/\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-276782\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Arrieta-sfoggia-la-maglia-rossoblu-foto-Michele-De-Marco.jpg\" alt=\"Arrieta sfoggia la maglia rossobl\u00f9 (foto Michele De Marco)\" width=\"574\" height=\"382\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Arrieta-sfoggia-la-maglia-rossoblu-foto-Michele-De-Marco.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Arrieta-sfoggia-la-maglia-rossoblu-foto-Michele-De-Marco-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Arrieta-sfoggia-la-maglia-rossoblu-foto-Michele-De-Marco-768x511.jpg 768w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><\/a><\/p>\n<h3><strong>Gaetano Piro &#8220;un altro campione alla Pirossigeno Cosenza Futsal&#8221;<\/strong><\/h3>\n<p>Ora Arrieta approda a Cosenza, pronto a esibirsi al <strong>PalaPirossigeno<\/strong> e nei palazzetti di tutta Italia con la maglia rossobl\u00f9. Il vice presidente del club, <strong>Gaetano Piro<\/strong>, ha espresso entusiasmo per l\u2019acquisizione:\u00a0<em>&#8220;<strong>Siamo estremamente felici e fieri di aver portato a Cosenza un altro campion<\/strong>e. Si tratta di un giocatore di caratura internazionale. Siamo orgogliosi di poterlo vedere in rossobl\u00f9 e avere un pezzo di Pirossigeno in albiceleste. Quando si \u00e8 presentata l&#8217;occasione di sferrare il colpo, ci siamo fatti trovare pronti. \u00c8 uno sforzo che abbiamo deciso di fare per regalare uno spettacolo sempre pi\u00f9 appassionante e innalzare la qualit\u00e0 del futsal da offrire ai nostri fantastici tifosi&#8221;!<\/em><\/p>\n<h2>Cosenza in scioltezza sul Marsala e ottavi di Coppa Divisione<\/h2>\n<p>Nel frattempo la\u00a0<strong>Pirossigeno Cosenza Futsal avanza nella Coppa della Divisione<\/strong> battendo il <strong>Marsala Futsal.<\/strong> Ci sono due categorie di differenza tra le squadre in campo sul parquet del palazzetto siciliano e si vedono tutte. Pronti, via e dopo appena 16 secondi\u00a0<strong>Marcelinho<\/strong>\u00a0sblocca il risultato ribadendo\u00a0<strong>in rete<\/strong>\u00a0una corta respinta di Cosenza sul sinistro di Marchio. Si fanno vedere i padroni di casa al terzo minuto con il bolide da distanza ravvicinata di Barroso disinnescato da Parisi.<\/p>\n<h3><strong>Pirossigeno Cosenza Futsal: Marcelinho mattatore<\/strong><\/h3>\n<p>Il Marsala \u00e8 nuovamente pericoloso al 5\u2032: la girata al volo di Tendero si stampa sulla traversa. Sul capovolgimento di fronte arriva il\u00a0<strong>raddoppio<\/strong>\u00a0dei <a href=\"https:\/\/www.pirossigenocosenza.it\/\" target=\"_blank\" rel=\"noopener\">lupi<\/a> firmato ancora da\u00a0<strong>Marcelinho<\/strong>\u00a0che fa cos\u00ec doppietta. Il\u00a0<strong>pivot brasiliano \u00e8 scatenato<\/strong>\u00a0e va a segno altre due volte a stretto giro di posta indirizzando di fatto la vittoria ospite. Al 15\u2032 colpisce\u00a0<strong>Marchio<\/strong>: il capitano si gira e sferra un tiro di precisione chirurgica che si insacca nell\u2019angolino basso. Prima dell\u2019intervallo c\u2019\u00e8 gloria anche per\u00a0<strong>Cambareri<\/strong>, che chiude una triangolazione perfetta con Marcelinho\u00a0<strong>insaccando<\/strong>\u00a0da pochi passi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-276793 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pirossigeno-Cosenza-Futsal.jpg\" alt=\"Pirossigeno Cosenza Futsal\" width=\"559\" height=\"330\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pirossigeno-Cosenza-Futsal.jpg 927w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pirossigeno-Cosenza-Futsal-300x177.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pirossigeno-Cosenza-Futsal-768x453.jpg 768w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/p>\n<p>Stesso copione nella ripresa.\u00a0<strong>Marcelinho<\/strong>\u00a0realizza un\u2019altra\u00a0<strong>rete capolavoro<\/strong>\u00a0scucchiaiando un pallone delizioso in fondo al sacco e raccogliendo gli\u00a0<strong>applausi<\/strong> convinti dello sportivissimo pubblico di casa. Gol della bandiera del Marsala realizzato da Barroso al 9&#8242;.<\/p>\n<p>Trascorrono pochi secondi e i rossobl\u00f9 (oggi in maglia verde)\u00a0<strong>ristabiliscono<\/strong>\u00a0le distanze con il diagonale potente ed estremamente preciso di Fantecele deviato in porta da\u00a0<strong>Cambareri<\/strong>, che firma la doppietta personale. La Pirossigeno a questo punto abbassa il ritmo e il risultato non cambia pi\u00f9.\u00a0<strong>1-8<\/strong>\u00a0il punteggio finale al Palazzetto dello Sport di Marsala e il quintetto di mister Paniccia stacca il pass per gli\u00a0<strong>ottavi<\/strong>\u00a0di Coppa della Divisione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pirossigeno Cosenza mette a segno un colpo da novanta! Il club rossobl\u00f9 si \u00e8 infatti assicurato le prestazioni del fuoriclasse argentino Kevin Nahuel Arrieta<\/p>\n","protected":false},"author":24,"featured_media":276781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-276777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/276777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=276777"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/276777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/276781"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=276777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=276777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=276777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}