{"id":276948,"date":"2025-11-28T12:30:41","date_gmt":"2025-11-28T11:30:41","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=276948"},"modified":"2025-11-28T12:35:06","modified_gmt":"2025-11-28T11:35:06","slug":"disordini-paolana-rossanese-13-indagati-procura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/disordini-paolana-rossanese-13-indagati-procura\/","title":{"rendered":"Disordini durante Paolana-Rossanese: 13 indagati per l\u2019incendio del pulmino e le violenze allo stadio"},"content":{"rendered":"<p>PAOLA (CS) &#8211; Per i <strong>violenti disordini<\/strong> avvenuti durante la partita <a href=\"https:\/\/quicosenza.it\/news\/paola-incendiato-un-furgoncino-dei-tifosi-della-rossanese\/\"><strong>Paolana-Rossanese<\/strong><\/a>, disputata lo scorso gennaio allo stadio comunale <strong>Eugenio Tarsitano<\/strong>, sono indagate 13 persone. Un incontro ad alto rischio che degener\u00f2 tra la fine del primo tempo e l\u2019inizio della ripresa, in una serie di episodi che hanno richiesto l&#8217;intervento massiccio delle forze dell\u2019ordine.<\/p>\n<h3>Disordini, dal lancio di oggetti all&#8217;incendio di un pulmino<\/h3>\n<p>Al centro dell\u2019inchiesta, <strong>l\u2019incendio del pulmino<\/strong> utilizzato dai <strong>tifosi della Rossanese<\/strong>, posteggiato all\u2019esterno dello stadio: uno degli episodi ritenuti pi\u00f9 gravi dell\u2019intero campionato di Eccellenza 2024-2025. Durante il match ci furono lanci di oggetti: seggiolini, fumogeni, pezzi della ceramica dei bagni e anche tentativi di aggressione tra tifoserie.<\/p>\n<p>Gli accertamenti sono stati eseguiti dalla Polizia del Commissariato di <a href=\"https:\/\/questure.poliziadistato.it\/it\/Cosenza\/articolo\/11405e5650903e951112930911\" rel=\"noopener\">Paola<\/a> e a seguito di rilievi sul posto e all\u2019analisi delle immagini registrate dalle telecamere esterne e dalle riprese effettuate all\u2019interno dell\u2019impianto sportivo sono stati individuati i soggetti indagati, provenienti <strong>da Paola, Rossano e Lamezia<\/strong>, ai quali vengono contestati il danneggiamento mediante incendio ma anche porto abusivo di mazze e bastoni in ferro e legno, uso e lancio di <strong>fumogeni<\/strong>, lancio di <strong>seggiolini<\/strong> e altri <strong>oggetti<\/strong> e l&#8217;utilizzo di passamontagna per non farsi riconoscere.<\/p>\n<p>La <strong>Procura di Paola<\/strong> dovrebbe ora procedere con la richiesta di rinvio a giudizio per le tredici persone coinvolte. Sono ancora in fase di valutazione invece, i provvedimenti di <strong>Daspo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019inchiesta aperta dopo i disordini dalla Procura di Paola ricostruisce quanto accaduto durante la partita di Eccellenza: tra le accuse danneggiamenti, aggressioni, uso di fumogeni e l\u2019incendio del mezzo dei tifosi ospiti<\/p>\n","protected":false},"author":42,"featured_media":276956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[],"class_list":["post-276948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/276948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=276948"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/276948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/276956"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=276948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=276948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=276948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}