{"id":27700,"date":"2013-11-19T10:36:33","date_gmt":"2013-11-19T09:36:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27700"},"modified":"2023-01-17T13:25:08","modified_gmt":"2023-01-17T12:25:08","slug":"11511-il-maltempo-flagella-la-calabria-danni-e-disagi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11511-il-maltempo-flagella-la-calabria-danni-e-disagi\/","title":{"rendered":"Il maltempo flagella la Calabria, danni e disagi"},"content":{"rendered":"<p>CATANZARO &#8211; Il violento nubifragio che si \u00e8 abbattuto su tutta la Calabria ha provocato ingenti danni e diversi disagi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Le zone maggiormente colpite sono quelle della costa ionica ed in particolare nel catanzarese, nel crotonese e nel vibonese. Sono numerosi gli allagamenti e le strade interrotte perch\u00e8 invase dal fango. In molti comuni le scuole sono rimaste chiuse. A Crotone, Catanzaro e Vibo Valentia sono centinaia le richieste di soccorso giunte ai vigili del fuoco. Soccorse anche persone bloccate in auto. Il nubifragio \u00e8 durato circa sei ore e sono caduti circa 145 millimetri di pioggia.&nbsp;<\/p>\n<p><span style=\"font-size: 12px; line-height: 1;\">&nbsp;<\/span><\/p>\n<p><strong>NEL CATANZARESE<\/strong> \u2013 A <strong>Taverna<\/strong> un muro \u00e8 crollato su una abitazione; per fortuna le persone che erano nella casa sono riuscite a mettersi in salvo in tempo. A Catanzaro, a causa della pioggia, ci sono difficolt\u00e0 negli spostamenti perch\u00e8 molte strade sono allagate. Il fiume Uria \u00e8 esondato provocando l&#8217;allagamento della statale 106 che \u00e8 stata invasa da fango e detriti. Alcuni tratti della statale al momento sono chiusi perch\u00e8 sono allagati. Sono bloccati anche alcuni tratti della <strong>statale 280 che collega Catanzaro con Lamezia Terme<\/strong>. Il traffico \u00e8 stato deviato verso altre strade interne. A Sellia Marina, un villaggio con 150 persone \u00e8 stato evacuato perch\u00e8 invaso dall&#8217;acqua a causa del violento nubifragio delle scorse ore. Lo <strong>straripamento del fiume Uria<\/strong> ha provocato anche di un altro villaggio che non risulta abitato. Sempre nella zona di<strong> Sellia Marina<\/strong> si sta cercando di mettere in sicurezza un ponte ferroviario gi\u00e0 da tempo inutilizzato che \u00e8 crollato. Nel quartiere <strong>Germaneto<\/strong> di Catanzaro una persona era rimasta bloccata a bordo della sua automobile che \u00e8 stata colpita da fango e detriti. La persona \u00e8 stata poi soccorsa dai vigili del fuoco. Numerose squadre di intervento stanno provvedendo anche a contattare persone disabili per trovare loro una sistemazione adeguata. Presso la Prefettura di Catanzaro \u00e8 stata istituita un\u2019unit\u00e0 di crisi che sta provvedendo a coordinare tutte le attivit\u00e0 di soccorso e di intervento. Infine, la chiesa della Madonna delle Grazie nel <strong>quartiere Cava a Catanzaro<\/strong> \u00e8 completamente allagata e tutti gli oggetti sacri e gli arredi sono stati danneggiati dall&#8217;acqua. I residenti del quartiere lamentano il fatto che da tre anni la zona \u00e8 costretta a subire danni dal maltempo. Stamane <strong>il sindaco di Catanzaro, Sergio Abramo<\/strong>, ha effettuato numerosi sopralluoghi nelle zone maggiormente colpite dal nubifragio. I quartieri che hanno subito pi\u00f9 danni sono quelli a sud della citt\u00e0, che sono stati invasi da fango e detriti. Molte strade sono allagate ed in alcuni quartieri si sono verificate delle frane.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>NEL VIBONESE<\/strong> &#8211; Il torrente <strong>Ancinale<\/strong>, \u00e8 esondato ed ha provocato allagamenti in alcune zone montane interessando in particolare i comuni di<strong> Serra San Bruno, Brognaturo, Spadola e Simbario<\/strong>. In alcuni casi l&#8217;acqua ha raggiunto i primi piani delle abitazioni. Sul posto stanno lavorando diverse squadre dei vigili del fuoco, che sono attualmente impegnate per far defluire l&#8217;acqua.<\/p>\n<p>&nbsp;<\/p>\n<p><strong> NEL CROTONESE &#8211;<\/strong> Sono centinaia di casi di allagamento, a causa del maltempo, nei comuni del crotonese, in particolare quelli della fascia ionica. Nei comuni di <strong>Cotronei, Cir\u00f2 Marina, Petilia Policastro e Mesoraca<\/strong> i sindaci hanno disposto la chiusura delle scuole. In provincia di Crotone i vigili del fuoco hanno dovuto fronteggiare oltre cento richieste di intervento da parte di persone che hanno subito danni alle abitazioni. Problemi anche al traffico; in particolare, alcuni tratti della statale 106 sono stati invasi da fango e detriti. Per fronteggiare i problemi sono a lavoro molte squadre dell&#8217;Anas. Anche la citt\u00e0 di Crotone \u00e8 stata colpita dal nubifragio, ma al momento non vengono segnalati particolari disagi.&nbsp;Il<strong> fiume Neto<\/strong> \u00e8 esondato nei pressi del comune di Rocca di Neto ed ha invaso la statale 106. L&#8217;esondazione ha provocato il completo allagamento della strada statale la cui carreggiata \u00e8 scomparsa inghiottita dall&#8217;acqua. Sul posto stanno giungendo i vigili del fuoco ed i volontari della protezione civile regionale. Anche nella zona di Strongoli, sempre nel crotonese, c&#8217;\u00e8 stata l&#8217;esondazione di torrenti. A Cir\u00f2 Marina l&#8217;acqua ha raggiunto l&#8217;altezza di un metro e ci sono abitazioni allagate fino al primo piano.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Disagi alla circolazione ferroviaria sulla linea jonica<\/strong> &#8211; La circolazione dei treni \u00e8 sospesa sulla linea Jonica tra Reggio Calabria e Sibari e tra Sibari e Soverato per allagamenti della sede ferroviaria in diversi punti della linea dalle 7.40 tra Squillace e Catanzaro Lido; dalle 8.30 tra Crotone e San Leonardo e dalle 10.15 tra Rossano e Crotone. I treni fanno capolinea a Soverato e Sibari e, laddove \u00e8 possibile la percorribilit\u00e0 delle strade, sono stati attivati autobus sostitutivi. Inoltre, tra Catanzaro Lido e Lamezia Terme la circolazione \u00e8 stata sospesa in via precauzionale tra le 8.40 e le 10.00. Due i treni regionali cancellati. I tecnici di Rete Ferroviaria Italiana sono al lavoro per ripristinare le normali condizioni di circolazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Il violento nubifragio che si \u00e8 abbattuto su tutta la Calabria ha provocato ingenti danni e diversi disagi.<\/p>\n","protected":false},"author":19,"featured_media":27701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-27700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27700"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27701"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}