{"id":277108,"date":"2025-11-30T13:50:43","date_gmt":"2025-11-30T12:50:43","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=277108"},"modified":"2025-11-30T13:51:29","modified_gmt":"2025-11-30T12:51:29","slug":"elezioni-ordine-dei-commercialisti-di-paola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/elezioni-ordine-dei-commercialisti-di-paola\/","title":{"rendered":"Elezioni Ordine dei Commercialisti di Paola, nasce la lista \u201cContinuit\u00e0 &#038; Innovazione\u201d guidata da Ciriaco Riente"},"content":{"rendered":"<p>PAOLA (CS) &#8211; Entra nel vivo la campagna elettorale per il rinnovo del Consiglio dell\u2019Ordine dei Dottori Commercialisti e degli Esperti Contabili di Paola. \u00c8 stata infatti ufficialmente presentata la lista <strong data-start=\"459\" data-end=\"489\">\u201cContinuit\u00e0 &amp; Innovazione\u201d<\/strong>, che sostiene la candidatura di <strong data-start=\"522\" data-end=\"540\">Ciriaco Riente<\/strong> alla presidenza per il mandato 2026.<\/p>\n<p data-start=\"579\" data-end=\"1038\">La lista nasce dal lavoro condiviso tra una parte dei consiglieri uscenti e numerosi professionisti del territorio che, negli ultimi mesi, hanno dato vita a un percorso partecipato e orientato a una gestione moderna i un Ordine, quello di Paola, che ha avuto nella figura di <a href=\"https:\/\/quicosenza.it\/news\/lutto-a-paola-scompare-giorgio-sganga-punto-di-riferimento-ed-ex-presidente-dellordine-dei-commercialisti\/\" target=\"_blank\" rel=\"noopener\">Sganga<\/a>, morto qualche mese fa, uno degli attori protagonisti del panorama nazionale. Il progetto intende valorizzare i risultati ottenuti sotto la presidenza di <strong data-start=\"884\" data-end=\"906\">Francesco Caldiero<\/strong>, proseguendo sulla strada del rinnovamento responsabile e in linea con gli indirizzi del presidente nazionale <strong data-start=\"1017\" data-end=\"1037\">Elbano De Nuccio<\/strong>. Il <a href=\"https:\/\/www.facebook.com\/profile.php?id=61584268748267\" target=\"_blank\" rel=\"noopener\">gruppo<\/a> \u00e8 composto da commercialisti provenienti da diversi centri della provincia, con esperienze eterogenee ma un obiettivo comune: costruire un Ordine pi\u00f9 vicino alla categoria, autorevole e proiettato verso il futuro.<\/p>\n<h3 data-start=\"1265\" data-end=\"1333\"><strong data-start=\"1269\" data-end=\"1333\">Il programma: tra innovazione digitale e formazione continua<\/strong><\/h3>\n<p data-start=\"1335\" data-end=\"1670\">Il cuore del programma elettorale \u00e8 l\u2019evoluzione della professione. In primo piano la <strong data-start=\"1421\" data-end=\"1448\">trasformazione digitale<\/strong>, con proposte dedicate alla diffusione delle competenze sull\u2019intelligenza artificiale, alla digitalizzazione degli studi professionali e all\u2019introduzione di strumenti innovativi per migliorare l\u2019organizzazione del lavoro.\u00a0Accanto all\u2019<strong>innovazione tecnologica,<\/strong> la lista punta a rafforzare la <strong data-start=\"1740\" data-end=\"1763\">formazione continua<\/strong>, con percorsi pianificati, contenuti aggiornati e collaborazioni strutturate con universit\u00e0 e centri di ricerca.<\/p>\n<h3 data-start=\"1335\" data-end=\"1670\">Rinnovo Ordine dei Commercialisti di Paola: attenzione ai giovani<\/h3>\n<p data-start=\"1878\" data-end=\"2146\">Grande attenzione \u00e8 rivolta ai <strong data-start=\"1909\" data-end=\"1935\">giovani commercialisti<\/strong>, considerati una risorsa strategica per il futuro dell\u2019Ordine. Tra le proposte: programmi di mentorship, iniziative dedicate ai professionisti nei primi anni di attivit\u00e0 e la promozione di tirocini qualificati.\u00a0Spazio anche al tema della <strong data-start=\"2175\" data-end=\"2199\">tutela professionale<\/strong>, con l\u2019obiettivo di potenziare gli strumenti di supporto agli iscritti attraverso osservatori specializzati e linee guida operative condivise. La lista propone inoltre un rafforzamento del dialogo con le istituzioni locali, cos\u00ec da rendere l\u2019Ordine un interlocutore stabile e autorevole nei principali tavoli economici e fiscali.<\/p>\n<p data-start=\"2531\" data-end=\"2797\">Tra i punti programmatici figura anche una revisione della <strong data-start=\"2590\" data-end=\"2626\">comunicazione interna ed esterna<\/strong>, per renderla pi\u00f9 accessibile, trasparente e tempestiva, oltre a una riflessione sul futuro della sede dell\u2019Ordine, da affrontare con responsabilit\u00e0 e visione strategica.<\/p>\n<h3 data-start=\"2799\" data-end=\"2851\"><strong data-start=\"2803\" data-end=\"2851\">&#8220;Continuit\u00e0 &amp; Innovazione\u201d un progetto tra radici solide e rinnovamento<\/strong><\/h3>\n<p data-start=\"2853\" data-end=\"3153\">\u201cContinuit\u00e0 &amp; Innovazione\u201d si presenta dunque come una proposta che mira a coniugare esperienza e visione contemporanea. L\u2019obiettivo dichiarato \u00e8 quello di costruire un Ordine dinamico, credibile e realmente al servizio dei colleghi, capace di interpretare con prontezza le sfide del mondo economico.<\/p>\n<h3 data-start=\"3155\" data-end=\"3186\"><strong data-start=\"3159\" data-end=\"3186\">I candidati della lista di Ciriaco Riente<\/strong><\/h3>\n<p data-start=\"3188\" data-end=\"3644\">A comporre la squadra sono: <strong data-start=\"3218\" data-end=\"3233\">Grazia Aita<\/strong> (Cetraro), <strong data-start=\"3245\" data-end=\"3267\">Ortenzia De Grazia<\/strong> (Amantea), <strong data-start=\"3279\" data-end=\"3300\">Nazareno Di Renzo<\/strong> (Belvedere M.mo), <strong data-start=\"3319\" data-end=\"3341\">Antonio Forestieri<\/strong> (Scalea), <strong data-start=\"3352\" data-end=\"3376\">Francesco Forestiero<\/strong> (Cetraro), <strong data-start=\"3388\" data-end=\"3408\">Vittorio Germano<\/strong> (Scalea), <strong data-start=\"3419\" data-end=\"3440\">Salvatore Impieri<\/strong> (Diamante), <strong data-start=\"3453\" data-end=\"3469\">Silvia Manzi<\/strong> (San Nicola Arcella), <strong data-start=\"3492\" data-end=\"3510\">Giuseppe Russo<\/strong> (Praia a Mare), <strong data-start=\"3527\" data-end=\"3544\">Michela Sarli<\/strong> (San Lucido), <strong data-start=\"3559\" data-end=\"3577\">Sabrina Sorace<\/strong> (Paola), <strong data-start=\"3587\" data-end=\"3604\">Luigi Suriano<\/strong> (Amantea), <strong data-start=\"3616\" data-end=\"3635\">Filomena Trotta<\/strong> (Paola).\u00a0Le elezioni si terranno <strong data-start=\"3670\" data-end=\"3697\">il 15 e 16 gennaio 2026<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lista guidata da Ciriaco Riente punta su digitalizzazione, giovani professionisti e continuit\u00e0 con il lavoro svolto negli ultimi anni. Le elezioni si terranno il 15 e 16 gennaio 2026<\/p>\n","protected":false},"author":55,"featured_media":277109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[],"class_list":["post-277108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/277108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=277108"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/277108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/277109"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=277108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=277108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=277108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}