{"id":277232,"date":"2025-12-02T07:00:11","date_gmt":"2025-12-02T06:00:11","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=277232"},"modified":"2025-12-02T07:10:38","modified_gmt":"2025-12-02T06:10:38","slug":"addetto-pulizie-san-giovanni-in-fiore-truffa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/addetto-pulizie-san-giovanni-in-fiore-truffa\/","title":{"rendered":"Addetto alla pulizie delle strade di San Giovanni in Fiore assolto dall\u2019accusa di truffa"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) &#8211; \u00a0<strong>Assolto dall&#8217;accusa di truffa<\/strong> un beneficiario di interventi di sostegno al reddito della <a href=\"https:\/\/www.regione.calabria.it\/\" target=\"_blank\" rel=\"noopener\">Regione Calabria.<\/a>\u00a0L\u2019uomo era rientrato nella misura di reimpiego in favore di disoccupati ultracinquantenni espulsi da settori ed aziende in crisi. Nel 2018 per conto del Comune di <a href=\"https:\/\/comune.sangiovanniinfiore.cs.it\/\" rel=\"noopener\"><u>San Giovanni in Fiore<\/u><\/a>\u00a0<strong>fungeva da addetto al servizio di pulizia delle strade<\/strong>.<\/p>\n<h3><strong>La presunta truffa e le assenze<\/strong><\/h3>\n<p>Secondo la Procura di Cosenza, tra febbraio e marzo 2018, per 7 volte si era allontanato arbitrariamente dalla postazione, <strong>senza segnalare l\u2019assenza<\/strong>\u00a0nel sistema di rilevazione basato sulle biomarcature. E avrebbe quindi ottenuto un ingiusto profitto costituito dallo <a href=\"https:\/\/quicosenza.it\/news\/via-il-reddito-di-cittadinanza-ecco-quante-famiglie-calabresi-sono-a-rischio-poverta\/\"><u>\u201cstipendio\u201d<\/u><\/a>\u00a0percepito pur non eseguendo le proprie prestazioni. Un altro suo \u201ccollega\u201d \u00e8 stato accusato degli stessi reati ed \u00e8 ancora in attesa di giudizio.<\/p>\n<h3><strong>Assolto addetto pulizie San Giovanni in Fiore<\/strong><\/h3>\n<p>Il giudice Palmina Formoso del Tribunale di Cosenza, nei giorni scorsi ha <strong>assolto il 65enne di San Giovanni in Fiore<\/strong>\u00a0perch\u00e9 il fatto non sussiste. La difesa, rappresentata dagli avvocato Pasquale Gallo e Alfonso Cassiano, ha dimostrato come il contratto fosse di 20 ore settimanali. Nel corso del processo, durato circa 7 anni, \u00e8 emerso che entrambi i <a href=\"https:\/\/quicosenza.it\/news\/ex-tirocinanti-impiegati-nelle-sedi-calabresi-proroga-sara-finanziata-fino-a-12-mesi-a-partire-dal-1-agosto\/\"><u>lavoratori<\/u><\/a>\u00a0non erano vincolati a svolgere un numero minino di ore giornaliere.<\/p>\n<h3><strong>L\u2019uomo era sul posto di lavoro<\/strong><\/h3>\n<p>Nel dibattimento la difesa ha provato che l\u2019uomo beneficiario del sussidio previsto dalla legge regionale n. 15 del 2008, nei giorni in cui appariva<a href=\"https:\/\/quicosenza.it\/news\/san-giovanni-in-fiore-punta-sulla-sostenibilita-inaugurate-sette-nuove-isole-ecologiche-informatizzate\/\"><u>\u00a0assente<\/u><\/a>, in realt\u00e0 era stato visto lavorare. Si trovava <strong>impegnato nella pulizia delle strade comunali<\/strong>, in posti diversi da quelli nei quali secondo gli investigatori doveva operare. Alle soglie del pensionamento il lavoratore \u00e8 cos\u00ec riuscito a dimostrare la propria innocenza in merito ai presunti episodi di assenteismo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019uomo lavorava in quanto beneficiario di interventi di sostegno al reddito. Era stato accusato di truffa per aver percepito indebitamente lo \u201cstipendio\u201d, ma il contratto era di 20 ore settimanali<\/p>\n","protected":false},"author":18,"featured_media":277233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-277232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/277232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=277232"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/277232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/277233"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=277232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=277232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=277232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}