{"id":278137,"date":"2025-12-11T14:36:15","date_gmt":"2025-12-11T13:36:15","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=278137"},"modified":"2025-12-11T14:36:15","modified_gmt":"2025-12-11T13:36:15","slug":"cosenza-calcio-tommaso-dorazio-200-presenze","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-calcio-tommaso-dorazio-200-presenze\/","title":{"rendered":"Tommaso D\u2019Orazio record e fedelt\u00e0: celebrato il traguardo delle 200 presenze con il Cosenza Calcio"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Tommaso D\u2019Orazio<\/strong>, capitano e simbolo della squadra, <strong>ha superato le 200 presenze con la maglia rossobl\u00f9<\/strong>. Un risultato che certifica non solo la longevit\u00e0 del <strong>terzino sinistro classe 1990<\/strong>, ma soprattutto il legame profondo instaurato negli anni con il club e con l\u2019intera piazza. Il Cosenza Calcio ha celebrato un traguardo speciale nella sala stampa del Marulla dove al capitano \u00e8 stata consegnata una maglia con il numero 200 e una targa alla presenza del direttore Generale Gualtieri e dell&#8217;addetto stampa Folino.<\/p>\n<h3>L&#8217;arrivo a Cosenza nel 2017<\/h3>\n<p>Arrivato per la prima volta a Cosenza nel gennaio del 2017, <strong>D\u2019Orazio ha saputo conquistare fin da subito il pubblico del \u201cMarulla\u201d<\/strong> grazie a personalit\u00e0, costanza e spirito di sacrificio. Tra i momenti indelebili della sua prima parentesi in rossobl\u00f9 spicca la <strong>storica <a href=\"https:\/\/quicosenza.it\/news\/223231-il-sogno-diventa-realta-siena-battuto-3-a-1-cosenza-fai-festa-sei-promosso-in-serie-b\/\" target=\"_blank\" rel=\"noopener\">promozione<\/a> in Serie B<\/strong> del giugno 2018, un traguardo raggiunto anche grazie alla sua continuit\u00e0 e alla sua leadership in campo.<\/p>\n<p>Dopo tre stagioni da protagonista con la maglia dei Lupi, il difensore ha intrapreso altre esperienze professionali, salvo poi fare <a href=\"https:\/\/quicosenza.it\/news\/495827-mercato-il-ritorno-di-dorazio-lesterno-sinistro-e-un-calciatore-del-cosenza\/\" target=\"_blank\" rel=\"noopener\">ritorno<\/a> a Cosenza <strong>nel gennaio 2023<\/strong>. Da allora \u00e8 diventato un punto fermo della formazione rossoblu, nonch\u00e9 un riferimento imprescindibile per compagni, staff tecnico e tifosi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-278141 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/596933749_1429745979157680_3227686125487259026_n.jpg\" alt=\"Tommaso D&#039;Orazio Cosenza\" width=\"581\" height=\"392\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/596933749_1429745979157680_3227686125487259026_n.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/596933749_1429745979157680_3227686125487259026_n-300x202.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/596933749_1429745979157680_3227686125487259026_n-768x518.jpg 768w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/><\/p>\n<h2>Tommaso D&#8217;Orazio celebrato dalla societ\u00e0<\/h2>\n<p>Il club ha voluto rendere omaggio al suo Capitano con un messaggio intriso di gratitudine<strong>: un ringraziamento per ogni corsa, ogni cross<\/strong>, ogni emozione regalata nel corso degli anni. Un gesto simbolico che riassume il rapporto speciale tra D\u2019Orazio e la citt\u00e0 dei Bruzi.\u00a0\u201c<strong><em>Onore alla tua maglia. Onore al nostro Capitano<\/em><\/strong>\u201d, conclude la nota della societ\u00e0, ribadendo l\u2019affetto e il rispetto verso un calciatore che \u00e8 ormai parte integrante della storia recente del<a href=\"https:\/\/www.facebook.com\/photo?fbid=1429745739157704&amp;set=pcb.1429745822491029\" target=\"_blank\" rel=\"noopener\"> Cosenza Calcio<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle prime gare con i rossoblu alla storica promozione in Serie B. Dai saluti al ritorno. D&#8217;Orazio terzino si conferma anima e capitano di un legame che dura dal 2017<\/p>\n","protected":false},"author":24,"featured_media":278139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-278137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=278137"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/278139"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=278137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=278137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=278137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}