{"id":278146,"date":"2025-12-11T15:20:51","date_gmt":"2025-12-11T14:20:51","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=278146"},"modified":"2025-12-11T16:10:30","modified_gmt":"2025-12-11T15:10:30","slug":"cosenza-testata-in-faccia-vigile-domiciliari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-testata-in-faccia-vigile-domiciliari\/","title":{"rendered":"Cosenza: testata in faccia ad un vigile: 38enne ai domiciliari in attesa di una struttura di riabilitazione"},"content":{"rendered":"<p>COSENZA \u2013 Per l\u2019uomo, <strong>un 38enne con problemi di tossicodipendenza iscritto al Sert<\/strong>, arrestato ieri mattina dopo<strong> aver rifilato una <\/strong><a href=\"https:\/\/quicosenza.it\/news\/cosenza-urina-strada-vigile-urbano-colpito\/\" target=\"_blank\" rel=\"noopener\">testata <\/a><strong>in faccia <\/strong>ad un agente della Polizia municipale di Cosenza, sono stati disposti <strong>gli arresti domiciliari<\/strong>, in attesa che venga individuata una <strong>struttura idonea<\/strong> che lo possa prendere in carico, vista proprio la sua dipendenza con la droga.<\/p>\n<h3>La decisione del tribunale di Cosenza<\/h3>\n<p>\u00c8 quanto deciso dal giudice del <strong>Tribunale di Cosenza<\/strong> stamattina al termine del <strong>processo per direttissima<\/strong> richiesto dal PM dopo l&#8217;episodio di cronaca a Cosenza. La vicenda \u00e8 nota: <strong>il 38enne<\/strong>, residente nella Presila, accusato di <strong>resistenza a pubblico ufficiale e lesioni<\/strong>, ieri mattina avrebbe <strong>prima molestato una ragazza<\/strong> che lavora in un negozio dell\u2019isola pedonale di Corso Mazzini. La ragazza, impaurita, \u00e8 rientrata nel negozio riferendo tutto alle colleghe e al suo datore di lavoro che, a sua volta, ha avvertito i vigili urbani che presidiavano la zona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-272958 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Tribunale-di-Cosenza.jpg\" alt=\"cetraro muto Tribunale di Cosenza\" width=\"610\" height=\"385\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Tribunale-di-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Tribunale-di-Cosenza-300x189.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Tribunale-di-Cosenza-768x485.jpg 768w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/p>\n<h3>L&#8217;intervento dei vigili e la testata in faccia<\/h3>\n<p>E poco dopo si \u00e8 verificato proprio l\u2019episodio pi\u00f9 grave: <strong>una testata in pieno volto<\/strong> ad un vigile urbano nel tentativo di opporre resistenza dopo che gli agenti <strong>lo avevano fermato nei pressi di Piazza XI Settembre<\/strong>. L\u2019uomo, a fatica, <strong>era stato poi immobilizzato e portato nell\u2019auto da altri 3 agenti<\/strong>, mentre Il vigile urbano colpito, soccorso dal 118, <strong>\u00e8 finito al pronto Soccorso<\/strong> con una forte contusione al setto nasale e <strong>un dente rotto <\/strong>dove si \u00e8 poi recato personalmente il sindaco di Cosenza, Franz Caruso, per manifestare la propria vicinanza all\u2019agente ferito e aggredito.<\/p>\n<p>Durante il processo di questa mattina, su richiesta del difensore, il 38enne ha richiesto e ottenuto di essere <strong>portato anche lui in ospedale,<\/strong> per un livido ad un occhio procurato dopo la colluttazione con gli stessi vigili.<\/p>\n<h3>La Provincia di Cosenza condanna con fermezza l&#8217;episodio<\/h3>\n<p>Su quanto accaduto si registra anche la solidariet\u00e0 del Presidente della provincia di Cosenza Lamensa, del Comandante Marano e dell\u2019intero corpo della Polizia Provinciale che parlando di: <strong>\u201cun attacco ingiustificabile a chi garantisce sicurezza e legalit\u00e0\u201d.<\/strong><\/p>\n<p>Per il <strong>Presidente della Provincia<\/strong>, <strong>Giancarlo Lamensa<\/strong>, si tratta di un fatto grave e ingiustificabile<em>: \u00abSiamo profondamente vicini all\u2019agente della Polizia Municipale vittima di questa aggressione. \u00c8 un <strong>episodio grave e ingiustificabile<\/strong>, che colpisce chi ogni giorno lavora con impegno per garantire sicurezza e decoro nella nostra citt\u00e0. A lui va il mio augurio sincero di una pronta guarigione. La Provincia di Cosenza \u00e8 al fianco della Polizia Municipale e di tutte le forze dell\u2019ordine che operano con senso del dovere e professionalit\u00e0\u00bb<\/em> &#8211; il commento.<\/p>\n<p>Condanna ferma dell\u2019episodio anche da parte del <strong>Comandante della Polizia Provinciale<\/strong> di Cosenza, Maggiore <strong>Rosario Marano<\/strong>: \u00ab<em>Condanniamo con fermezza quanto accaduto. Non \u00e8 accettabile che un agente venga aggredito mentre svolge il proprio lavoro e richiama un cittadino al rispetto delle regole. Tutto il corpo della Polizia Provinciale \u00e8 al fianco del collega ferito e riaffermiamo il nostro impegno condiviso per garantire sicurezza, legalit\u00e0 e rispetto verso gli operatori che ogni giorno presidiano il territorio<\/em>\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-278154 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Polizia-provinciale-Cosenza.jpg\" alt=\"Polizia provinciale Cosenza\" width=\"641\" height=\"428\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Polizia-provinciale-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Polizia-provinciale-Cosenza-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Polizia-provinciale-Cosenza-768x513.jpg 768w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/p>\n<p><strong>L\u2019intero corpo della Polizia Provinciale di Cosenza<\/strong> si stringe attorno all\u2019agente ferito, con un sentimento di forte <strong>vicinanza umana e professionale<\/strong>. Gli uomini e le donne del corpo esprimono sdegno per l\u2019aggressione subita da un collega impegnato nel suo dovere e ribadiscono con fermezza che atti di violenza contro chi indossa una divisa non sono solo un affronto alla persona, ma un attacco al ruolo istituzionale che tutti gli operatori di polizia rappresentano ogni giorno sul territorio.\u00a0La <a href=\"https:\/\/www.provincia.cs.it\/portale\/\" target=\"_blank\" rel=\"noopener\">Provincia di Cosenza<\/a> rinnova il proprio supporto agli agenti impegnati quotidianamente sul territorio e sottolinea l\u2019importanza di proteggere chi lavora, per garantire legalit\u00e0 e sicurezza alla comunit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 38enne, gi\u00e0 seguito dal Sert per problemi di tossicodipendenza, \u00e8 finito ai domiciliari nel processo per direttissima in attesa che venga individuata una struttura ideonea<\/p>\n","protected":false},"author":55,"featured_media":278150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,803],"tags":[],"class_list":["post-278146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-cronaca"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=278146"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/278150"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=278146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=278146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=278146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}