{"id":278712,"date":"2025-12-17T12:53:06","date_gmt":"2025-12-17T11:53:06","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=278712"},"modified":"2025-12-17T12:53:06","modified_gmt":"2025-12-17T11:53:06","slug":"mariano-tifoseria-sambiase-raccolta-fondi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/mariano-tifoseria-sambiase-raccolta-fondi\/","title":{"rendered":"&#8220;Tutti insieme per Mariano&#8221;, la tifoseria del Sambiase lancia una raccolta fondi"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; Il <a href=\"https:\/\/quicosenza.it\/news\/180-chili-malattia-rara-mariano-interrogazione\/\" target=\"_blank\" rel=\"noopener\"><strong>caso del piccolo Mariano<\/strong><\/a> arriva sul campo da calcio con l&#8217;iniziativa benefica <strong>&#8220;Tutti insieme per Mariano&#8221;.<\/strong> <strong>La tifoseria del Sambiase<\/strong> ha, infatti, scelto di far diventare il <strong>calcio un veicolo di solidariet\u00e0 e speranza <\/strong>attraverso una <strong>raccolta <\/strong><strong>fondi <\/strong>per il piccolo affetto da una malattia rara.<\/p>\n<p>L&#8217;iniziativa \u00e8 promossa da <strong>&#8220;Noi Siamo il Sambiase \u2013 la voce ufficiale della tifoseria giallorossa&#8221;. <\/strong>In occasione del match <strong>Sambiase\u2013Reggina<\/strong>, in programma\u00a0<strong>domenica 21 dicembre<\/strong>, la tifoseria giallorossa con la sua iniziativa benefica vuole sostenere il bambino dell&#8217;hinterland lametino che per via di una malattia rara oggi \u00e8 arrivato a pesare 180 chili.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-278720 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/tutti-insieme-per-mariano-tifoseria-del-sambiase-in-campo-per-solidarieta.jpeg\" alt=\"Mariano Sambiase raccolta fondi \" width=\"474\" height=\"474\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/tutti-insieme-per-mariano-tifoseria-del-sambiase-in-campo-per-solidarieta.jpeg 635w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/tutti-insieme-per-mariano-tifoseria-del-sambiase-in-campo-per-solidarieta-300x300.jpeg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/tutti-insieme-per-mariano-tifoseria-del-sambiase-in-campo-per-solidarieta-150x150.jpeg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/tutti-insieme-per-mariano-tifoseria-del-sambiase-in-campo-per-solidarieta-80x80.jpeg 80w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/p>\n<h3>Raccolta fondi per Mariano, la tifoseria in campo<\/h3>\n<p>La <strong>Sambiase <\/strong>ha deciso di devolvere\u00a0<strong>l&#8217;intero ricavato della vendita delle fanzine<\/strong> alla raccolta fondi destinata ad aiutare il piccolo e la sua famiglia sul fronte delle <strong>cure specialistiche <\/strong>che saranno <a href=\"https:\/\/quicosenza.it\/news\/piccolo-mariano-curato-casa\/\" target=\"_blank\" rel=\"noopener\">effettuate a casa<\/a> ma che hanno costi elevati e che rendono fondamentale il sostegno della comunit\u00e0.<\/p>\n<p>&#8220;Ancora una volta il popolo giallorosso dimostra come il tifo non sia solo passione sportiva &#8211; dicono dalla <a href=\"http:\/\/facebook.com\/23Settembre2001Sambiase\" rel=\"noopener\">tifoseria del club<\/a> &#8211; ma anche <strong>cuore, vicinanza e impegno sociale<\/strong>. L&#8217;invito \u00e8 rivolto a tutti: partecipare con una\u00a0<strong>libera donazione<\/strong>, perch\u00e9 ogni gesto, anche il pi\u00f9 piccolo, pu\u00f2 fare la differenza. &#8220;<strong>Tutti insieme per Mariano<\/strong>&#8221; non \u00e8 solo uno slogan, ma un <strong>messaggio forte di unit\u00e0 e solidariet\u00e0.<\/strong> Domenica, sugli spalti e fuori dal campo, il Sambiase giocher\u00e0 una partita speciale: quella dell&#8217;umanit\u00e0 e dell&#8217;aiuto concreto verso chi ha pi\u00f9 bisogno&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del match Sambiase\u2013Reggina, la rifoseria giallorossa ha deciso che l&#8217;intero ricavato della vendita delle fanzine\u00a0sar\u00e0 destinato alla raccolta fondi per aiutare Mariano e la sua famiglia <\/p>\n","protected":false},"author":90,"featured_media":278719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-278712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=278712"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/278719"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=278712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=278712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=278712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}