{"id":278823,"date":"2025-12-18T14:44:20","date_gmt":"2025-12-18T13:44:20","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=278823"},"modified":"2025-12-18T17:56:52","modified_gmt":"2025-12-18T16:56:52","slug":"cosenza-calcio-cavese-busce-fiducia-mercato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-calcio-cavese-busce-fiducia-mercato\/","title":{"rendered":"Cosenza Calcio, domani la Cavese per chiudere al meglio il 2025. Busc\u00e8: &#8220;ho fiducia nel mercato e nel Presidente&#8221;"},"content":{"rendered":"<p><strong>COSENZA<\/strong> \u2013 Ultima giornata del <strong>girone d&#8217;andata<\/strong> per il <strong>Cosenza Calcio<\/strong>, che domani sera o<strong>spiter\u00e0 la Cavese al San Vito-Gigi Marulla<\/strong>. I rossobl\u00f9 proveranno a chiudere il 2025\u00a0 sulla scia di un ottimo girone di andata, frutto di un ottimo percorso considerando <strong>l&#8217;emergenza infortuni che ha colpito la rosa<\/strong>. A fare il punto della situazione, in conferenza stampa, il tecnico Busc\u00e8<\/p>\n<h3><strong>L&#8217;infortunio di Mazzocchi e la fiducia nel mercato<\/strong><\/h3>\n<p>La notizia peggiore \u00e8 arrivata nelle ultime ore: <strong>Simone Mazzocchi<\/strong> dovr\u00e0 <a href=\"https:\/\/quicosenza.it\/news\/cosenza-calcio-tegola-busce-mazzocchi-spalla\/\" target=\"_blank\" rel=\"noopener\">operarsi<\/a> e rester\u00e0 fuori a lungo. &#8220;<em>Dispiace, perch\u00e9 tutti volevamo qualcosa di diverso<\/em>&#8220;, ha spiegato Busc\u00e8 con rammarico. Il tecnico ha voluto mandare un messaggio al giocatore:<em> &#8220;<strong>Gli ho fatto un in bocca al lupo<\/strong>, deve stare sereno e quando ritorner\u00e0 avr\u00e0 tutto il tempo per rifarsi<\/em>&#8220;.<\/p>\n<p>Sul fronte mercato Busc\u00e8 si \u00e8 mostrato ottimista: &#8220;<em>Ho fiducia nella propriet\u00e0. Mi sono confrontato con il Presidente e c&#8217;\u00e8 tanta positivit\u00e0, questa cosa mi ha fatto molto piacere. Sono sereno sotto questo aspetto<\/em>&#8220;. Un messaggio chiaro che il tecnico aveva gi\u00e0 lanciato dopo il match contro il Picerno: &#8220;<em>Nel confronto con la propriet\u00e0 vedo entusiasmo nel Presidente. Questo mi fa ben sperare per il mercato di gennaio: la societ\u00e0 ci sar\u00e0 vicina<\/em>&#8220;.<\/p>\n<h2><strong>Emergenza e scelte: chi gioca contro la Cavese<\/strong><\/h2>\n<p>L&#8217;infermeria rossobl\u00f9 non accenna a svuotarsi. Oltre agli infortuni di lungo corso di Curfalidis e Cimino, \u00a0e ora Mazzocchi alla spalla, ci sono altri problemi da gestire. &#8220;<strong><em>Ferrara ha avuto qualche problema a sinistra, bisogna capire in queste ore se sar\u00e0 disponibile, ma credo di no<\/em><\/strong>&#8220;, ha rivelato Busc\u00e8. In pi\u00f9, cinque giocatori sono diffidati.<\/p>\n<p>Nonostante tutto, la formazione non dovrebbe discostarsi molto dall&#8217;ultima uscita: &#8220;<strong><em>Non voglio scombussolare quasi nulla, perch\u00e9 abbiamo trovato una quadra e delle certezze. Nulla vieta che ci possa essere qualche cambio all&#8217;ultimo o a partita in corso<\/em><\/strong>&#8220;. Al posto di Ferrara dovrebbe agire D&#8217;Orazio, con <strong>Beretta confermato in attacco<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-272619 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Cosenza-Calcio-formazione_01.jpg\" alt=\"Cosenza Calcio formazione_01\" width=\"732\" height=\"473\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Cosenza-Calcio-formazione_01.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Cosenza-Calcio-formazione_01-300x194.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Cosenza-Calcio-formazione_01-768x496.jpg 768w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/p>\n<h3><strong>Cosenza Calcio, Il bilancio del girone d&#8217;andata<\/strong><\/h3>\n<p>Quattro punti nelle ultime tre gare hanno generato qualche rammarico, ma Busc\u00e8 invita a guardare oltre il risultato: &#8220;<strong><em>Bisogna dare importanza alle prestazioni<\/em><\/strong><em> che sta facendo questa squadra, altrimenti si giudica solo in base ai risultati e sarebbe la cosa pi\u00f9 sbagliata. Nel calcio chi vince \u00e8 bravo e chi perde \u00e8 un somaro? Non \u00e8 cos\u00ec<\/em>&#8220;.\u00a0Il tecnico ha poi analizzato gli errori commessi: &#8220;<strong><em>Sui punti persi bisogna fare mea culpa, io per primo<\/em><\/strong><em>. Gol subiti su calcio piazzato con la partita in mano, come ad Altamura, Sorrento e Potenza. Errori banali ed evitabilissimi<\/em>&#8220;. Punti che oggi pesano nella corsa al vertice: &#8220;<em>Quei 4-5 punti che ci mancano ora peserebbero. Ci serva da lezione<\/em>&#8220;.<\/p>\n<h2><strong>Per Busc\u00e8 un bilancio pi\u00f9 che positivo<\/strong><\/h2>\n<p>Eppure, il bilancio complessivo del Cosenza Calcio resta pi\u00f9 che positivo: &#8220;<em>P<strong>er le difficolt\u00e0 avute, soprattutto tre operazioni a ginocchia e spalla, questi ragazzi sono da elogiare dal primo all&#8217;ultimo<\/strong>. La squadra ha dimostrato di non essere inferiore a nessuno<\/em>&#8220;.<\/p>\n<h3><strong>La Cavese e una sfida da non sottovalutare<\/strong><\/h3>\n<p>Dopo il Pareggio di <a href=\"https:\/\/www.ilcosenza.it\/2025\/12\/13\/il-tabellino-di-trapani-cosenza-1-1\/\" target=\"_blank\" rel=\"noopener\">Trapani<\/a>, domani sar\u00e0 la <strong>sfida contro una Cavese che non va sottovalutata<\/strong>: &#8220;<em>Va affrontata con le pinze. Conosco l&#8217;allenatore e alcuni giocatori, hanno trovato equilibrio. Possono farti male da un momento all&#8217;altro. Bisogna affrontarli con umilt\u00e0 e spirito di sacrificio, senza guardare la classifica<\/em>&#8220;. Il pericolo maggiore? <strong>Un calo di concentrazione<\/strong>: &#8220;<em>Ogni singolo giocatore deve stare sul pezzo per 100 minuti. Il rischio \u00e8 sentirsi rilassati quando hai il pallino del gioco in mano; quello \u00e8 il momento pi\u00f9 pericoloso<\/em>&#8220;. La ricetta \u00e8 chiara: <strong>pazienza, letture giuste e intensit\u00e0 per tutti i novanta minuti, anzi cento come ribadito pi\u00f9 volte dal tecnico.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-278846 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Mister-Busce-Cosenza.jpg\" alt=\"Mister Busc\u00e8 Cosenza Calcio\" width=\"611\" height=\"413\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Mister-Busce-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Mister-Busce-Cosenza-300x203.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/Mister-Busce-Cosenza-768x519.jpg 768w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/><\/p>\n<h3><strong>Florenzi e la voglia di vedere i tifosi al Marulla<\/strong><\/h3>\n<p>Una menzione speciale per <strong>Florenzi,<\/strong> da cui Busc\u00e8 si aspetta di pi\u00f9: &#8220;<em>Chi sa saltare l&#8217;uomo fa la differenza. <strong>Nei primi 5-10 metri ha caratteristiche che pochi hanno<\/strong>. Deve avere pi\u00f9 continuit\u00e0 e crederci. Deve essere consapevole della sua forza e pensare positivo<\/em>&#8220;.\u00a0Infine, un pensiero ai tifosi, ancora lontani dal Marulla: &#8220;<em>Incontro spesso persone facendo la spesa e hanno tutti voglia di venire allo stadio. Vedo nei loro occhi l&#8217;appartenenza. I ragazzi stanno trasportando un po&#8217; tutti. <strong>Sarebbe bello avere un Marulla con tanta gente a trascinare,<\/strong> perch\u00e9 il girone di ritorno sar\u00e0 un altro campionato<\/em>&#8220;.\u00a0<em>&#8220;Ho visto una squadra serena<\/em>&#8221; ha concluso Busc\u00e8. &#8220;R<em>agazzi molto concentrati col sorriso sulle labbra, che non \u00e8 poco<\/em>&#8220;. Domani sera parola al campo<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tecnico Busc\u00e8 analizza il momento del Cosenza tra l&#8217;infortunio di Mazzocchi e le ambizioni per il girone di ritorno. &#8220;Mi sono confrontato con il Presidente e c&#8217;\u00e8 tanta positivit\u00e0, questa cosa mi ha fatto molto piacere. Siamo quarti, questi ragazzi sono sacri&#8221;<\/p>\n","protected":false},"author":24,"featured_media":276475,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-278823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=278823"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/278823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/276475"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=278823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=278823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=278823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}