{"id":279309,"date":"2025-12-24T13:27:47","date_gmt":"2025-12-24T12:27:47","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=279309"},"modified":"2025-12-24T15:35:50","modified_gmt":"2025-12-24T14:35:50","slug":"natale-calabria-superenalotto-estrazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/natale-calabria-superenalotto-estrazione\/","title":{"rendered":"Natale baciato dalla fortuna in Calabria, il &#8220;5&#8221; al Superenalotto vale quasi 40mila euro"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Il <strong>Natale<\/strong> si tinge d&#8217;oro per un fortunato giocatore a <strong>Reggio Calabria<\/strong>, premiato con l&#8217;ultima <strong>estrazione<\/strong> del<strong> SuperEnalotto<\/strong>. Nell\u2019estrazione di marted\u00ec 23 dicembre 2025, la dea bendata ha fatto tappa in riva allo Stretto, regalando una vincita che accende l&#8217;entusiasmo in pieno clima festivo.<\/p>\n<p>Ad annunciarlo \u00e8 stata l&#8217;agenzia specializzata <em>Agripronews<\/em> <strong><a href=\"https:\/\/www.agipronews.it\/lotto\/SuperEnalotto:-a-Reggio-Calabria-centrato-un-%E2%80%9C5%E2%80%9D-da-oltre-39mila-euro-id.225094\" target=\"_blank\" rel=\"noopener\">che ha comunicato<\/a><\/strong> l&#8217;<strong>importo<\/strong> esatto e anche la <strong>ricevitoria<\/strong> nella quale \u00e8 stata giocata la<strong> schedina vincente<\/strong>.<\/p>\n<h2>Vincita milionaria a Reggio Calabria<\/h2>\n<p>\u00c8 stato centrato un &#8220;<strong>5<\/strong>&#8221; <strong>del valore di 39.811,06 euro<\/strong>. La schedina vincente \u00e8 stata giocata presso la Rivendita Tabacchi Condemi, situata nel cuore della citt\u00e0, precisamente in Corso Garibaldi 346.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-186982\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot.jpg\" alt=\"superenalotto\" width=\"540\" height=\"334\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/superenalotto-jackpot-356x220.jpg 356w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/p>\n<p>Sebbene il colpo grosso sia stato solo sfiorato, la cifra rappresenta comunque un importante &#8220;regalo&#8221; sotto l&#8217;albero per il <strong>vincitore <\/strong>che si \u00e8 potuto cos\u00ec aggiudicare la cifra di quasi 40mila euro.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/gratta-e-vinci-colpaccio-da-100mila-euro-a-rende-la-vincita-con-un-biglietto-supergold\/\" target=\"_blank\" rel=\"noopener\">Non si tratta in ogni caso di un episodio isolato in Calabria<\/a>. Ad ottobre, infatti, per un Gratta e Vinci si \u00e8 riusciti a guadagnare qualcosa come 100mila euro. L&#8217;episodio in questione \u00e8 avvenuto a <strong>Rende<\/strong>, in provincia di Cosenza.<\/p>\n<h3>Non si ferma la corsa al jackpot<\/h3>\n<p>Se la Calabria festeggia un Natale fortunato, resta ancora aperta la caccia al jackpot milionario. L\u2019ultima volta che \u00e8 stato centrato il &#8220;6&#8221; risale al 22 maggio 2025. In quella circostanza, infatti, a Desenzano del Garda (BS) ci si aggiudic\u00f2 la cifra record di 35,4 milioni di euro.<\/p>\n<p>Da quel momento, per\u00f2, il <strong>montepremi<\/strong> ha continuato a crescere, raggiungendo cifre importanti. Si resta in attesa della <strong>prossima estrazione<\/strong>, evento programmato per <strong>sabato 27 dicembre 2025<\/strong>. Ma prima c&#8217;\u00e8 una breve pausa di Natale, poi si potr\u00e0 tentare nuovamente la fortuna e magari conquistare il <strong>jackpot<\/strong> <strong>attuale di 96,8 milioni di euro<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quasi 40mila euro che arrivano proprio nel pieno delle feste di Natale. Gioia e felicit\u00e0, intanto il jackpot sale a quasi 97 milioni di euro<\/p>\n","protected":false},"author":93,"featured_media":279314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-279309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/279309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=279309"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/279309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/279314"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=279309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=279309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=279309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}