{"id":279943,"date":"2026-01-04T17:15:38","date_gmt":"2026-01-04T16:15:38","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=279943"},"modified":"2026-01-05T12:26:40","modified_gmt":"2026-01-05T11:26:40","slug":"attacco-usa-venezuela-sindaco-cosenza-trump","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/attacco-usa-venezuela-sindaco-cosenza-trump\/","title":{"rendered":"Attacco Usa in Venezuela, il sindaco di Cosenza sostiene le iniziative contro l\u2019azione di Trump"},"content":{"rendered":"<p>COSENZA &#8211;<strong> Cosenza per la pace contro l&#8217;attacco bellico di Trump in Venezuela<\/strong>.\u201cCosenza \u00e8 una citt\u00e0 che, nel corso della sua storia, ha sempre affermato i principi della pace, della solidariet\u00e0 tra i popoli, del diritto all\u2019autodeterminazione e del rispetto delle regole del diritto internazionale. Valori nei quali ci riconosciamo pienamente e che continuano a guidare la nostra azione&#8221;, dichiara il <strong>sindaco di Cosenza Franz Caruso.<\/strong><\/p>\n<p>Esprimo, pertanto, il mio convinto <strong>sostegno alle iniziative<\/strong> che in queste settimane si stanno organizzando p<strong>er contrastare le politiche di matrice imperialista<\/strong> riconducibili all\u2019amministrazione Trump. Politiche che rischiano di alimentare nuovi conflitti, aggravare le disuguaglianze e produrre pericolose tensioni sul piano globale\u201d.<\/p>\n<h3>Sostegno alla protesta contro l\u2019azione di Trump in Venezuela<\/h3>\n<p>Il sindaco Franz Caruso dichiara di volersi porre &#8220;al fianco alle tante associazioni che intendono manifestare contro l\u2019azione messa in campo dal governo Trump nei confronti del Venezuela, con l\u2019obiettivo di riaffermare i principi della democrazia e dell\u2019autodeterminazione dei popoli.<\/p>\n<p>\u201cRitengo fondamentale \u2013 prosegue il Primo Cittadino \u2013 che le istituzioni locali facciano sentire la propria voce quando sono in gioco principi universali come la giustizia, la cooperazione tra i popoli e il rifiuto della legge del pi\u00f9 forte. Le <strong>mobilitazioni civili rappresentano uno strumento democratico<\/strong> essenziale per affermare questi valori e per richiamare la comunit\u00e0 internazionale alle proprie responsabilit\u00e0\u201d.<\/p>\n<p>\u201cQualora gli impegni istituzionali precedentemente assunti lo consentano \u2013 conclude il sindaco Franz Caruso \u2013<strong> intendo partecipare personalmente alla manifestazione in programma per mercoled\u00ec 7 gennaio<\/strong>, scendendo in piazza insieme a cittadine e cittadini, associazioni e movimenti che chiedono un mondo pi\u00f9 equo e fondato sul dialogo, non sulla sopraffazione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l&#8217;attacco Usa in Venezuela, il sindaco di Cosenza Franz Caruso dichiara che parteciper\u00e0 alle manifestazioni  in programma<\/p>\n","protected":false},"author":58,"featured_media":279944,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-279943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/279943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=279943"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/279943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/279944"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=279943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=279943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=279943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}