{"id":280279,"date":"2026-01-08T20:00:34","date_gmt":"2026-01-08T19:00:34","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=280279"},"modified":"2026-01-08T19:44:56","modified_gmt":"2026-01-08T18:44:56","slug":"castrovillari-garante-carcere-sistema-collasso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/castrovillari-garante-carcere-sistema-collasso\/","title":{"rendered":"Castrovillari, Garante su violenza in carcere: \u00absistema al collasso, serve tutela per agenti e detenuti\u00bb"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Dopo aver appreso dell\u2019avvenuto <a href=\"https:\/\/quicosenza.it\/news\/aggressione-carcere-castrovillari-agente-ferito\/\">episodio nel carcere di Castrovillari<\/a>, la Garante della casa circondariale <strong>Tina Zaccato<\/strong> si <strong>\u00e8 recata presso l\u2019istituto in mattinata<\/strong>, in primis per accertarsi delle condizioni di salute<strong> dell\u2019Assistente Capo che ha subito l\u2019aggressione e poi per incontrare i rappresentanti del Sindacato Sappe<\/strong> che ne hanno dato la notizia attraverso le testate giornalistiche locali, fino a giungere ad una nota fatta dal Segretario nazionale Giovan Battista Durante.<\/p>\n<h3>L&#8217;aggressione nel carcere di Castrovillari, l&#8217;intervento della Garante<\/h3>\n<p>La Garante ha incontrato Gaetano Maurmo, vice segretario regionale del <a href=\"https:\/\/www.sappe.it\/segreterie-sappe\/\" rel=\"noopener\"><strong>Sappe<\/strong><\/a> eh ha poi interloquito a lungo con Leonardo De Santis, Segretario locale del Sappe di Castrovillari. Nel pomeriggio, ha tentuto un <strong>incontro telefonico<\/strong> con il segretario regionale del Sappe Francesco Ciccone, sottolineando la propria disponibilit\u00e0 e presenza a favore delle forze dell\u2019ordine che lavorano al momento, anche negli istituti di pena calabresi, in situazioni molto stringenti. Ciccone ha avvisato la Zaccato che presto verr\u00e0 fatta richiesta di una interrogazione parlamentare a questo proposito. Sono infatti in media 2000 all\u2019anno le aggressioni registrare a danno degli agenti di Polizia Penitenziaria nelle carceri italiane. Questo denota e sottolinea un sistema al collasso dove \u00e8 necessario l\u2019intervento della politica. Al momento nella C.C. di Castrovillari si contano 199 detenuti per una capienza regolamentare di 122 posti.<\/p>\n<h3>Le criticit\u00e0<\/h3>\n<p>La garante sottolinea l\u2019accento sul <strong>tasso di sovraffollamento<\/strong>, dato incidente sulla <strong>vita lavorativa dei dipendenti<\/strong> all\u2019interno del carcere e sulla qualit\u00e0 dello sconto della pena che porta a situazioni estreme. Nel carcere di Castrovillari anche la sezione femminile non vive una situazione indenne al sovraffollamento<strong> su 17 posti regolamentati, sale infatti a 30 il numero delle detenute presenti<\/strong> in istituto per un organico di<strong> 104 agenti effettivi su 124 previsti<\/strong> e dove ad oggi, visto il problema del sovraffollamento, ce ne vorrebbero sicuramente di pi\u00f9 anche per evitare situazioni di burn-out tra gli agenti che di pi\u00f9, sono toccati dal sistema carcere e detentivo.<\/p>\n<p>Da sociologa, la Garante del carcere di Castrovillari tiene molto al dato numerico dell\u2019istituzione cui \u00e8 designata e non perde di mira anche il numero dei suicidi. Ne sono stati registrati circa 80 nell\u2019anno 2025, di cui uno degli ultimi dell\u2019anno appena passato, proprio lo scorso 26 dicembre. C\u2019\u00e8 bisogno di un intervento non solo a livello locale, ma del Governo e del Parlamento per un intervento immediato che veda l\u2019attuarsi di una nuova stagione di riforme per garantire condizioni di detenzione rispettose dei diritti umani in modo da contrastare casi del genere.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-280282\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/carcere-di-castrovillari.jpg\" alt=\"carcere di castrovillari\" width=\"517\" height=\"320\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/carcere-di-castrovillari.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/carcere-di-castrovillari-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/carcere-di-castrovillari-768x475.jpg 768w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><\/p>\n<p>La garante <strong>ha incontrato in mattinata anche alcuni insegnanti del CPIA<\/strong> che lavorano all\u2019interno del carcere informandosi sui progetti in itinere. Da insegnate non perde di vista l\u2019importanza della scuola come strumento di riscatto di queste persone e sottolinea l\u2019importanza del lavoro del CPIA (Centro provinciale per l\u2019istruzione degli adulti) che va sicuramente rafforzato non solo per i percorsi di scolarizzazione di secondo grado ma anche per quelli di istruzione primaria che vedono corsi di alfabetizzazione ed apprendimento della lingua italiana per gli stranieri. L\u2019unico modo per scontare la pena in modo dignitoso e pensare ad un reinserimento futuro e ad un abbassamento della recidiva, \u00e8 tenere impegnati i detenuti facendoli studiare e dandogli nuove opportunit\u00e0. E\u2019 necessario un incremento dei corsi di formazione professionali, del lavoro all\u2019esterno per i detenuti che possono accede a questa misura e di un sistema di comunicazione efficace che metta in relazione l\u2019interno con l\u2019esterno ed anche il livello istituzionale.<\/p>\n<p>Visto il dato emergente e la situazione al collasso, bisogna pensare in primis alle condizioni di vita dei detenuti in relazione al sovraffollamento, da questo ne deriva lo stato di salute di tutto il sistema penitenziario e del lavoro degli agenti e del personale civile al suo interno. Bisogna tenere presente che nel nostro Paese il numero delle persone detenute \u00e8 in forte crescita ed a fronte di una capienza a disposizione di circa 46mila posti, abbiamo una <strong>popolazione carceraria che supera i 63mila posti disponibili<\/strong>.<\/p>\n<p>Largo dunque alle <strong>misure alternative ed alla messa in prova ai servizi sociali<\/strong>. Bisogna inoltre tener presente che ci lasciamo appena ora alle spalle le festivit\u00e0 natalizie e tener dunque presente della situazione legata all\u2019affettivit\u00e0 ed alle feste trascorse lontane dagli affetti. Sono tante le cose di cui tener conto ed il pi\u00f9 delle volte, sono proprio gli agenti di Polizia penitenziaria a dover fronteggiare a tutto questo. Importante in questa situazione anche il ruolo della Chiesa e del culto, che oltre ad avere un ruolo celebrativo e di consolazione, si vede impegnato a dare anche una mano reale. Da poco l\u2019istituto ha visto l\u2019ingresso di un nuovo cappellano, Franco Granata che nel periodo prima delle feste ha dato vita ad una raccolta di indumenti per i detenuti sprovvisti di abiti. In un luogo dove tutto spesso manca, anche la carit\u00e0 \u00e8 importante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-252567\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari.jpg\" alt=\"\" width=\"564\" height=\"349\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/03\/carcere-castrovillari-356x220.jpg 356w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><\/p>\n<h3>Solidariet\u00e0 all&#8217;agente aggredito<\/h3>\n<p>&#8220;Esprimo ancora una volta piena solidariet\u00e0 all\u2019agente aggredito &#8211; ha dichiarato Zaccato &#8211; augurandogli una <strong>pronta guarigione<\/strong>. La violenza all\u2019interno degli istituti penitenziari non \u00e8 un fatto ordinario e bisogna pensare agli agenti in servizio negli istituti&#8221;. La garante presto terr\u00e0 un incontro con tutte le sigle sindacali presenti in istituto e presto vorr\u00e0 incontrare anche i lavoratori dell\u2019ambito sanitario che lavorano all\u2019interno. L\u2019ambito sanitario \u00e8 un altro ambito delicato in tutta la Calabria ed anche all\u2019interno degli istituti di pena e bisogna pensare anche a questi lavoratori. Da RSA della FLC CGIL e con l\u2019esperienza del suo lavoro a scuola, la garante d\u00e0 molta importanza al mondo sindacale all\u2019interno degli ambiti lavorativi ed il suo ruolo, non prescinde mai da un\u2019attenzione dedicata ai lavoratori. La Garante augura venga fatto al pi\u00f9 presto un tavolo tecnico a livello locale, provinciale, in una provincia dove in 4 istituti penitenziari \u00e8 presente solo una garante su 4 carceri ed a livello regionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l\u2019aggressione a un agente della Polizia Penitenziaria, Tina Zaccato denuncia sovraffollamento e criticit\u00e0 nella Casa Circondariale di Castrovillari e rilancia sul ruolo della scuola e dei percorsi di reinserimento<\/p>\n","protected":false},"author":42,"featured_media":280280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-280279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/280279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=280279"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/280279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/280280"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=280279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=280279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=280279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}