{"id":280445,"date":"2026-01-10T16:35:53","date_gmt":"2026-01-10T15:35:53","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=280445"},"modified":"2026-01-10T18:02:48","modified_gmt":"2026-01-10T17:02:48","slug":"cosenza-maltempo-crisi-idrica-semaforo-caduto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-maltempo-crisi-idrica-semaforo-caduto\/","title":{"rendered":"Giornata nera per Cosenza tra forte maltempo e crisi idrica: semaforo e alberi caduti in strada"},"content":{"rendered":"<p>COSENZA &#8211; Un <strong>sabato nero<\/strong> quello che oggi, 10 gennaio, sta vivendo la citt\u00e0 di <strong>Cosenza<\/strong>, stretta, come <a href=\"https:\/\/quicosenza.it\/news\/maltempo-cosentino-vento-pioggia-neve-grandine\/\" target=\"_blank\" rel=\"noopener\">tutta la Calabria<\/a> del resto, nella morsa del maltempo. E come se questo non bastasse a creare molti <strong>disagi<\/strong>, si aggiunge anche la problematica della <strong>crisi idrica<\/strong>.<\/p>\n<p>Questa mattina, infatti, la Sorical ha comunicato un<a href=\"https:\/\/quicosenza.it\/news\/acquedotto-abatemarco-rottura-interruzioni\/\" target=\"_blank\" rel=\"noopener\"> ennesima rottura<\/a> sull&#8217;acquedotto dell&#8217;Abatemarco non facile da individuare. Ecco perch\u00e8 molte zone della citt\u00e0 sono senz&#8217;acqua. Il ripristino del servizio, tra l&#8217;altro, non sar\u00e0 garantito probabilmente, prima di domani.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-280442 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Maltempo-Cosenza.jpg\" alt=\"Maltempo Cosentino\" width=\"499\" height=\"329\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Maltempo-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Maltempo-Cosenza-300x198.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Maltempo-Cosenza-768x506.jpg 768w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>I residenti in citt\u00e0 dunque, si trovano a fare i conti con tantissimi disagi. In molti sono stati anche <a href=\"https:\/\/quicosenza.it\/news\/terremoto-circolazione-ferroviaria-sospesa\/\">svegliati all&#8217;alba dalla forte scossa di terremoto di magnitudo 5.1<\/a> che si \u00e8 verificata al largo delle coste reggine alle ore 5.53.<\/p>\n<p>A rendere ancora pi\u00f9 difficile la gestione dell&#8217;emergenza sono i<strong> tanti danni <\/strong>causati dalle<strong> forti raffiche di vento e dalla pioggia incessante <\/strong>che in diverse zone del territorio cittadino ha provocato la <strong>caduta di rami e alberi, allagamenti e problemi alla viabilit\u00e0.\u00a0<\/strong><\/p>\n<h3>Maltempo, a Cosenza cade in strada un semaforo<\/h3>\n<p>Diversi gli alberi caduti che hanno dannegiato le auto parcheggiate in strada. Ad essere precipitato sulla carreggiata anche un <strong>semaforo<\/strong>. \u00c8 accaduto <strong>all&#8217;incrocio tra Viale Cosmai e Via Dalla chiesa.<\/strong><\/p>\n<p>Fortunatamente la caduta <strong>non ha provocato danni a cose e persone.<\/strong>\u00a0Come fa sapere l&#8217;assessore <strong>Francesco De Cicco<\/strong> che si sta occupando di monitorare la situazione in citt\u00e0 collaborando con le forze dell\u2019ordine e gli enti preposti, <a href=\"https:\/\/www.facebook.com\/francescodeciccosindaco\" target=\"_blank\" rel=\"noopener\">tramite i suoi canali social<\/a>, che &#8220;La situazione \u00e8 sotto controllo&#8221;.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-280445 gallery-columns-4 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/quicosenza.it\/news\/cosenza-maltempo-crisi-idrica-semaforo-caduto\/senza-titolo123\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"248\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Senza-titolo123-300x248.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Senza-titolo123-300x248.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Senza-titolo123.jpg 319w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href=\"https:\/\/quicosenza.it\/news\/cosenza-maltempo-crisi-idrica-semaforo-caduto\/senza-titolo12\/\"><img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"300\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Senza-titolo12-186x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Senza-titolo12-186x300.jpg 186w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Senza-titolo12.jpg 309w\" sizes=\"auto, (max-width: 186px) 100vw, 186px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href=\"https:\/\/quicosenza.it\/news\/cosenza-maltempo-crisi-idrica-semaforo-caduto\/614373439_1477458097272881_8113391487992761317_n\/\"><img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"300\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/614373439_1477458097272881_8113391487992761317_n-226x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/614373439_1477458097272881_8113391487992761317_n-226x300.jpg 226w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/614373439_1477458097272881_8113391487992761317_n-771x1024.jpg 771w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/614373439_1477458097272881_8113391487992761317_n-768x1020.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/614373439_1477458097272881_8113391487992761317_n-1157x1536.jpg 1157w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/614373439_1477458097272881_8113391487992761317_n.jpg 1536w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href=\"https:\/\/quicosenza.it\/news\/cosenza-maltempo-crisi-idrica-semaforo-caduto\/613637167_1477458077272883_7570666380933207059_n\/\"><img loading=\"lazy\" decoding=\"async\" width=\"197\" height=\"300\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/613637167_1477458077272883_7570666380933207059_n-197x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/613637167_1477458077272883_7570666380933207059_n-197x300.jpg 197w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/613637167_1477458077272883_7570666380933207059_n-673x1024.jpg 673w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/613637167_1477458077272883_7570666380933207059_n-768x1169.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/613637167_1477458077272883_7570666380933207059_n-1009x1536.jpg 1009w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/613637167_1477458077272883_7570666380933207059_n.jpg 1287w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Il semaforo che si trovava al centro della carreggiata \u00e8 stato prontamente spostato lungo il marciapiede in attesa del ripristino facendo in modo che la viabilit\u00e0 non fosse compromessa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-280453 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Semafoto-caduto-Cosenza.jpg\" alt=\"Maltempo Cosenza \" width=\"500\" height=\"324\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Semafoto-caduto-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Semafoto-caduto-Cosenza-300x194.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Semafoto-caduto-Cosenza-768x497.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<h3>Disagi idrici, Sorical \u00ablavori rinviati a causa del maltempo\u00bb<\/h3>\n<p>In un aggiornamento alle ore 15:00 Sorical ha comunicato che a seguito della rottura, questa mattina, della condotta dell\u2019acquedotto Abatemarco, causata da uno smottamento del terreno nel tratto in uscita dalla galleria Mula, le squadre tecniche di Sorical hanno lavorato per tutta la mattinata per individuare il punto del guasto. Poi per realizzare una pista di accesso per i mezzi meccanici e allestire il cantiere.<\/p>\n<p>Dalle verifiche effettuate, \u00e8 emerso che la <strong>condotta \u00e8 tranciata per un tratto di circa tre metri<\/strong>. Le operazioni di riparazione non potranno partire finch\u00e9 le condizioni meteo non miglioreranno. Al momento, vento forte, neve e grandine stanno impedendo l&#8217;accesso in sicurezza al sito. Gi\u00e0 nelle prime ore del mattino si \u00e8 <strong>registrata una notevole riduzione della portata in arrivo dall&#8217;Abatemarco<\/strong>. La rottura, di entit\u00e0 significativa (<strong>stimata in almeno 300 litri al secondo<\/strong>), \u00e8 stata <strong>confermata<\/strong>, ma le difficili condizioni meteorologiche, con pioggia intensa, hanno rallentato le operazioni.<\/p>\n<p>Attualmente, i <strong>serbatoi dei 26 Comuni<\/strong> serviti dall\u2019acquedotto Abatemarco risultano disalimentati, ad eccezione di quelli riforniti dall\u2019acquedotto Capodacqua. Seguiranno ulteriori aggiornamenti non appena l\u2019evoluzione delle condizioni meteo consentir\u00e0 la ripresa delle operazioni di riparazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I cittadini restano senza acqua e fanno i conti con i disagi del maltempo. Alcuni alberi hanno dannegiato le auto parcheggiate in strada ed un semaforo. \u00e8 crollato all&#8217;incrocio tra Viale Cosmai e Via Dalla chiesa <\/p>\n","protected":false},"author":90,"featured_media":280446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-280445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/280445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=280445"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/280445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/280446"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=280445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=280445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=280445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}