{"id":28050,"date":"2013-11-30T08:44:21","date_gmt":"2013-11-30T07:44:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28050"},"modified":"2023-01-17T13:25:27","modified_gmt":"2023-01-17T12:25:27","slug":"11691-sequestrate-sei-tonnellate-di-botti-illegali-a-cerzeto-e-torano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11691-sequestrate-sei-tonnellate-di-botti-illegali-a-cerzeto-e-torano\/","title":{"rendered":"Sequestrate sei tonnellate di botti illegali a Cerzeto e Torano"},"content":{"rendered":"<p>CERZETO (CS) &#8211; Sei tonnellate di botti illegali sono state sequestrate dalla Guardia di finanza nel cosentino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I fuochi pirotecnici del tipo &#8220;panzer&#8221;, &#8220;E io pago&#8221;, &#8220;Star Wars&#8221; e &#8220;Zeus&#8221;, per 790 mila pezzi e 950 mila bocche di fuoco, erano stipati in tre depositi di Cerzeto e Torano Castello, in provincia di Cosenza. Il valore commerciale \u00e8 di oltre 200 mila euro. Le fiamme gialle, dopo alcuni giorni di pedinamenti ed appostamenti, hanno individuato i locali, nella disponibilit\u00e0 di tre persone del luogo, che sono state denunciate. Due di loro non sono stati in grado di esibire alcuna documentazione che giustificasse il possesso del materiale, mentre il terzo, titolare della licenza prefettizia, ne deteneva un quantitativo molto superiore a quello autorizzato. Uno dei tre depositi scoperti dalle fiamme gialle, \u00e8 risultato particolarmente pericoloso in quanto si trova a ridosso di un supermercato molto frequentato. Il sequestro \u00e8 al momento il pi\u00f9 consistente del genere effettuato in Italia nel 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CERZETO (CS) &#8211; Sei tonnellate di botti illegali sono state sequestrate dalla Guardia di finanza nel cosentino.<\/p>\n","protected":false},"author":19,"featured_media":28051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-28050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28050"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28051"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}