{"id":28157,"date":"2013-12-03T09:11:53","date_gmt":"2013-12-03T08:11:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28157"},"modified":"2023-01-17T13:25:33","modified_gmt":"2023-01-17T12:25:33","slug":"11746-crotone-la-minaccia-degli-scafisti-di-gettare-una-bimba-in-mare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11746-crotone-la-minaccia-degli-scafisti-di-gettare-una-bimba-in-mare\/","title":{"rendered":"Crotone, la minaccia degli scafisti di gettare una bimba in mare"},"content":{"rendered":"<p>CROTONE &#8211; Sono tre, le persone fermato oggi dalla Polizia.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sono accusate di essere gli scafisti dell&#8217;imbarcazione con a bordo 142 migranti rimasti alla deriva per oltre 36 ore al largo di Crotone a causa del mare molto mosso. Gli scafisti erano giunti ieri nel porto di Crotone con una motovedetta della Guardia costiera che aveva effettuato l&#8217;intervento di soccorso. Tra i particolari riferiti dagli investigatori anche la minaccia da parte dei tre scafisti di gettare una bambina di tre anni, in acqua solo perch\u00e9 vomitava a causa delle condizioni del mare molto mosso. La piccola, \u00e8 stata portata nel centro di prima accoglienza di Isola Capo Rizzuto, insieme al padre. Gli scafisti sono anche accusati di avere sottoposto i migranti a maltrattamenti e violenze fisiche, costringendoli, tra l&#8217;altro, a togliere a turno l&#8217;acqua che aveva invaso il barcone a causa del mare mosso. I tre, sono stati bloccati nel centro di prima accoglienza di Isola Capo Rizzuto, dove erano stati portati insieme ai migranti dopo lo sbarco a Crotone. Dei tre fermati, uno era il motorista dell&#8217;imbarcazione, mentre gli altri due tenevano sotto controllo gli immigrati. La Squadra mobile di Crotone prosegue l&#8217;attivit\u00e0 investigativa per individuare altri scafisti, alcuni dei quali si potrebbero nascondere nell&#8217;altro gruppo di immigrati che erano sulla barca alla deriva e che \u00e8 stato portato ieri sera a Roccella Jonica (Rc).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Sono tre, le persone fermato oggi dalla Polizia.<\/p>\n","protected":false},"author":19,"featured_media":28158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28157"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28158"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}