{"id":281581,"date":"2026-01-21T19:38:45","date_gmt":"2026-01-21T18:38:45","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=281581"},"modified":"2026-01-21T19:38:45","modified_gmt":"2026-01-21T18:38:45","slug":"maltempo-calabria-circolazione-ferroviaria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/maltempo-calabria-circolazione-ferroviaria\/","title":{"rendered":"Ondata di maltempo in Calabria, circolazione ferroviaria in ripresa nella regione"},"content":{"rendered":"<p>COSENZA &#8211; Circolazione ferroviaria in ripresa in Calabria dopo l&#8217;eccezionale ondata di <a href=\"https:\/\/quicosenza.it\/news\/acqua-cosenza-maltempo-acquedotti-sorical\/\" target=\"_blank\" rel=\"noopener\">maltempo <\/a>causato dal <a href=\"https:\/\/quicosenza.it\/news\/ciclone-harry-calabria-treni-statale-108-bis\/\" target=\"_blank\" rel=\"noopener\">ciclone Harry.<\/a> &#8220;Domani &#8211; si legge in una nota di Fs &#8211; riapriranno gradualmente le linee Lamezia Terme Centrale-Catanzaro Lido e via Tropea, mentre resta chiusa la Ionica, da Melito a Crotone, per consentire ai tecnici di Rfi gli interventi di ripristino dell&#8217;infrastruttura dai danni causati dal maltempo&#8221;.<\/p>\n<p>Intano la <strong>Regione Calabria<\/strong> avvia la conta dei danni ingenti procedendo alla richiesta al Governo dello <a href=\"https:\/\/quicosenza.it\/news\/ciclone-harry-occhiuto-emergenza-nazionale\/\" target=\"_blank\" rel=\"noopener\">stato di emergenza nazionale.<\/a><\/p>\n<h3>Maltempo in Calabria, l\u2019allerta scende ad arancione<\/h3>\n<p>Intanto la <a href=\"https:\/\/www.protezionecivilecalabria.it\/\" target=\"_blank\" rel=\"noopener\">Protezione civile regionale<\/a> ha diramato un bollettino meteo che vede le condizioni in miglioramento. L\u2019allerta sulle zone ioniche del Catanzarese e su quelle ioniche e tirreniche del Reggino<strong>\u00a0\u00e8 scesa, per la giornata di oggi, ad arancione<\/strong>. La situazione meteorologica appare in miglioramento e per domani, \u00e8 previsto un ulteriore declassamento con\u00a0<strong>allerta gialla<\/strong>\u00a0su tutta la Calabria.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circolazione ferroviaria in ripresa in Calabria dopo l&#8217;eccezionale ondata di maltempo causato dal ciclone Harry<\/p>\n","protected":false},"author":58,"featured_media":281582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-281581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/281581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=281581"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/281581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/281582"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=281581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=281581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=281581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}