{"id":28193,"date":"2013-12-04T14:10:19","date_gmt":"2013-12-04T13:10:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28193"},"modified":"2023-01-17T13:25:35","modified_gmt":"2023-01-17T12:25:35","slug":"11764-aeroporto-crotone-per-le-feste-natalizie-nuovi-voli-per-roma-e-milano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11764-aeroporto-crotone-per-le-feste-natalizie-nuovi-voli-per-roma-e-milano\/","title":{"rendered":"Aeroporto Crotone, per le feste natalizie nuovi voli per Roma e Milano"},"content":{"rendered":"<p>CROTONE &#8211; Alitalia ha istituito nuovi da e per l&#8217;aeroporto Sant&#8217;Anna di Crotone nel periodo natalizio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;obiettivo \u00e8 di soddisfare la forte richiesta di collegamenti aerei su questo territorio in un periodo particolare dell&#8217;anno. &#8220;I collegamenti Crotone &#8211; Roma Fiumicino &#8211; spiega un comunicato della compagnia di bandiera &#8211; saranno attivi dal 20 dicembre al 7 gennaio 2014, per 3 giorni alla settimana, il marted\u00ec, il venerd\u00ec e la domenica. Dal 22 dicembre, fino al 5 gennaio 2014, saranno attivi anche i collegamenti Crotone &#8211; Milano Linate che avranno frequenza bisettimanale e verranno effettuati nei giorni di Giovedi&#8217; e Domenica. Su tutti i voli per Roma e per Milano &#8211; si legge infine &#8211; Alitalia utilizzera&#8217; moderni aerei Embraer E-175 da 88 posti&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Alitalia ha istituito nuovi da e per l&#8217;aeroporto Sant&#8217;Anna di Crotone nel periodo natalizio.<\/p>\n","protected":false},"author":22,"featured_media":28194,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28193"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28194"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}